{"id":121493,"date":"2016-11-22T08:09:00","date_gmt":"2016-11-22T12:09:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/politica\/vida\/20161122\/mas-funciones-para-casi-casi-primera-dama\/"},"modified":"2025-07-18T09:06:54","modified_gmt":"2025-07-18T09:06:54","slug":"mas-funciones-para-casi-casi-primera-dama","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20161122\/mas-funciones-para-casi-casi-primera-dama\/","title":{"rendered":"M\u00e1s funciones para &#8216;Casi casi Primera Dama&#8217;"},"content":{"rendered":"<p>A d\u00edas de anunciar la venta de boletos para el primer espect\u00e1culo &#8216;stand-up&#8217; de Alexandra Fuentes, &#8216;La Casi Casi Primera Dama&#8217;, las entradas de las cinco funciones se agotaron. Por ello, Molusco Inc. inform\u00f3 que el evento se mueve al Centro de Bellas Artes de Caguas para abrir dos nuevas funciones: el s\u00e1bado 28 de enero a las 8:30 p.m. y el domingo, 29 de enero a las 6:00 p.m.<\/p>\n<p>&#8216;Estoy bien agradecida del cari\u00f1o del p\u00fablico y feliz de que los boletos se acabaron tan r\u00e1pido. Este show ser\u00e1 para que se r\u00edan de principio a fin&#8217;, asegur\u00f3 Fuentes.<\/p>\n<p>El libreto y la direcci\u00f3n de &#8216;La Casi Casi Primera Dama&#8217; estar\u00e1n a cargo de Carlos Vega, y recoge las historias y an\u00e9cdotas que experiment\u00f3 Alexandra mientras estuvo involucrada en la pasada campa\u00f1a electoral. Adem\u00e1s, se combinar\u00e1 el estilo &#8216;stand-up comedy&#8217; con otros elementos de apoyo como videos en pantallas, m\u00fasica y la participaci\u00f3n de invitados especiales.<\/p>\n<p>Para m\u00e1s informaci\u00f3n y boletos debe comunicarse a Ticket Center al (787) 792-5000 o acceder a la p\u00e1gina www.tcpr.com.<\/p>","protected":false},"excerpt":{"rendered":"<p>A d\u00edas de anunciar la venta de boletos para el primer espect\u00e1culo &#8216;stand-up&#8217; de Alexandra Fuentes, &#8216;La Casi Casi Primera Dama&#8217;, las entradas de las cinco funciones se agotaron. Por ello, Molusco Inc. inform\u00f3 que el evento se mueve al Centro de Bellas Artes de Caguas para abrir dos nuevas funciones: el s\u00e1bado 28 de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":504333,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[7,2,69],"tags":[],"class_list":["post-121493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-ultima-hora","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/121493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=121493"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/121493\/revisions"}],"predecessor-version":[{"id":504339,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/121493\/revisions\/504339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/504333"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=121493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=121493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=121493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}