{"id":121217,"date":"2012-07-12T06:38:00","date_gmt":"2012-07-12T10:38:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20120712\/hacienda-adelanta-cheques-para-el-wiken-sin-ivu\/"},"modified":"2025-08-26T05:11:53","modified_gmt":"2025-08-26T05:11:53","slug":"hacienda-adelanta-cheques-para-el-wiken-sin-ivu","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20120712\/hacienda-adelanta-cheques-para-el-wiken-sin-ivu\/","title":{"rendered":"Hacienda adelanta cheques para el wik\u00e9n sin IVU"},"content":{"rendered":"<p>El Secretario del Departamento de Hacienda, Jes\u00fas M\u00e9ndez Rodr\u00edguez, anunci\u00f3 que el pago de la n\u00f3mina de los empleados p\u00fablicos del Gobierno de Puerto Rico que cobran por cheque impreso se adelantar\u00e1 para hoy jueves.<\/p>\n<p>De esta manera tendr\u00e1n disponible su paga al mismo tiempo que los empleados que cobran mediante dep\u00f3sito directo. Esta determinaci\u00f3n se hizo para que puedan aprovechar el &#8216;Per\u00edodo Libre del Impuesto sobre Ventas por Regreso a la Escuela&#8217;, que comenzar\u00e1 a las 12:01 de la ma\u00f1ana del viernes, 13 de julio de 2012 y concluir\u00e1 a las 12:00 de la medianoche del domingo 15 de julio de 2012.<\/p>\n<p>Entre los art\u00edculos que cubre el Per\u00edodo Libre del Impuesto sobre Ventas por Regreso a la Escuela est\u00e1n: ropa (hasta $75 por art\u00edculo), computadoras (hasta $750 por art\u00edculo), programas para computadoras (hasta $200 por art\u00edculo), art\u00edculos escolares (hasta $50 por art\u00edculo) y libros de texto universitarios y escolares (hasta $200 por art\u00edculo).<\/p>\n<p>M\u00e9ndez concluy\u00f3 indicando que &#8216;el consumidor todos los a\u00f1os anticipa este periodo libre de IVU (Impuesto de Ventas y Uso) para hacer sus compras de regreso a la escuela, as\u00ed que esperamos beneficiarlo al brindarle ahorros, a la vez que generamos actividad econ\u00f3mica, ya que cientos de comercios experimentan un aumento en sus ventas durante este per\u00edodo de compras de regreso a la escuela sin IVU.<\/p>\n<p>Vea tambi\u00e9n:<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/noticia\/126547\/miles-de-contribuyentes-siguen-sin-recibir-su-anhelado-reintegro.html\/\" target=\"_blank\">Miles de contribuyentes siguen sin recibir su anhelado reintegro<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El Secretario del Departamento de Hacienda, Jes\u00fas M\u00e9ndez Rodr\u00edguez, anunci\u00f3 que el pago de la n\u00f3mina de los empleados p\u00fablicos del Gobierno de Puerto Rico que cobran por cheque impreso se adelantar\u00e1 para hoy jueves. De esta manera tendr\u00e1n disponible su paga al mismo tiempo que los empleados que cobran mediante dep\u00f3sito directo. Esta determinaci\u00f3n [&hellip;]<\/p>","protected":false},"author":0,"featured_media":913548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-121217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/121217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=121217"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/121217\/revisions"}],"predecessor-version":[{"id":913572,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/121217\/revisions\/913572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/913548"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=121217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=121217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=121217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}