{"id":120074,"date":"2013-05-08T06:13:11","date_gmt":"2013-05-08T10:13:11","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20130508\/aemead-pide-precaucion-por-lluvias\/"},"modified":"2025-08-23T07:32:16","modified_gmt":"2025-08-23T07:32:16","slug":"aemead-pide-precaucion-por-lluvias","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20130508\/aemead-pide-precaucion-por-lluvias\/","title":{"rendered":"AEMEAD pide precauci\u00f3n por lluvias"},"content":{"rendered":"<p>El director ejecutivo de la Agencia Estatal para el Manejo de Emergencias y Administraci\u00f3n de Desastres (AEMEAD), Miguel A. R\u00edos Torres hizo un llamado a la ciudadan\u00eda a tener mucha precauci\u00f3n en las \u00e1reas que est\u00e1n inundadas debido a las fuertes lluvias que han ocurrido en las \u00faltimas horas.<\/p>\n<p>El funcionario indic\u00f3 que, basado en los informes del Servicio Nacional de Meteorolog\u00eda (SNM), el mi\u00e9rcoles puede haber un panorama similar de fuertes aguaceros en el \u00e1rea norte, interior y oeste, como los ocurridos en el municipio de San Sebasti\u00e1n.<\/p>\n<p>R\u00edos destac\u00f3 que estos aguaceros pueden dejar inundaciones urbanas las cuales en algunos sitios pueden provocar accidentes, si no se tiene la precauci\u00f3n adecuada.<\/p>\n<p>&#8216;Le pedimos a la ciudadan\u00eda que recuerde que no se debe de cruzar \u00e1reas inundadas en autom\u00f3viles, ni tratar de cruzar r\u00edos crecidos porque estas corrientes son muy fuertes y pueden arrastrar cualquier veh\u00edculo o cualquier persona y producir desgracias&#8217;, se\u00f1al\u00f3 R\u00edos Torres.<\/p>\n<p>Seg\u00fan el SNM, una alta presi\u00f3n en la superficie se desarrollar\u00e1 a trav\u00e9s del norte del \u00e1rea el mi\u00e9rcoles y aire un poco m\u00e1s seco se mover\u00e1 sobre las islas. Sin embargo, la humedad persistente combinada con el calor diurno y los efectos locales contribuir\u00e1n al desarrollo de aguaceros y tronadas aisladas durante las tardes hasta el fin de semana.<\/p>","protected":false},"excerpt":{"rendered":"<p>El director ejecutivo de la Agencia Estatal para el Manejo de Emergencias y Administraci\u00f3n de Desastres (AEMEAD), Miguel A. R\u00edos Torres hizo un llamado a la ciudadan\u00eda a tener mucha precauci\u00f3n en las \u00e1reas que est\u00e1n inundadas debido a las fuertes lluvias que han ocurrido en las \u00faltimas horas. El funcionario indic\u00f3 que, basado en [&hellip;]<\/p>","protected":false},"author":0,"featured_media":895639,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-120074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/120074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=120074"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/120074\/revisions"}],"predecessor-version":[{"id":895661,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/120074\/revisions\/895661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/895639"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=120074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=120074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=120074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}