{"id":119895,"date":"2014-03-24T18:32:05","date_gmt":"2014-03-24T22:32:05","guid":{"rendered":"http:\/\/www.noticel.com\/cuidate\/ahora\/20140324\/mas-del-8-de-los-medicos-abandonaron-la-isla-en-los-ultimos-3-anos\/"},"modified":"2025-08-20T04:30:54","modified_gmt":"2025-08-20T04:30:54","slug":"mas-del-8-de-los-medicos-abandonaron-la-isla-en-los-ultimos-3-anos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20140324\/mas-del-8-de-los-medicos-abandonaron-la-isla-en-los-ultimos-3-anos\/","title":{"rendered":"M\u00e1s del 8% de los m\u00e9dicos abandonaron la Isla en los \u00faltimos 3 a\u00f1os"},"content":{"rendered":"<p>M\u00e1s del 8% de los 12,000 medicos de Puerto Rico han abandonado la isla caribe\u00f1a en los \u00faltimos tres a\u00f1os y emigrado a EE.UU. en busca de mejores salarios, m\u00e1s calidad de vida y menos denuncias por negligencia.<\/p>\n<p>El vicepresidente de la Junta de Licenciamiento y Disciplina Medica de Puerto Rico (JLDMPR) y posible pr\u00f3ximo presidente del Colegio de Medicos, V\u00edctor Ramos, detall\u00f3 a Efe que la gran mayor\u00eda de los cerca de mil medicos que han emigrado en este \u00faltimo trienio son especialistas.<\/p>\n<p>&#8216;Especialidades como Obstetricia y Anestesiolog\u00eda son algunas en las que m\u00e1s se ha notado la salida y en ciertas \u00e1reas hay una evidente escasez&#8217;, a\u00f1adi\u00f3 el responsable del organismo encargado, entre otras funciones, del registro de medicos y concesi\u00f3n de licencias en Puerto Rico.<\/p>\n<p>As\u00ed, de los cuatrocientos cardi\u00f3logos que ejerc\u00edan en la isla hace tres a\u00f1os hoy queda un centenar, mientras que en la actualidad \u00fanicamente se puede encontrar a una veintena de neurocirujanos en activo.<\/p>\n<p>A su juicio, las razones de este exodo, que -como dijo- supone una amenaza para el mantenimiento en Puerto Rico de una adecuada atenci\u00f3n en todas las especialidades, ese deben buscar, b\u00e1sicamente, en los bajos salarios comparados con los de EE.UU.<\/p>\n<p>Ramos apunt\u00f3 que la criminalidad que golpea a Puerto Rico y que cada semana deja como saldo cerca de diez muertes, la mayor\u00eda en ajustes de cuentas por narcotr\u00e1fico, y un deterioro generalizado en la calidad de vida contribuyen tambien a que cada vez m\u00e1s medicos opten por hacer las maletas.<\/p>\n<p>Otro factor que propicia este exodo de doctores es el incremento de denuncias por impericia medica, en gran parte debido, seg\u00fan dijo, a la proliferaci\u00f3n de abogados especializados en la materia.<\/p><div class=\"notic-content-middle\" id=\"notic-2287749294\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.facebook.com\/magnapremiumlager\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"106-2026-21_Magna Verano Display v.02\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30090709\/106-2026-21_Magna-Verano-Display-v.02_300x600-2.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30090709\/106-2026-21_Magna-Verano-Display-v.02_300x600-2.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30090709\/106-2026-21_Magna-Verano-Display-v.02_300x600-2-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/07\/30090709\/106-2026-21_Magna-Verano-Display-v.02_300x600-2-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;De hecho ahora hay muchas pr\u00e1cticas de riesgo que directamente han dejado de llevarse a cabo por miedo a las demandas y que s\u00f3lo se hacen ya en el Centro Medico&#8217;, el gran hospital p\u00fablico de Puerto Rico, dijo Ramos.<\/p>\n<p>La raz\u00f3n, explic\u00f3, es que en ese centro hospitalario existen l\u00edmites legales a las cuant\u00edas de las indemnizaciones.<\/p>\n<p>El hasta ahora presidente del Colegio de Medicos Cirujanos de Puerto Rico, Eduardo Ibarra (que se disputa estos d\u00edas con Ramos la presidencia de esa organizaci\u00f3n), coincide con su colega en que los salarios y la inseguridad son factores clave en el exodo de profesionales.<\/p>\n<p>En entrevista con Efe a\u00f1adi\u00f3 que hay medicos que s\u00f3lo ingresan cinco d\u00f3lares por cada paciente atendido de Medicaid, el programa federal de seguros de salud a personas con bajos ingresos, mientras que algunas aseguradoras se demoran en pagar hasta noventa d\u00edas, lo que dificulta la supervivencia de las consultas.<\/p>\n<p>A su juicio, otro de los problemas es el elevad\u00edsimo precio de la luz, &#8216;insoportable&#8217; para algunas especialidades. &#8216;Yo mismo tuve que cerrar un centro de radiolog\u00eda por facturas mensuales que llegaban a los 15,000 d\u00f3lares&#8217;, record\u00f3 Ibarra.<\/p>\n<p>Este conjunto de factores es la causa de que en algunas especialidades ni siquiera haya medio centenar de profesionales, una cifra &#8216;a todas las luces insuficiente&#8217; para una poblaci\u00f3n de 3.7 millones de habitantes, seg\u00fan Ibarra.<\/p>","protected":false},"excerpt":{"rendered":"<p>M\u00e1s del 8% de los 12,000 medicos de Puerto Rico han abandonado la isla caribe\u00f1a en los \u00faltimos tres a\u00f1os y emigrado a EE.UU. en busca de mejores salarios, m\u00e1s calidad de vida y menos denuncias por negligencia. El vicepresidente de la Junta de Licenciamiento y Disciplina Medica de Puerto Rico (JLDMPR) y posible pr\u00f3ximo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":879158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-119895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/119895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=119895"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/119895\/revisions"}],"predecessor-version":[{"id":879165,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/119895\/revisions\/879165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/879158"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=119895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=119895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=119895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}