{"id":119181,"date":"2015-06-01T09:59:43","date_gmt":"2015-06-01T13:59:43","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20150601\/avanzan-planes-para-dragado-de-orilla-en-carraizo\/"},"modified":"2025-08-16T10:33:33","modified_gmt":"2025-08-16T10:33:33","slug":"avanzan-planes-para-dragado-de-orilla-en-carraizo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20150601\/avanzan-planes-para-dragado-de-orilla-en-carraizo\/","title":{"rendered":"Avanzan planes para dragado de orilla en Carra\u00edzo"},"content":{"rendered":"<p>El presidente de Autoridad de Acueductos y Alcantarillados (AAA), Alberto L\u00e1zaro confirm\u00f3 el lunes que est\u00e1n adelantados los procedimientos para iniciar las labores del dragado de orilla en el embalse Carra\u00edzo.<\/p>\n<p>&#8216;Se radic\u00f3 en la Junta de Calidad Ambiental y en el Cuerpo de Ingenieros la solicitud de permisos. Esperamos esta semana visitar el lugar con posibles contratistas&#8217;, dijo L\u00e1zaro en NotiUno.<\/p>\n<p>Detall\u00f3 que el permiso que otorg\u00f3 el Cuerpo de Ingenieros en 1996 para dragar el cuerpo de agua, a\u00fan est\u00e1 vigente. &#8216;Estamos solicit\u00e1ndole que nos permitan hacer esta actividad, que aunque un poquito diferente en la parte operacional, para fines pr\u00e1cticos, es pr\u00e1cticamente lo mismo y estamos solicitando que nos extiendan el mismo permiso&#8217;, se\u00f1al\u00f3 L\u00e1zaro quien dijo esperan tener contestaci\u00f3n esta misma semana.<\/p><div class=\"notic-content-middle\" id=\"notic-1084372426\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Mientras tanto, el presidente de la AAA, dijo que a pesar de las lluvias del fin de semana, el embalse Carra\u00edzo descendi\u00f3 13 cent\u00edmetros.<\/p>\n<p>&#8216;Esperamos evaluar esta semana cu\u00e1l es el pron\u00f3stico del tiempo a corto y mediano plazo para tomar una determinaci\u00f3n si hay que extender el racionamiento a dos d\u00edas para los clientes que se sirven del Lago Carra\u00edzo&#8217;, advirti\u00f3 el funcionario.<\/p>\n<p>De otra parte, indic\u00f3 que en el Lago La Plata, este fin de semana aument\u00f3 30 cent\u00edmetros. &#8216;Es bueno. Nos da un poco m\u00e1s de vida para tener que declarar un racionamiento para los clientes. Quiz\u00e1s una semana m\u00e1s&#8217;, indic\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>El presidente de Autoridad de Acueductos y Alcantarillados (AAA), Alberto L\u00e1zaro confirm\u00f3 el lunes que est\u00e1n adelantados los procedimientos para iniciar las labores del dragado de orilla en el embalse Carra\u00edzo. &#8216;Se radic\u00f3 en la Junta de Calidad Ambiental y en el Cuerpo de Ingenieros la solicitud de permisos. Esperamos esta semana visitar el lugar [&hellip;]<\/p>","protected":false},"author":0,"featured_media":849757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-119181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/119181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=119181"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/119181\/revisions"}],"predecessor-version":[{"id":849784,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/119181\/revisions\/849784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/849757"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=119181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=119181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=119181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}