{"id":118733,"date":"2015-09-08T10:08:00","date_gmt":"2015-09-08T14:08:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20150908\/plan-de-ajuste-fiscal-se-entregara-esta-tarde\/"},"modified":"2025-07-28T23:58:38","modified_gmt":"2025-07-28T23:58:38","slug":"plan-de-ajuste-fiscal-se-entregara-esta-tarde","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20150908\/plan-de-ajuste-fiscal-se-entregara-esta-tarde\/","title":{"rendered":"Plan de Ajuste Fiscal se entregar\u00e1 esta tarde"},"content":{"rendered":"<p>El secretario de la Gobernaci\u00f3n, V\u00edctor Su\u00e1rez Melendez, afirm\u00f3 que esta tarde ser\u00e1 entregado el Plan de Ajuste Fiscal a cinco a\u00f1os, luego de que el gobernador Alejandro Garc\u00eda Padilla le otorgara una pr\u00f3rroga al Grupo de Trabajo para la Recuperaci\u00f3n Fiscal y Econ\u00f3mica de Puerto Rico.<\/p>\n<p>Sin embargo, Su\u00e1rez Mel\u00e9ndez, quien es miembro del Grupo, manifest\u00f3 que &#8216;el Gobernador ha instruido al Grupo de Trabajo que desarroll\u00f3 el plan a hacer p\u00fablico el mismo ma\u00f1ana, mi\u00e9rcoles 9 de septiembre de 2015. Este plan es un elemento indispensable para encaminar el crecimiento econ\u00f3mico de Puerto Rico, enfrentar los retos fiscales y recuperar el bienestar social de los puertorrique\u00f1os&#8217;.<\/p>\n<p>Informaci\u00f3n que ha sido filtrada a la prensa en los pasados d\u00edas apuntan a que el plan tiene sobre la mirilla la reestructuraci\u00f3n de algunas agencias, el cierre de escuelas, la eliminaci\u00f3n de los bonos, restricci\u00f3n en el pago de horas extra, reducci\u00f3n del periodo de vacaciones, aumento en el periodo probatorio para nuevos empleados, y crear cierta flexibilidad sobre el salario m\u00ednimo federal, entre otros.<\/p><div class=\"notic-content-middle\" id=\"notic-804925919\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Algunos sindicatos ya se han expresado en contra de las propuestas a la reforma laboral y los alegados planes para privatizar y desmantelar el Departamento de Educaci\u00f3n, la Universidad de Puerto Rico, la Autoridad de Energ\u00eda El\u00e9ctrica, la Autoridad de Acueductos y Alcantarillados, la Autoridad Metropolitana de Autobuses, la Autoridad de Carreteras y Transportaci\u00f3n y el Fondo del Seguro del Estado. Estos han convocado a una manifestaci\u00f3n para el pr\u00f3ximo viernes, 11 de septiembre, a las 4:30 p.m. frente al Capitolio.<\/p>\n<p>Adem\u00e1s, los sindicatos convocaron &#8216;a una asamblea nacional de pueblo durante el mes de octubre en la cual recomendaremos la aprobaci\u00f3n de un Paro Nacional y otras acciones de movilizaci\u00f3n que sean efectivas para denunciar y detener las propuestas de ajuste que el gobierno quiere imponer, en particular la Junta de Control Fiscal&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>El secretario de la Gobernaci\u00f3n, V\u00edctor Su\u00e1rez Melendez, afirm\u00f3 que esta tarde ser\u00e1 entregado el Plan de Ajuste Fiscal a cinco a\u00f1os, luego de que el gobernador Alejandro Garc\u00eda Padilla le otorgara una pr\u00f3rroga al Grupo de Trabajo para la Recuperaci\u00f3n Fiscal y Econ\u00f3mica de Puerto Rico. Sin embargo, Su\u00e1rez Mel\u00e9ndez, quien es miembro del [&hellip;]<\/p>","protected":false},"author":0,"featured_media":604090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-118733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/118733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=118733"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/118733\/revisions"}],"predecessor-version":[{"id":604114,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/118733\/revisions\/604114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/604090"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=118733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=118733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=118733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}