{"id":117945,"date":"2013-11-09T09:38:03","date_gmt":"2013-11-09T13:38:03","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20131109\/presa-con-fianza-de-1-6-millones-la-nieta-del-profesor-asesinado\/"},"modified":"2025-07-18T10:15:59","modified_gmt":"2025-07-18T10:15:59","slug":"presa-con-fianza-de-1-6-millones-la-nieta-del-profesor-asesinado","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20131109\/presa-con-fianza-de-1-6-millones-la-nieta-del-profesor-asesinado\/","title":{"rendered":"Presa con fianza de $1.6 millones la nieta del profesor asesinado"},"content":{"rendered":"<p>En horas de la noche del viernes en el Tribunal de Mayag\u00fcez se les radicaron cargos a Brenda Moy\u00e1 Barbosa y Alex Matos Jusino por los delitos de asesinato, secuestro, robo, destrucci\u00f3n de evidencia, tentativa de retirar dinero de ATH y ley de armas en el caso de la muerte del excatedr\u00e1tico Jaime Moy\u00e1 Quintana esta semana.<\/p>\n<p>La juez Jeisa Villarrubio encontr\u00f3 causa en todos los cargos imponi\u00e9ndole una fianza global a cada uno de $1,600,000.<\/p>\n<p>Moy\u00e1 Barbosa fue ingresada en la c\u00e1rcel para mujeres en Vega Alta y Matos Jusino en las Cucharas en Ponce al no poder prestar dicha fianza.<\/p>\n<p>Moy\u00e1 Barbosa tiene 29 a\u00f1os, mientras que Matos Jusino tiene 28 a\u00f1os y es vecino del residencial p\u00fablico Columbus Landing en Mayag\u00fcez.<\/p>\n<p>Moy\u00e1 Barbosa tiene un caso previo por obstrucci\u00f3n a la justicia &#8216;de hace a\u00f1os&#8217;, seg\u00fan inform\u00f3 la Polic\u00eda a este diario digital el viernes.<\/p><div class=\"notic-content-middle\" id=\"notic-2238249370\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>A preguntas de este medio sobre c\u00f3mo pudiera estar involucrada la nieta de la v\u00edctima en el asesinato, la directora del CIC subray\u00f3 el viernes que no pod\u00eda entrar en detalles. &#8216;Es parte del proceso investigativo&#8217;, acot\u00f3.<\/p>\n<p>De igual manera, a tempranas horas de la ma\u00f1ana del viernes, las autoridades confirmaron que estaban en la b\u00fasqueda de una tercera persona de inter\u00e9s en el caso, pero todav\u00eda no han dado con su paradero.<\/p>\n<p>Moy\u00e1 Quintana, de 88 a\u00f1os, fue amordazado y apu\u00f1alado en lo que se presume fue un secuestro con la intenci\u00f3n de robarle.<\/p>\n<p><em>Pendientes a NotiCel para la ampliaci\u00f3n de esta noticia.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>En horas de la noche del viernes en el Tribunal de Mayag\u00fcez se les radicaron cargos a Brenda Moy\u00e1 Barbosa y Alex Matos Jusino por los delitos de asesinato, secuestro, robo, destrucci\u00f3n de evidencia, tentativa de retirar dinero de ATH y ley de armas en el caso de la muerte del excatedr\u00e1tico Jaime Moy\u00e1 Quintana [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-117945","post","type-post","status-publish","format-standard","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=117945"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117945\/revisions"}],"predecessor-version":[{"id":515714,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117945\/revisions\/515714"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=117945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=117945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=117945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}