{"id":117801,"date":"2015-04-07T06:23:40","date_gmt":"2015-04-07T10:23:40","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20150407\/menor-con-trauma-craneal-tras-accidente-con-motora\/"},"modified":"2025-08-18T04:10:27","modified_gmt":"2025-08-18T04:10:27","slug":"menor-con-trauma-craneal-tras-accidente-con-motora","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20150407\/menor-con-trauma-craneal-tras-accidente-con-motora\/","title":{"rendered":"Menor con trauma craneal tras accidente con motora"},"content":{"rendered":"<p>La Polic\u00eda inform\u00f3 que un choque de car\u00e1cter grave se registr\u00f3 a eso de las 9:45 de la noche del lunes en la carretera PR-5 en direcci\u00f3n de Cata\u00f1o hacia Bayam\u00f3n, en la entrada de Puente Blanco, en el que resultaron heridos dos menores de 15 a\u00f1os.<\/p>\n<p>Seg\u00fan la investigaci\u00f3n preliminar, el conductor de una motora todo terreno y su pasajero, ambos de 15 a\u00f1os, impactaron de frente a la conductora de un veh\u00edculo Mitsubshi Mirage que se dirig\u00eda de Cata\u00f1o a Bayam\u00f3n cuando hac\u00eda un viraje a la izquierda hacia Puente Blanco. \u00c9sta fue identificada como Mar\u00eda Mel\u00e9ndez Mendoza.<\/p>\n<p>Las autoridades indicaron que el conductor de la motora result\u00f3 con trauma craneal y fue llevado hasta el Centro M\u00e9dico de R\u00edo Piedras, mientras que el pasajero, result\u00f3 con heridas leves. Ambos menores viajaban en la motora en violaci\u00f3n a la Ley 22 y desprovistos de todo equipo protector que resguardara su seguridad y sin supervisi\u00f3n de un adulto. \u00c9stos no fueron identificados.<\/p>\n<p>La Polic\u00eda detall\u00f3 que Mel\u00e9ndez Mendoza, quien pose\u00eda su documentaci\u00f3n vigente, result\u00f3 ilesa.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda inform\u00f3 que un choque de car\u00e1cter grave se registr\u00f3 a eso de las 9:45 de la noche del lunes en la carretera PR-5 en direcci\u00f3n de Cata\u00f1o hacia Bayam\u00f3n, en la entrada de Puente Blanco, en el que resultaron heridos dos menores de 15 a\u00f1os. Seg\u00fan la investigaci\u00f3n preliminar, el conductor de una [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-117801","post","type-post","status-publish","format-standard","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=117801"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117801\/revisions"}],"predecessor-version":[{"id":865877,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117801\/revisions\/865877"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=117801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=117801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=117801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}