{"id":117257,"date":"2013-11-22T07:05:52","date_gmt":"2013-11-22T11:05:52","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20131122\/precaucion-pavimento-mojado-6\/"},"modified":"2025-07-18T09:59:47","modified_gmt":"2025-07-18T09:59:47","slug":"precaucion-pavimento-mojado-6","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20131122\/precaucion-pavimento-mojado-6\/","title":{"rendered":"Precauci\u00f3n, pavimento mojado"},"content":{"rendered":"<p>Sigue la investigaci\u00f3n del accidente leve contra objeto fijo en la carretera 861, intersecci\u00f3n la carretera 862 en Bayam\u00f3n.<\/p>\n<p>Acumulaci\u00f3n de agua en la carretera 5, frente al barrio Juana Matos en Cata\u00f1o; Carretera 2, intersecci\u00f3n en la carretera 690 en Vega Alta; carretera 676, barrio Bajura, Vega Alta; la carretera 647, barrio Senejeta en Vega Alta; carretera 620, barrio F\u00e1tima en Vega Alta.<\/p>\n<p>Pavimento mojado \u00c1rea Metropolitana, Norte, Este y tramos del centro de la Isla.<\/p>\n<p>Neblina en la zona Central de la Isla.<\/p>\n<p>Pesado en la carretera 2, carretera 165, carretera 167 en Bayam\u00f3n; Pesado en Expreso De Diego, desde Toa Baja a San Juan; Pesado en la carretera 30 entre Gurabo y Caguas; Semi pesado en Autopista Luis A Ferr\u00e9, \u00e1rea de Bairoa, Caguas Norte y Montehiedra, en direcci\u00f3n a San Juan.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sigue la investigaci\u00f3n del accidente leve contra objeto fijo en la carretera 861, intersecci\u00f3n la carretera 862 en Bayam\u00f3n. Acumulaci\u00f3n de agua en la carretera 5, frente al barrio Juana Matos en Cata\u00f1o; Carretera 2, intersecci\u00f3n en la carretera 690 en Vega Alta; carretera 676, barrio Bajura, Vega Alta; la carretera 647, barrio Senejeta en [&hellip;]<\/p>","protected":false},"author":0,"featured_media":512810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-117257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=117257"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117257\/revisions"}],"predecessor-version":[{"id":512815,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117257\/revisions\/512815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/512810"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=117257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=117257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=117257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}