{"id":117015,"date":"2015-04-03T21:33:31","date_gmt":"2015-04-04T01:33:31","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20150403\/sol-olas-arena-y-cervezas-arropan-la-semana-santa\/"},"modified":"2025-08-18T04:10:32","modified_gmt":"2025-08-18T04:10:32","slug":"sol-olas-arena-y-cervezas-arropan-la-semana-santa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20150403\/sol-olas-arena-y-cervezas-arropan-la-semana-santa\/","title":{"rendered":"Sol, olas, arena y cervezas arropan la Semana Santa"},"content":{"rendered":"<p>Ya se ha hecho costumbre que se transporte a las playas y centros recreativos del pa\u00eds la celebraci\u00f3n de Semana Santa, que festeja la muerte y la resurrecci\u00f3n de Jes\u00fas en la tradici\u00f3n cristiana.<\/p>\n<p>En la tarde del Viernes Santo, decenas de personas se congregaron en Ocean Park. Un grupo de veintea\u00f1eros jugaba en la net de volleyball, los m\u00e1s peque\u00f1os corr\u00edan o se enterraban en la arena, algunos adultos conversaban animadamente con cerveza en mano mientras otros tomaban el sol.<\/p>\n<p>La pregunta quedaba suspendida en el aire. Celebraban desde el sol y el mar los acontecimientos narrados por la Biblia con motivo de Semana Santa?<\/p>\n<p>&#8216;La s\u00faper Semana Santa. La semana que uno muere, sobrevive, lo rescatan, mueve una piedra y ya est\u00e1 en los cielos velando por nosotros&#8217;, respondi\u00f3 entre risas y burlas Raymarie Acevedo, residente de Caguas.<\/p>\n<p>Adoptando un tono m\u00e1s serio, la mujer de 26 a\u00f1os indic\u00f3 que, al momento, est\u00e1 al margen de las religiones que, seg\u00fan ella, se encargan \u00fanicamente de lavarle el cerebro a la gente, al igual que la pol\u00edtica.<\/p>\n<p>Al otro lado de la playa, los amigos Liroy y Jos\u00e9 Angel se separaron de su grupo de amistades para contestar la pregunta. Entre risas que sonaban a nervios, intentaron explicar qu\u00e9 se celebraba ese d\u00eda.<\/p><div class=\"notic-content-middle\" id=\"notic-1577112065\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;Pues\u2026 la resurrecci\u00f3n de Jes\u00fas\u2026 y la\u2026&#8217;, fueron las palabras que lograron formular, ahogadas por las risas c\u00f3mplices. No obstante, los dos residentes de San Juan, quienes afirmaron ser cristianos, se apresuraron a a\u00f1adir que Jes\u00fas dio todo por nosotros y uno debe estar agradecido por eso.<\/p>\n<p>Por su parte, Juan Calca\u00f1o, que se encontraba con su familia y amistades bajo la sombra de una palmera, coment\u00f3 que fueron a la Iglesia temprano y luego desviaron el camino hacia la playa para tomar un respiro y llevar a los dos ni\u00f1os peque\u00f1os que correteaban a su alrededor.<\/p>\n<p>Cuando a Braulio, a su lado, se le pregunt\u00f3 qu\u00e9 se celebraba en Semana Santa, dijo carecer de la informaci\u00f3n necesaria para responder, pero que cre\u00eda que involucraba algo sobre la resurrecci\u00f3n de Cristo.<\/p>\n<p>Aun as\u00ed, a\u00f1adi\u00f3 que uno, por tradici\u00f3n, celebra la Semana Santa, para tomar d\u00edas de vacaciones junto a la familia, con los amigos, en la playa, comiendo habichuelas y dulce, dijo.<\/p>\n<p>Fue Omar, vecino de Lo\u00edza, quien respondi\u00f3 con precisi\u00f3n a la pregunta. Dijo con voz firme que durante esta semana se celebraba la resurrecci\u00f3n de Dios, que ser\u00eda el domingo, y que el viernes se conmemora el d\u00eda en que muri\u00f3 en la cruz.<\/p>\n<p>&#8216;No estoy en una Iglesia ahora mismo porque no me congrego en ninguna pero soy creyente. En la ma\u00f1ana hicimos una oraci\u00f3n y trajimos nuestra comida, nuestro pescadito, y comimos aqu\u00ed en familia. As\u00ed la pasamos bien, en armon\u00eda&#8217;, concluy\u00f3 el hombre, tomando un sorbo de su cerveza.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ya se ha hecho costumbre que se transporte a las playas y centros recreativos del pa\u00eds la celebraci\u00f3n de Semana Santa, que festeja la muerte y la resurrecci\u00f3n de Jes\u00fas en la tradici\u00f3n cristiana. En la tarde del Viernes Santo, decenas de personas se congregaron en Ocean Park. Un grupo de veintea\u00f1eros jugaba en la [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-117015","post","type-post","status-publish","format-standard","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=117015"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117015\/revisions"}],"predecessor-version":[{"id":865905,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/117015\/revisions\/865905"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=117015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=117015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=117015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}