{"id":116142,"date":"2016-04-18T14:39:00","date_gmt":"2016-04-18T18:39:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/educacion\/upr\/20160418\/senador-denuncia-despilfarro-de-la-upr-para-hospedaje-durante-las-justas\/"},"modified":"2025-07-26T19:31:46","modified_gmt":"2025-07-26T19:31:46","slug":"senador-denuncia-despilfarro-de-la-upr-para-hospedaje-durante-las-justas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160418\/senador-denuncia-despilfarro-de-la-upr-para-hospedaje-durante-las-justas\/","title":{"rendered":"Senador denuncia despilfarro de la UPR para hospedaje durante las Justas"},"content":{"rendered":"<p>El senador del Partido Nuevo Progresista (PNP), \u00c1ngel &#8216;Chayanne&#8217; Mart\u00ednez Santiago, denunci\u00f3 hoy, lunes, que la Universidad de Puerto Rico (UPR) pag\u00f3 para que un selecto grupo de sus empleados se hospedaran en el lujoso hotel Mayag\u00fcez Resort &amp; Casino para que pudieran disfrutar de las Justas de la Liga Atletica Universitaria (LAI).<\/p>\n<p>Adem\u00e1s indic\u00f3 que tres de los cinco empleados que se quedaron en el resort residen en el Municipio de Cabo Rojo.<\/p>\n<p>&#8216;Esto es un abuso de primer orden. C\u00f3mo es posible que en tiempos de crisis fiscal, en donde el Banco Gubernamental de Fomento se encuentra en la insolvencia y que los suplidores del gobierno, incluyendo los terapistas de educaci\u00f3n especial, no han cobrado en meses, el Presidente de la UPR, Urayo\u00e1n Walker, autorizara el gasto de $6,467.30 para que estos empelados se dieran la buena vida en un lujoso hotel?&#8217;, sentenci\u00f3 el Senador por el Distrito de Arecibo.<\/p>\n<p>Seg\u00fan informaci\u00f3n en manos de Mart\u00ednez Santiago, los empleados se quedaron desde el 11 hasta el 17 de abril, una semana completa. El costo de cuatro de las cinco habitaciones fue de $1,306.46. El escandaloso desembolso fue aprobado por Ray Qui\u00f1onez V\u00e1zquez, Director del Programa de Asuntos Deportivos de la UPR.<\/p>\n<p>Los fondos provinieron de la cuenta 30110-638-000-XXXX-520-0-16.<\/p><div class=\"notic-content-middle\" id=\"notic-677672462\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>&#8216;No existe ninguna excusa para despilfarrar estos dineros en habitaciones de hotel. Los empleados que trabajaron en las Justas, por lo menos tres de ellos, viven en Cabo Rojo. Qu\u00e9 gasto tan grande era que ten\u00edan que hospedarlos en un hotel de lujo? La administraci\u00f3n de la UPR est\u00e1 mal enfocada si piensa que pod\u00eda pasar esto por debajo de la mesa. Este gasto fr\u00edvolo es una bofetada al pueblo y a los estudiantes. Tan culpable es el Presidente de la UPR, como quienes aprobaron esto&#8217;, agreg\u00f3 el l\u00edder estadista.<\/p>\n<p>En un memo con fecha del 31 de marzo, Qui\u00f1onez V\u00e1zquez, quien tambi\u00e9n se qued\u00f3 hospedado en hotel aunque vive en Cabo Rojo, le pide al Rector del Recinto Universitario de Mayag\u00fcez (RUM), John Fern\u00e1ndez Van Cleve, que concuerde con su solicitud de fondos para la estad\u00eda en el mencionado resort.<\/p>\n<p>Otra persona que se hospedo fue la secretaria de Qui\u00f1onez V\u00e1zquez, la se\u00f1ora Marilyn Garc\u00eda.<\/p>\n<p>El tambi\u00e9n portavoz de la delegaci\u00f3n del PNP en la Comisi\u00f3n de Salud del Senado reclam\u00f3 la renuncia de Walker, citando su pobre desempe\u00f1o y falta de controles administrativos.<\/p>","protected":false},"excerpt":{"rendered":"<p>El senador del Partido Nuevo Progresista (PNP), \u00c1ngel &#8216;Chayanne&#8217; Mart\u00ednez Santiago, denunci\u00f3 hoy, lunes, que la Universidad de Puerto Rico (UPR) pag\u00f3 para que un selecto grupo de sus empleados se hospedaran en el lujoso hotel Mayag\u00fcez Resort &amp; Casino para que pudieran disfrutar de las Justas de la Liga Atletica Universitaria (LAI). Adem\u00e1s indic\u00f3 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":585098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-116142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/116142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=116142"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/116142\/revisions"}],"predecessor-version":[{"id":585112,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/116142\/revisions\/585112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/585098"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=116142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=116142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=116142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}