{"id":116135,"date":"2016-07-18T21:07:00","date_gmt":"2016-07-19T01:07:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/gobierno\/la-calle\/policia\/20160718\/policia-busca-a-trio-por-robo-domiciliario-a-mano-armada-video\/"},"modified":"2025-07-30T06:21:42","modified_gmt":"2025-07-30T06:21:42","slug":"policia-busca-a-trio-por-robo-domiciliario-a-mano-armada-video","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160718\/policia-busca-a-trio-por-robo-domiciliario-a-mano-armada-video\/","title":{"rendered":"Polic\u00eda busca a tr\u00edo por robo domiciliario a mano armada (v\u00eddeo)"},"content":{"rendered":"<p>La Polic\u00eda de Puerto Rico divulg\u00f3 hoy, lunes, un v\u00eddeo de una c\u00e1mara de seguridad para dar con tres individuos que asaltaron un hogar en Toa Baja a mano armada.<\/p>\n<p>El robo domiciliario se report\u00f3 el pasado 15 de julio en una residencia en la urbanizaci\u00f3n Levittown.<\/p><div class=\"notic-content-middle\" id=\"notic-3340106657\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La querellante aleg\u00f3 que tres individuos a bordo de una guagua Kia color bronce llegaron a la residencia, dos de ellos la amenazaron con un arma de fuego despoj\u00e1ndola de una computadora port\u00e1til, un celular y una cadena. Luego amenazaron a un empleado de la compa\u00f1\u00eda Liberty que realizaba unos trabajos en la casa, y lo despojaron de una cartera.<\/p>\n<p>Nadie result\u00f3 herido durante la comisi\u00f3n del delito. Cualquier persona que pueda ofrecer informaci\u00f3n sobre este caso puede llamar al 787-269-2424 o al 787-343-2020.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda de Puerto Rico divulg\u00f3 hoy, lunes, un v\u00eddeo de una c\u00e1mara de seguridad para dar con tres individuos que asaltaron un hogar en Toa Baja a mano armada. El robo domiciliario se report\u00f3 el pasado 15 de julio en una residencia en la urbanizaci\u00f3n Levittown. La querellante aleg\u00f3 que tres individuos a bordo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":614743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,12,2],"tags":[],"class_list":["post-116135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-la-calle","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/116135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=116135"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/116135\/revisions"}],"predecessor-version":[{"id":614764,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/116135\/revisions\/614764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/614743"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=116135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=116135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=116135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}