{"id":115882,"date":"2017-02-10T12:03:00","date_gmt":"2017-02-10T16:03:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/20170210\/camara-investigara-violaciones-sobre-la-calidad-de-agua-potable\/"},"modified":"2025-07-23T02:25:38","modified_gmt":"2025-07-23T02:25:38","slug":"camara-investigara-violaciones-sobre-la-calidad-de-agua-potable","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20170210\/camara-investigara-violaciones-sobre-la-calidad-de-agua-potable\/","title":{"rendered":"C\u00e1mara investigar\u00e1 violaciones sobre la calidad de agua potable"},"content":{"rendered":"<p>Los representantes Jose &#8216;Che&#8217; Perez Cordero y Joel Franqui Atiles presentaron el viernes una resoluci\u00f3n para que se investiguen supuestas violaciones por parte de la Autoridad de Acueductos y Alcantarillados (AAA) con los par\u00e1metros de calidad establecidos en el agua potable que se distribuye a los abonados.<\/p>\n<p>P\u00e9rez Cordero, representante del Distrito 18, expres\u00f3 que luego de haberse publicado en la prensa que la AAA ha estado distribuyendo agua a la ciudadan\u00eda que no cumple con los par\u00e1metros de trihalometanos requeridos, ambos representantes presentaron la resoluci\u00f3n de la C\u00e1mara 159, la que ordena a la Comisi\u00f3n de Salud realizar una investigaci\u00f3n exhaustiva para comprobar si la AAA ha estado incumpliendo con el debido proceso de desinfecci\u00f3n del agua que se consume y los factores que lo han propiciado.<\/p>\n<p>&#8216;Es alarmante esta situaci\u00f3n que se conoci\u00f3 a trav\u00e9s de un auncio publicado en un medio. El que supuestamente se distribuya agua potable con componentes cancer\u00edgenos para el consumo de la poblaci\u00f3n, es una negligencia. Por eso hay que investigar con premura para conocer los hallazgos, fijar responsabilidades y tomar medidas correctivas, inmediatamente&#8217;, advirti\u00f3 P\u00e9rez Cordero en declaraciones escritas.<\/p><div class=\"notic-content-middle\" id=\"notic-4124716215\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Por su parte, Franqui Atiles, representante del Distrito 15, se\u00f1al\u00f3 que la AAA public\u00f3 el anuncio donde alertaba que &#8216;algunas personas que consumen agua potable que contienen trihalometanos totales en exceso de su nivel m\u00e1ximo por muchos a\u00f1os podr\u00edan presentar efectos adversos a su salud, problemas con los ri\u00f1ones o h\u00edgado, efectos al sistema nervioso y se puede aumentar el riesgo de contraer c\u00e1ncer&#8217;.<\/p>\n<p>Seg\u00fan la informaci\u00f3n, se realizaron muestreos que culminaron en diciembre pasado en los pueblos de Carolina, Can\u00f3vanas, Corozal, Lo\u00edza, Trujillo Alto, Toa Alta y San Juan, los cuales reflejaron un alto nivel de estos componentes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los representantes Jose &#8216;Che&#8217; Perez Cordero y Joel Franqui Atiles presentaron el viernes una resoluci\u00f3n para que se investiguen supuestas violaciones por parte de la Autoridad de Acueductos y Alcantarillados (AAA) con los par\u00e1metros de calidad establecidos en el agua potable que se distribuye a los abonados. P\u00e9rez Cordero, representante del Distrito 18, expres\u00f3 que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":562082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-115882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/115882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=115882"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/115882\/revisions"}],"predecessor-version":[{"id":562083,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/115882\/revisions\/562083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/562082"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=115882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=115882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=115882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}