{"id":115315,"date":"2016-10-03T22:25:00","date_gmt":"2016-10-04T02:25:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/junta-fiscal\/20161003\/se-activa-la-diaspora-ante-primera-reunion-publica-de-la-junta-de-control-f\/"},"modified":"2025-08-16T10:38:34","modified_gmt":"2025-08-16T10:38:34","slug":"se-activa-la-diaspora-ante-primera-reunion-publica-de-la-junta-de-control-f","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20161003\/se-activa-la-diaspora-ante-primera-reunion-publica-de-la-junta-de-control-f\/","title":{"rendered":"Se activa la di\u00e1spora ante primera reuni\u00f3n p\u00fablica de la Junta de Control F"},"content":{"rendered":"<p>&#8216;La gente estuvo de acuerdo en aprobar esto&#8217;, afirm\u00f3 en Nueva York el recien nombrado presidente de la Junta de Control Fiscal (JCF), Jose Carri\u00f3n III, refiriendose al establecimiento de la entidad que el viernes tom\u00f3 control sobre todas las agencias del gobierno de Puerto Rico. Carri\u00f3n argument\u00f3 que la JCF fue el resultado de un proceso bipartita, &#8216;tanto en Washington como en Puerto Rico&#8217;.<\/p>\n<p>La reuni\u00f3n comenz\u00f3 a las 8:30 de la ma\u00f1ana, pero ya desde las 7 hab\u00eda un grupo de manifestantes en contra de la JCF frente al edificio federal Alexander Hamilton. Eran alrededor de 40, un n\u00famero que, al parecer de algunos periodistas, era muy bajo. Alguno de los periodistas opin\u00f3 incluso que eran tan pocos que hac\u00edan el rid\u00edculo, que era mejor que no hubiesen protestado.<\/p>\n<p>El grupo de manifestantes despleg\u00f3 una pancarta y aunque no intentaron impedir la entrada por completo, hicieron que fuera lo m\u00e1s inc\u00f3moda posible. Cada vez que ve\u00edan a alguien en gab\u00e1n le gritaban, no importa qui\u00e9n fuera, &#8216;you vulture&#8217;, &#8216;buitre&#8217;, &#8216;cochino oink oink&#8217;. Pero los integrantes de la Junta nunca entraron por la puerta principal.<\/p>\n<p>En medio del reperpero entr\u00f3 Rafael Rojo, un desarrollador recordado por su rol en defensa de la construcci\u00f3n de Paseo Caribe, hoy director ejecutivo de la organizaci\u00f3n Bonistas del Patio, que quiere recuperar sus $2.5 millones que tiene en bonos del Banco Gubernamental de Fomento. A la entrada del edificio Hamilton, frente a los manifestantes, Rojo estaba nervioso, mirando a todos lados y cubri\u00e9ndose con la espalda de quien entraba delante de \u00e9l; pas\u00f3 desapercibido. De regreso a Puerto Rico, estaba mucho m\u00e1s relajado, en primera clase, tomando champagne en copa de pl\u00e1stico.<\/p>\n<p>Entre los manifestantes hab\u00eda tambi\u00e9n un hombre engabanado. Era un nuyorrican del sindicato de empleados p\u00fablicos Civil Service Employees Association en la ciudad de Nueva York, quien se disfraz\u00f3 de ejecutivo para entrar a la reuni\u00f3n. Su nombre es David Galarza.<\/p>\n<p>Luego de estar afuera junto al grupo de manifestantes, compuesto principalmente por puertorrique\u00f1os y puertorrique\u00f1as de la di\u00e1spora neoyorquina, Galarza entr\u00f3 al anfiteatro y se sent\u00f3 a observar la reuni\u00f3n de la JCF. Hab\u00eda muchos espacios vac\u00edos en las filas de asientos del anfiteatro. Los que las ocupaban eran, principalmente, desconocidos en gab\u00e1n, como Galarza.<\/p>\n<p>En medio de la reuni\u00f3n, Galarza se levant\u00f3 de su asiento y grit\u00f3: &#8216;se acabaron las PROMESAS, you guys are raping Puerto Rico (ustedes est\u00e1n violando a Puerto Rico)&#8217;. A \u00e9l se unieron otros dos manifestantes que gritaron en contra de la JCF.<\/p>\n<p>&#8216;Estamos bien claros que la di\u00e1spora aqu\u00ed est\u00e1 presente, estamos presentes en muchas luchas. La di\u00e1spora siempre ha jugado un papel bien importante, bien clave porque estamos en el belly of the beast (vientre de la bestia). Que hayan tenido esta reuni\u00f3n, en ese edificio donde est\u00e1 el Native American Museum, en el basement de donde est\u00e1 el bankruptcy court de los Estados Unidos, y tambi\u00e9n en un edificio que se llama Hamilton que es uno de los colonialistas originales de este pa\u00eds, o sea, es una bofetada inmensa al pueblo de Puerto Rico&#8217;, dijo Galarza.<\/p>\n<p>Tras la reuni\u00f3n p\u00fablica que no dur\u00f3 media hora y tuvo m\u00e1s bien el formato de una conferencia con libreto, y en la cual las decisiones tomadas por unanimidad no admitieron ninguna discusi\u00f3n, Carri\u00f3n hizo unas expresiones a la prensa, bajo la mirada ansiosa de Ana Matosantos, la \u00fanica mujer integrante de la JCF.<\/p>\n<p>&#8216;Estamos trabajando lo m\u00e1s r\u00e1pido posible y estableciendo los procedimientos para ser lo m\u00e1s transparente posible&#8217;, fue una de las primeras expresiones de Carri\u00f3n como presidente.<\/p>\n<p>En la ley PROMESA no queda claro qu\u00e9 documentos van a ser p\u00fablicos y cu\u00e1les no y a la prensa nos preocupa el tema de la transparencia, c\u00f3mo van a trabajarlo?, pregunt\u00f3 el Centro de Periodismo Investigativo.<\/p>\n<p>&#8216;La realidad es que es parte de los by laws (reglamentos), cuando los puedas verificar, el tema de la transparencia est\u00e1 presente&#8217;.<\/p>\n<p>Pero el reglamento de la JCF, que se aprob\u00f3 all\u00ed de inmediato, por unanimidad y sin margen a que se discutiera ninguna de sus cl\u00e1usulas, lo \u00fanico que indica sobre aspectos de transparencia es que con excepci\u00f3n de las sesiones ejecutivas, &#8216;todas las reuniones de la Junta en las que se toma acci\u00f3n oficial de cualquier tipo, ser\u00e1n abiertas al p\u00fablico. Las reuniones p\u00fablicas pueden ser en una oficina de la Junta o en cualquier otro lugar que se determine por la Junta, siempre que sean en un lugar accesible al p\u00fablico. En la medida de lo posible, las reuniones p\u00fablicas se transmitir\u00e1n por internet en la p\u00e1gina web de la Junta&#8217;.<\/p>\n<p>Menciona que &#8216;la divulgaci\u00f3n p\u00fablica de los materiales pertinentes de la Junta se har\u00e1 en el momento oportuno. La Junta mantendr\u00e1 una p\u00e1gina web donde se publicar\u00e1n todas las notificaciones p\u00fablicas&#8217;.<\/p>\n<p>El reglamento, que en t\u00e9rminos generales reitera aspectos que ya est\u00e1n contenidos en la Ley PROMESA, es poco preciso y gen\u00e9rico, lo que tiene el resultado de dar amplio margen a la JCF a tomar decisiones sin cortapisas.<\/p>\n<p>Pero la ley es ambigua en ese sentido, hay documentos que no se especifica si van a ser p\u00fablicos o no, insisti\u00f3 el CPI a Carri\u00f3n.<\/p>\n<p>&#8216;La ambig\u00fcedad quiz\u00e1 la est\u00e1s interpretando de forma negativa. Vamos a hacer todo lo posible por poner todo lo m\u00e1ximo que podamos para la luz p\u00fablica, e inclusive vamos a traducir los trabajos de la Junta y vamos a tener facilidad para cuando llegue el momento de testificar; que tambi\u00e9n personas que solamente se expresan en el idioma espa\u00f1ol, tambi\u00e9n puedan hacerlo. O sea, estamos conscientes de ese tema y vamos a hacer todo lo posible por la transparencia&#8217;, dijo Carri\u00f3n.<\/p>\n<p>Para la cr\u00f3nica completa pulse <a href=\"http:\/\/periodismoinvestigativo.com\">aqu\u00ed<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8216;La gente estuvo de acuerdo en aprobar esto&#8217;, afirm\u00f3 en Nueva York el recien nombrado presidente de la Junta de Control Fiscal (JCF), Jose Carri\u00f3n III, refiriendose al establecimiento de la entidad que el viernes tom\u00f3 control sobre todas las agencias del gobierno de Puerto Rico. Carri\u00f3n argument\u00f3 que la JCF fue el resultado de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":849802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-115315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/115315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=115315"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/115315\/revisions"}],"predecessor-version":[{"id":849820,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/115315\/revisions\/849820"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/849802"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=115315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=115315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=115315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}