{"id":114802,"date":"2016-04-02T12:59:00","date_gmt":"2016-04-02T16:59:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20160402\/exhortan-a-los-viequenses-a-expresarse-ante-consulta-sobre-un-puente-con-la\/"},"modified":"2025-07-22T00:35:29","modified_gmt":"2025-07-22T00:35:29","slug":"exhortan-a-los-viequenses-a-expresarse-ante-consulta-sobre-un-puente-con-la","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160402\/exhortan-a-los-viequenses-a-expresarse-ante-consulta-sobre-un-puente-con-la\/","title":{"rendered":"Exhortan a los viequenses a expresarse ante consulta sobre un puente con la"},"content":{"rendered":"<p>El senador Pedrito Rodr\u00edguez Gonz\u00e1lez del Distrito de Carolina exhort\u00f3 el s\u00e1bado al pueblo de Vieques a que ejerzan su voto ante la consulta que se realizar\u00e1 el domingo, 3 de abril de 2016 sobre la construcci\u00f3n de un puente entre Ceiba y Vieques.<\/p>\n<p>&#8216;La ordenanza N\u00famero 24, Serie 2014-15 fue aprobada ante la Legislatura Municipal para la edificaci\u00f3n de un puente entre ambos pueblos que incluye en el Presupuesto Municipal 2015-16, una partida econ\u00f3mica para sufragar los costos de dicha consulta&#8217;, explic\u00f3 el senador en un comunicado de prensa.<\/p>\n<p>Durante los pasados a\u00f1os, grupos en contra o a favor han realizados manifestaciones, consultas, entre otros. El senador exhorta a los viequenses a que aprovechen esta oportunidad para expresarse, ya que la propuesta para construir un puente de 6.5 millas le dar\u00eda acceso a la Isla Grande y a su vez, los viequenses tendr\u00edan acceso a los mercados, servicios de salud, entre otros servicios no disponibles en la Isla Nena.<\/p><div class=\"notic-content-middle\" id=\"notic-3660424841\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El proyecto propone diversas maneras de financiamiento para lograr el prop\u00f3sito de la misma, si resultase favorable la consulta para el pueblo de Vieques. Adem\u00e1s, la realizaci\u00f3n del estudio revela que no hay vida marina coralizada que pueda ser afectada ante la construcci\u00f3n del puente.<\/p>\n<p>&#8216;Los viequenses son los que se tienen que expresarse \u00fanicamente ante este asunto, ya que esto fue una iniciativa de su legislatura municipal y ellos son los que tienen el derecho a decir lo que desean. De ser favorable la consulta, entiendo que realizaci\u00f3n del puente deber\u00eda de ser mediante una APP&#8217;, expres\u00f3 el senador Rodr\u00edguez Gonz\u00e1lez.<\/p>","protected":false},"excerpt":{"rendered":"<p>El senador Pedrito Rodr\u00edguez Gonz\u00e1lez del Distrito de Carolina exhort\u00f3 el s\u00e1bado al pueblo de Vieques a que ejerzan su voto ante la consulta que se realizar\u00e1 el domingo, 3 de abril de 2016 sobre la construcci\u00f3n de un puente entre Ceiba y Vieques. &#8216;La ordenanza N\u00famero 24, Serie 2014-15 fue aprobada ante la Legislatura [&hellip;]<\/p>","protected":false},"author":0,"featured_media":550507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-114802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/114802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=114802"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/114802\/revisions"}],"predecessor-version":[{"id":550509,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/114802\/revisions\/550509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/550507"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=114802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=114802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=114802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}