{"id":114452,"date":"2014-01-29T22:26:00","date_gmt":"2014-01-30T02:26:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20140129\/velazquez-vuelve-a-la-silla-ganadora-luego-de-accidente\/"},"modified":"2025-08-21T11:17:39","modified_gmt":"2025-08-21T11:17:39","slug":"velazquez-vuelve-a-la-silla-ganadora-luego-de-accidente","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20140129\/velazquez-vuelve-a-la-silla-ganadora-luego-de-accidente\/","title":{"rendered":"Vel\u00e1zquez vuelve a la silla ganadora luego de accidente"},"content":{"rendered":"<p>Le tom\u00f3 unos &#8216;d\u00editas&#8217; pero ya est\u00e1 de nuevo ganando en las grandes ligas. Se trata del boricua John Velazquez, quien gan\u00f3 su primera carrera esta tarde en Gulfstream Park, menos de tres meses luego de la aparatosa carrera que sufriera durante la celebraci\u00f3n del Breeders&#8217; Cup Juvenile Fillies en Santa Anita.<\/p>\n<p>El &#8216;Hall Of Famer&#8217; sufri\u00f3 la ruptura de su bazo en aquella ocasi\u00f3n, y se especulaba cu\u00e1nto tiempo estar\u00eda convalesciendo antes de regresar a las carreras.<\/p>\n<p>Llev\u00f3 a la tresa\u00f1era Got Lucky a un c\u00f3modo triunfo en un grupo de &#8216;Allowance&#8217; como la gran favorita, ganando por m\u00e1s de cinco cuerpos a distancia de una milla. El entrenador de la hija de A.P. Indy es el famoso entrenador Todd Pletcher.<\/p>\n<p>El tiempo de la cebruna fue de 1:38.39 para la potranca, que hab\u00eda terminado segunda en Demoisell Stakes el pasado 30 de noviembre. Es una medio hermana de la madre del ganador del Derby de Kentucky de 2010, Super Saver.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le tom\u00f3 unos &#8216;d\u00editas&#8217; pero ya est\u00e1 de nuevo ganando en las grandes ligas. Se trata del boricua John Velazquez, quien gan\u00f3 su primera carrera esta tarde en Gulfstream Park, menos de tres meses luego de la aparatosa carrera que sufriera durante la celebraci\u00f3n del Breeders&#8217; Cup Juvenile Fillies en Santa Anita. El &#8216;Hall Of [&hellip;]<\/p>","protected":false},"author":0,"featured_media":886151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-114452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/114452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=114452"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/114452\/revisions"}],"predecessor-version":[{"id":886190,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/114452\/revisions\/886190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/886151"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=114452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=114452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=114452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}