{"id":113948,"date":"2016-05-24T13:08:00","date_gmt":"2016-05-24T17:08:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20160524\/sagrado-concedera-honoris-causa-a-carlos-delgado-y-a-manuel-mendez-del-rio\/"},"modified":"2025-07-27T11:04:24","modified_gmt":"2025-07-27T11:04:24","slug":"sagrado-concedera-honoris-causa-a-carlos-delgado-y-a-manuel-mendez-del-rio","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20160524\/sagrado-concedera-honoris-causa-a-carlos-delgado-y-a-manuel-mendez-del-rio\/","title":{"rendered":"Sagrado conceder\u00e1 Honoris Causa a Carlos Delgado y a Manuel M\u00e9ndez del R\u00edo"},"content":{"rendered":"<p>La Universidad del Sagrado Coraz\u00f3n (USC) conferir\u00e1 el grado de Doctor en Humanidades Honoris Causa a dos extraordinarios ejemplos de compromiso etico y servicio a la humanidad. Esta merecida distinci\u00f3n ser\u00e1 para el expelotero y fil\u00e1ntropo, Carlos Delgado Hern\u00e1ndez y Manuel Mendez del R\u00edo Piovich, creador de la Fundaci\u00f3n Microfinanzas BBVA, seg\u00fan lo dio a conocer el presidente de la USC, Gilberto J. Marxuach Torr\u00f3s.<\/p>\n<p>Adem\u00e1s anunci\u00f3 que la profesora Mar\u00eda Garc\u00e9s Vel\u00e1zquez, quien tuvo una destacada trayectoria como Catedr\u00e1tica en la Escuela de Enfermer\u00eda por espacio de 29 a\u00f1os, recibir\u00e1 la distinci\u00f3n de Profesora Em\u00e9ritus. Durante sus a\u00f1os de servicio, Garc\u00e9s Vel\u00e1zquez demostr\u00f3 un profundo sentido de integridad moral, honestidad intelectual y compromiso comunitario, cualidades que sirvieron de ejemplo e inspiraci\u00f3n a estudiantes, facultad y comunidad universitaria.<\/p>\n<p>&#8216;Cada uno, con un trasfondo distinto, denota un profundo compromiso de legar una mejor sociedad a trav\u00e9s de sus acciones afirmativas en beneficio de una causa com\u00fan. Su rectitud de car\u00e1cter, valores humanos y capacidad de trascender en sus ejecutorias, les ha llevado a que se confiera este honor por parte de la Universidad del Sagrado Coraz\u00f3n&#8217;, destac\u00f3 Marxuach.<\/p><div class=\"notic-content-middle\" id=\"notic-2234814572\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Carlos Delgado Hern\u00e1ndez ser\u00e1 reconocido por su responsabilidad social y compromiso firme con la educaci\u00f3n de nuestra ni\u00f1ez con necesidades especiales y la juventud universitaria, las v\u00edctimas de abuso, los j\u00f3venes con gran potencial deportivo, los hospitales pedi\u00e1tricos y m\u00faltiples causas filantr\u00f3picas en y fuera de Puerto Rico, a trav\u00e9s de la Fundaci\u00f3n Extra Bases, Inc. Su vida ejemplar como ciudadano y hombre de profunda integridad moral, as\u00ed como su brillante carrera como pelotero de Grandes Ligas, han merecido el afecto, reconocimiento y la admiraci\u00f3n del pueblo puertorrique\u00f1o.<\/p>\n<p>Asimismo, Manuel M\u00e9ndez del R\u00edo Piovich recibir\u00e1 el reconicimiento por su profunda responsabilidad social, compromiso \u00e9tico, car\u00e1cter moral y servicio a la humanidad. Ante el panorama desolador que contempl\u00f3 durante los a\u00f1os en que trabaj\u00f3 en varias naciones latinoamericanas y tras una exitosa carrera en el mundo de las finanzas y la banca internacional, M\u00e9ndez del R\u00edo Piovich cre\u00f3 en el 2007 la Fundaci\u00f3n Microfinanzas BBVA. Desde su creaci\u00f3n, esta Fundaci\u00f3n se propuso enfrentar y erradicar la pobreza a partir del concepto de finanzas responsables productivas que atendieran las necesidades de sectores marginados de la sociedad. Los resultados del proyecto son tan admirables, que lo convierten en una de las iniciativas de mayor impacto social en Am\u00e9rica Latina.<\/p>\n<p>Los grados honor\u00edficos se otorgar\u00e1n durante la Septuag\u00e9sima S\u00e9ptima Colaci\u00f3n de Grados, que se celebrar\u00e1 el viernes, 3 de junio de 2016, a las 2:00 p.m. en el Centro de Convenciones de Puerto Rico.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Universidad del Sagrado Coraz\u00f3n (USC) conferir\u00e1 el grado de Doctor en Humanidades Honoris Causa a dos extraordinarios ejemplos de compromiso etico y servicio a la humanidad. Esta merecida distinci\u00f3n ser\u00e1 para el expelotero y fil\u00e1ntropo, Carlos Delgado Hern\u00e1ndez y Manuel Mendez del R\u00edo Piovich, creador de la Fundaci\u00f3n Microfinanzas BBVA, seg\u00fan lo dio a [&hellip;]<\/p>","protected":false},"author":0,"featured_media":590566,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-113948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=113948"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113948\/revisions"}],"predecessor-version":[{"id":590579,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113948\/revisions\/590579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/590566"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=113948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=113948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=113948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}