{"id":113780,"date":"2012-10-01T00:00:00","date_gmt":"2012-10-01T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20121001\/las-lobas-a-un-paso-de-su-tercer-titulo\/"},"modified":"2025-08-25T13:04:27","modified_gmt":"2025-08-25T13:04:27","slug":"las-lobas-a-un-paso-de-su-tercer-titulo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20121001\/las-lobas-a-un-paso-de-su-tercer-titulo\/","title":{"rendered":"Las Lobas a un paso de su tercer t\u00edtulo"},"content":{"rendered":"<p><i>Las Lobas a un paso de su tercer t\u00edtulo<\/i><\/p>\n<p>Las Lobas de Arecibo se colocaron a un paso de conquistar su tercer t\u00edtulo nacional en l\u00ednea al derrotar 14-1 a las Brujas de Guayama, el pasado fin de semana, en la continuaci\u00f3n de la serie final del torneo juvenil de la Liga de Beisbol Femenino de Puerto Rico.<\/p>\n<p>Con el triunfo sobre las sure\u00f1as, las Lobas extendieron a 44 su racha de triunfos en tres a\u00f1os de existencia del torneo.<\/p>\n<p>Las arecibe\u00f1as marcaron cinco carreras en el primer episodio y pisaron el plato en ocho ocasiones en la tercera entrada.<\/p>\n<p>Las lanzadoras Ashley Nieves y Michelle Mart\u00ednez se combinaron para permitir apenas un imparable con una carrera.<\/p>\n<p>Nieves, quien trabaj\u00f3 tres entradas con cinco ponchetes, extendi\u00f3 a 16-0 su marca perfecta en tres a\u00f1os de participaci\u00f3n en la Liga.<\/p>\n<p>En la ofensiva ganadora, Ambar Luciano bate\u00f3 de 2-2 con dos carreras anotadas, Ashley G\u00f3mez de 2-1 con dos remolcadas y Michelle Mart\u00ednez se fue de 3-1 con un doble y 3 carreras remolcadas.<\/p>\n<p>Por Guayama, Nicole Caraballo fue la \u00fanica que peg\u00f3 hit en causa perdida.<\/p>\n<p>La serie es a un m\u00e1ximo de tres desaf\u00edos. El equipo ganador de dos juegos se proclamar\u00e1 campe\u00f3n. El segundo partido de la serie ser\u00e1 este s\u00e1bado. El parque donde se celebrar\u00e1 el juego ser\u00e1 anunciado pr\u00f3ximamente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Las Lobas a un paso de su tercer t\u00edtulo Las Lobas de Arecibo se colocaron a un paso de conquistar su tercer t\u00edtulo nacional en l\u00ednea al derrotar 14-1 a las Brujas de Guayama, el pasado fin de semana, en la continuaci\u00f3n de la serie final del torneo juvenil de la Liga de Beisbol Femenino [&hellip;]<\/p>","protected":false},"author":0,"featured_media":911514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-113780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=113780"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113780\/revisions"}],"predecessor-version":[{"id":911554,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113780\/revisions\/911554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/911514"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=113780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=113780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=113780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}