{"id":113622,"date":"2015-04-08T17:29:32","date_gmt":"2015-04-08T21:29:32","guid":{"rendered":"http:\/\/www.noticel.com\/boxeo-caliente\/deportes\/20150408\/bachatero-homenajea-a-macho-camacho-en-video-musical\/"},"modified":"2025-08-19T03:39:49","modified_gmt":"2025-08-19T03:39:49","slug":"bachatero-homenajea-a-macho-camacho-en-video-musical","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20150408\/bachatero-homenajea-a-macho-camacho-en-video-musical\/","title":{"rendered":"Bachatero homenajea a &#8216;Macho&#8217; Camacho en video musical"},"content":{"rendered":"<p>El bachatero dominicano Anzel presenta hoy miercoles el v\u00eddeo de su nuevo sencillo, &#8216;Nunca me fui&#8217;, en el que rinde homenaje al boxeador boricua Hector &#8216;Macho&#8217; Camacho, quien muri\u00f3 en 2013 a causa de un disparo.<\/p>\n<p>\u00bbMacho&#8217; Camacho no es solamente un icono en el mundo de los deportes, sino para la comunidad latina en general&#8217;, asegur\u00f3 en un comunicado de prensa el artista, quien asegur\u00f3 que es un amante del boxeo.<\/p>\n<p>El cantautor, de 28 a\u00f1os, que presentar\u00e1 el v\u00eddeo en el programa Primer Impacto, de la cadena hispana Univision, expres\u00f3 que quer\u00eda asegurarse de honrar de alguna manera la memoria del boxeador.<\/p><div class=\"notic-content-middle\" id=\"notic-4290167202\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>&#8216;Macho&#8217; Camacho muri\u00f3 a los 50 a\u00f1os tras haber recibido un disparo en la cara durante un tiroteo frente a un establecimiento de Bayam\u00f3n, ciudad aleda\u00f1a a San Juan.<\/p>\n<p>El nuevo v\u00eddeo de Anzel fue grabado en Venezuela y lo dirigi\u00f3 Marlon Pe\u00f1a, quien ha trabajado con grandes figuras como el reguetonero puertorrique\u00f1o Don Omar y el d\u00fao venezolano Chino y Nacho.<\/p>","protected":false},"excerpt":{"rendered":"<p>El bachatero dominicano Anzel presenta hoy miercoles el v\u00eddeo de su nuevo sencillo, &#8216;Nunca me fui&#8217;, en el que rinde homenaje al boxeador boricua Hector &#8216;Macho&#8217; Camacho, quien muri\u00f3 en 2013 a causa de un disparo. \u00bbMacho&#8217; Camacho no es solamente un icono en el mundo de los deportes, sino para la comunidad latina en [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-113622","post","type-post","status-publish","format-standard","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=113622"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113622\/revisions"}],"predecessor-version":[{"id":870124,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113622\/revisions\/870124"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=113622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=113622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=113622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}