{"id":113598,"date":"2012-08-20T13:25:00","date_gmt":"2012-08-20T17:25:00","guid":{"rendered":"http:\/\/www.noticel.com\/economia\/20120820\/baja-el-desempleo-segun-departamento-del-trabajo\/"},"modified":"2025-08-26T06:22:03","modified_gmt":"2025-08-26T06:22:03","slug":"baja-el-desempleo-segun-departamento-del-trabajo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20120820\/baja-el-desempleo-segun-departamento-del-trabajo\/","title":{"rendered":"Baja el desempleo seg\u00fan Departamento del Trabajo"},"content":{"rendered":"<p>El Departamento del Trabajo y Recursos Humanos (DTRH), public\u00f3 el lunes los datos estad\u00edsticos de empleo y desempleo en Puerto Rico para el mes de julio de 2012, que muestran una continua disminuci\u00f3n en la tasa y cifra de desempleo por los pasados siete meses.<\/p>\n<p>La tasa de desempleo ajustada estacionalmente para julio de 2012 fue de 13.7 por ciento.<\/p>\n<p>En relaci\u00f3n a julio de 2011 (15.6 por ciento) la tasa baj\u00f3 1.9 puntos porcentuales.<\/p>\n<p>El n\u00famero de personas desempleadas, ajustada estacionalmente, en julio de 2012 fue de 173,000. En relaci\u00f3n a julio de 2011 fue de 198,000 el n\u00famero del desempleo ajustado estacionalmente, lo que represent\u00f3 una baja de 25,000.<\/p>\n<p>El empleo total ajustado estacionalmente en Puerto Rico para el mes de julio de 2012 fue de 1,094,000; lo que present\u00f3 un crecimiento de 22,000 personas empleadas al compararse con julio de 2011 que fue de 1,072,000.<\/p>\n<p>En cuanto a la Encuesta de Establecimientos, se inform\u00f3 que el empleo asalariado no agr\u00edcola en Puerto Rico, ajustado estacionalmente, fue de 912,800 en julio de 2012.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Departamento del Trabajo y Recursos Humanos (DTRH), public\u00f3 el lunes los datos estad\u00edsticos de empleo y desempleo en Puerto Rico para el mes de julio de 2012, que muestran una continua disminuci\u00f3n en la tasa y cifra de desempleo por los pasados siete meses. La tasa de desempleo ajustada estacionalmente para julio de 2012 [&hellip;]<\/p>","protected":false},"author":0,"featured_media":534052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-113598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=113598"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113598\/revisions"}],"predecessor-version":[{"id":914198,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113598\/revisions\/914198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/534052"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=113598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=113598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=113598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}