{"id":113270,"date":"2014-01-07T06:41:56","date_gmt":"2014-01-07T10:41:56","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20140107\/media-hora-diaria-de-meditacion-alivia-los-sintomas-de-depresion-y-ansiedad\/"},"modified":"2025-08-22T05:41:52","modified_gmt":"2025-08-22T05:41:52","slug":"media-hora-diaria-de-meditacion-alivia-los-sintomas-de-depresion-y-ansiedad","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20140107\/media-hora-diaria-de-meditacion-alivia-los-sintomas-de-depresion-y-ansiedad\/","title":{"rendered":"Media hora diaria de meditaci\u00f3n alivia los s\u00edntomas de depresi\u00f3n y ansiedad"},"content":{"rendered":"<p>Una media hora diaria de meditaci\u00f3n puede aliviar los s\u00edntomas de la ansiedad y la depresi\u00f3n, seg\u00fan un estudio que difunde hoy la revista Journal of Internal Medicine, una de las publicaciones de la Sociedad Medica de Estados Unidos.<\/p>\n<p>&#8216;Hay mucha gente que usa la meditaci\u00f3n, pero no es una pr\u00e1ctica que se considere como una terapia m\u00e9dica convencional&#8217;, indic\u00f3 Madhav Goyal, profesor asistente en la Divisi\u00f3n de Medicina Interna en la Escuela de Medicina de la Universidad John Hopkins, de Maryland.<\/p>\n<p>&#8216;Pero, en nuestro estudio, la meditaci\u00f3n aparentemente proporcion\u00f3 tanto alivio de algunos de los s\u00edntomas de la ansiedad y la depresi\u00f3n como otros estudios han encontrado en los medicamentos antidepresivos&#8217;, a\u00f1adi\u00f3.<\/p>\n<p>Los pacientes que participaron en el estudio no ten\u00edan ansiedad o depresi\u00f3n graves.<\/p>\n<p>Los investigadores evaluaron el grado en el cual esos s\u00edntomas cambiaban en las personas que ten\u00edan una variedad de condiciones tales como el insomnio o la fibromialgia, aunque s\u00f3lo una minor\u00eda de ellas ten\u00edan un diagn\u00f3stico de enfermedad mental.<\/p>\n<p>Goyal y sus colegas encontraron que la llamada &#8216;meditaci\u00f3n centrada&#8217; -una forma budista que centra la atenci\u00f3n en el momento presente sin juicio sobre lo que ocurre- tambi\u00e9n mostr\u00f3 la posibilidad del alivio de algunos s\u00edntomas dolorosos.<\/p>\n<p>Las conclusiones se validaron a\u00fan despu\u00e9s de que los investigadores controlaran la posibilidad de un efecto placebo, por el cual los sujetos en un estudio se sienten mejor aun si no reciben tratamiento alguno porque perciben que se les da alguna ayuda para sus padecimientos.<\/p>\n<p>Para su estudio los investigadores analizaron cuarenta y siete pruebas cl\u00ednicas realizadas en junio de 2013 entre 3,515 participantes y que involucraron meditaci\u00f3n y varios aspectos de la salud mental y f\u00edsica, incluidas depresi\u00f3n, ansiedad, estr\u00e9s, insomnio, abuso de sustancias, diabetes, enfermedad cardiaca, c\u00e1ncer y dolores cr\u00f3nicos.<\/p>\n<p>Los cient\u00edficos encontraron pruebas de mejor\u00eda moderada en los s\u00edntomas de ansiedad, depresi\u00f3n y dolor despu\u00e9s de que los participantes cursaran un programa t\u00edpico de instrucci\u00f3n en meditaci\u00f3n centrada.<\/p>\n<p>Asimismo hallaron pruebas menores de mejor\u00eda en el estr\u00e9s y la calidad de vida.<\/p>\n<p>En los estudios que siguieron a los participantes por seis meses las mejor\u00edas persistieron.<\/p>\n<p>Goyal dijo que &#8216;mucha gente tiene esta idea de que la meditaci\u00f3n es sentarse y no hacer nada&#8217;.<\/p>\n<p>&#8216;Pero \u00e9sa no es la realidad&#8217;, agreg\u00f3.<\/p>\n<p>&#8216;La meditaci\u00f3n es un entrenamiento activo de la mente para aumentar la percepci\u00f3n de la realidad, y hay diferentes programas de meditaci\u00f3n que buscan esto por v\u00edas distintas&#8217;, enfatiz\u00f3.<\/p>\n<p>La meditaci\u00f3n centrada se practica, habitualmente, de 30 a 40 minutos por d\u00eda, y enfatiza la aceptaci\u00f3n de las percepciones, sentimientos y pensamientos sin juzgarlos, y un relajamiento del cuerpo y la mente.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una media hora diaria de meditaci\u00f3n puede aliviar los s\u00edntomas de la ansiedad y la depresi\u00f3n, seg\u00fan un estudio que difunde hoy la revista Journal of Internal Medicine, una de las publicaciones de la Sociedad Medica de Estados Unidos. &#8216;Hay mucha gente que usa la meditaci\u00f3n, pero no es una pr\u00e1ctica que se considere como [&hellip;]<\/p>","protected":false},"author":0,"featured_media":887562,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-113270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=113270"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113270\/revisions"}],"predecessor-version":[{"id":887601,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113270\/revisions\/887601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/887562"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=113270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=113270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=113270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}