{"id":113089,"date":"2012-05-29T06:33:00","date_gmt":"2012-05-29T10:33:00","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20120529\/asfixiada-por-el-calor-dominicana\/"},"modified":"2025-08-27T05:09:04","modified_gmt":"2025-08-27T05:09:04","slug":"asfixiada-por-el-calor-dominicana","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20120529\/asfixiada-por-el-calor-dominicana\/","title":{"rendered":"Asfixiada por el calor Dominicana"},"content":{"rendered":"<p>Santo Domingo &#8211; Las autoridades sanitarias de Rep\u00fablica Dominicana llamaron hoy a la poblaci\u00f3n a adoptar una serie de medidas preventivas para evitar muertes y problemas de salud ante la intensa ola de calor que asfixia estos d\u00edas el pa\u00eds.<\/p>\n<p>La temperatura oscila hoy entre los 29 y 30 grados en buena parte del territorio nacional pero la humedad eleva la sensaci\u00f3n t\u00e9rmica por encima de los 32 grados.<\/p>\n<p>Las situaci\u00f3n se mantendr\u00e1n as\u00ed durante los pr\u00f3ximos d\u00edas, seg\u00fan el pron\u00f3stico de la Oficina Nacional de Meteorolog\u00eda (Onamet), quien recomend\u00f3 a la poblaci\u00f3n no exponerse al sol durante las 11.00 y 16.00 hora local (15.00 y 20.00 GMT).<\/p>\n<p>Ante este panorama, el ministro de Salud, Bautista Rojas G\u00f3mez, instruy\u00f3 hoy a los directores y encargados de \u00e1reas de salud distribuir en sus respectivas localidades materiales preventivos de c\u00f3mo enfrentar la \u00e9poca de calor.<\/p>\n<p>Entre las medidas figura el consumo de comidas ligeras y refrescantes como frutas y vegetales por su alto contenido de agua, fibra, vitaminas y otros nutrientes, se\u00f1al\u00f3 en un comunicado.<\/p>\n<p>Asimismo, recomend\u00f3 ingerir l\u00edquidos con mayor frecuencia, sobre todo, si se est\u00e1 expuesto al sol, pr\u00e1ctica alg\u00fan ejercicio o realiza alguno tipo de actividad f\u00edsica.<\/p>\n<p>&#8216;Mantener estas medidas de prevenci\u00f3n en esta \u00e9poca de altas temperaturas es lo fundamental, ya que lo que queremos es evitar trastornos de salud en la poblaci\u00f3n&#8217; agreg\u00f3.<\/p>\n<p>Adem\u00e1s exhort\u00f3 a la poblaci\u00f3n a que durante el verano &#8216;adopten todas esas medidas debido a que el calor, la transpiraci\u00f3n y la humedad hacen que el organismo pierda mayor proporci\u00f3n de agua&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Santo Domingo &#8211; Las autoridades sanitarias de Rep\u00fablica Dominicana llamaron hoy a la poblaci\u00f3n a adoptar una serie de medidas preventivas para evitar muertes y problemas de salud ante la intensa ola de calor que asfixia estos d\u00edas el pa\u00eds. La temperatura oscila hoy entre los 29 y 30 grados en buena parte del territorio [&hellip;]<\/p>","protected":false},"author":0,"featured_media":916272,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-113089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=113089"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113089\/revisions"}],"predecessor-version":[{"id":916285,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/113089\/revisions\/916285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/916272"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=113089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=113089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=113089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}