{"id":112152,"date":"2016-10-05T16:03:00","date_gmt":"2016-10-05T20:03:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/mundo\/politica\/20161005\/abogan-por-la-libertad-de-oscar-lopez-en-el-washington-post\/"},"modified":"2025-08-16T18:43:05","modified_gmt":"2025-08-16T18:43:05","slug":"abogan-por-la-libertad-de-oscar-lopez-en-el-washington-post","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20161005\/abogan-por-la-libertad-de-oscar-lopez-en-el-washington-post\/","title":{"rendered":"Abogan por la libertad de Oscar L\u00f3pez en el Washington Post"},"content":{"rendered":"<p>La Coalici\u00f3n para la Liberaci\u00f3n de Oscar L\u00f3pez arrecia su campa\u00f1a por la excarcelaci\u00f3n del prisionero pol\u00edtico de cara a un evento multitudinario convocado para el domingo, 9 de octubre, el parque Lafayette de Washingotn D.C.<\/p>\n<p>Los esfuerzos del organismo incluyeron una publicaci\u00f3n hoy, mi\u00e9rcoles, en el Washington Post.<\/p>\n<p>En la actividad del domingo frente a la Casa Blanca se espera la participaci\u00f3n del congresista puertorrique\u00f1o Luis Guti\u00e9rrez, la conjecal de la ciudad de Nueva York, Melissa Mark Viverito, la alcaldesa de San Juan, Carmen Yul\u00edn Cruz Soto, el acad\u00e9mico Cornel West y el artista Ren\u00e9 P\u00e9rez, conocido como Residente.<\/p><div class=\"notic-content-middle\" id=\"notic-824502880\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>El evento que inicia al mediod\u00eda incluye presentaciones art\u00edsticas.<img decoding=\"async\" embed-content-articleid=\"609967503\" embed-content-groupid=\"593030475\" embed-content-id=\"609967503\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2016\/10\/05\/IMG_4407_8151794_ver1.0_320_240.jpg\"\/><\/p>\n<p><em>Anuncio en el Washington Post<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>La Coalici\u00f3n para la Liberaci\u00f3n de Oscar L\u00f3pez arrecia su campa\u00f1a por la excarcelaci\u00f3n del prisionero pol\u00edtico de cara a un evento multitudinario convocado para el domingo, 9 de octubre, el parque Lafayette de Washingotn D.C. Los esfuerzos del organismo incluyeron una publicaci\u00f3n hoy, mi\u00e9rcoles, en el Washington Post. En la actividad del domingo frente [&hellip;]<\/p>","protected":false},"author":0,"featured_media":853180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17,7,2],"tags":[],"class_list":["post-112152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","category-politica","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/112152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=112152"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/112152\/revisions"}],"predecessor-version":[{"id":853194,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/112152\/revisions\/853194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/853180"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=112152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=112152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=112152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}