{"id":110387,"date":"2013-11-01T12:51:16","date_gmt":"2013-11-01T16:51:16","guid":{"rendered":"http:\/\/www.noticel.com\/mundo\/20131101\/un-muerto-un-desaparecido-y-46-evacuados-por-fuertes-lluvias-en-argentina\/"},"modified":"2025-07-18T10:25:07","modified_gmt":"2025-07-18T10:25:07","slug":"un-muerto-un-desaparecido-y-46-evacuados-por-fuertes-lluvias-en-argentina","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20131101\/un-muerto-un-desaparecido-y-46-evacuados-por-fuertes-lluvias-en-argentina\/","title":{"rendered":"Un muerto, un desaparecido y 46 evacuados por fuertes lluvias en Argentina"},"content":{"rendered":"<p>Al menos una persona muerta, una desaparecida y 46 evacuadas dejan las fuertes lluvias que afectan a diez provincias argentinas, en especial a C\u00f3rdoba (centro), informaron hoy las autoridades.<\/p>\n<p>El Servicio Meteorol\u00f3gico Nacional (SMN) se\u00f1al\u00f3 que una fuerte tormenta se abati\u00f3 el jueves sobre varias regiones de Argentina.<\/p>\n<p>Las provincias m\u00e1s afectadas por las lluvias son las de Buenos Aires, Santa Fe, Santiago del Estero, Entre R\u00edos, Tucum\u00e1n, La Pampa, Catamarca, La Rioja, Santa Fe y C\u00f3rdoba.<\/p>\n<p>En C\u00f3rdoba, el temporal afect\u00f3 a varios barrios de la capital hom\u00f3nima, informaron hoy autoridades locales, que estiman que las precipitaciones en la ciudad son &#8216;superiores a los 50 mil\u00edmetros&#8217;, por lo que se ha declarado el estado de &#8216;emergencia ambiental&#8217;.<\/p>\n<p>Las fuertes lluvias causaron la muerte en C\u00f3rdoba de una joven de 14 a\u00f1os al caerle encima el techo de su casa por el fuerte viento, y un taxista permanece desaparecido tras ser arrastrado por el r\u00edo al caerse un puente en la localidad de Jes\u00fas Mar\u00eda.<\/p>\n<p>Otras 46 personas debieron ser evacuadas hacia lugares m\u00e1s seguros, se inform\u00f3.<\/p>\n<p>La ciudad de Buenos Aires tambi\u00e9n permanece en alerta, aunque no se cumplieron las previsiones que auguraban una fuerte tormenta que descargar\u00eda m\u00e1s de 130 mil\u00edmetros de agua durante la pasada noche.<\/p>\n<p>El SMN se\u00f1al\u00f3 que las lluvias continuar\u00e1n este viernes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Al menos una persona muerta, una desaparecida y 46 evacuadas dejan las fuertes lluvias que afectan a diez provincias argentinas, en especial a C\u00f3rdoba (centro), informaron hoy las autoridades. El Servicio Meteorol\u00f3gico Nacional (SMN) se\u00f1al\u00f3 que una fuerte tormenta se abati\u00f3 el jueves sobre varias regiones de Argentina. Las provincias m\u00e1s afectadas por las lluvias [&hellip;]<\/p>","protected":false},"author":0,"featured_media":517189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-110387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/110387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=110387"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/110387\/revisions"}],"predecessor-version":[{"id":517197,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/110387\/revisions\/517197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/517189"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=110387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=110387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=110387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}