{"id":108305,"date":"2016-07-26T18:19:00","date_gmt":"2016-07-26T22:19:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/credito-de-pr\/economia\/gobierno\/20160726\/agp-firma-medidas-de-presupuesto-antes-de-partir-a-convencion-democrata\/"},"modified":"2025-07-19T02:53:10","modified_gmt":"2025-07-19T02:53:10","slug":"agp-firma-medidas-de-presupuesto-antes-de-partir-a-convencion-democrata","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20160726\/agp-firma-medidas-de-presupuesto-antes-de-partir-a-convencion-democrata\/","title":{"rendered":"AGP firma medidas de presupuesto antes de partir a Convenci\u00f3n Dem\u00f3crata"},"content":{"rendered":"<p>El gobernador Alejandro Garc\u00eda Padilla firm\u00f3 varias proyectos de ley relacionados al presupuesto para el a\u00f1o fiscal 2016 &#8211; 2017 que a su vez buscan atender la delicada situaci\u00f3n de liquidez del gobierno.<\/p>\n<p>Se trata del proyecto de la C\u00e1mara 2960 para volver a nutrir el Fondo de Emergencia con una aportaci\u00f3n no menor al 1% del estimado de rentas sometido por Hacienda para la preparaci\u00f3n del presupuesto recomendado, as\u00ed como el proyecto de la C\u00e1mara 2961 que permite manejar el desembolso de asignaciones especiales incluidas en el presupuesto considerando la liquidez del gobierno, y el proyecto de la C\u00e1mara 2962 que crea un mecanismo de ley para reestructurar parte de la deuda del gobierno estatal con el Banco Gubernamental de Fomento (BGF).<\/p>\n<p>El Fondo de Emergencia creado por el P de la C 2960 para afrontar las necesidades p\u00fablicas inesperadas e imprevistas, comenzar\u00eda a nutrirse nuevamente tras la firma ejecutiva. Durante los \u00faltimos a\u00f1os se legisl\u00f3 para que este fondo no se nutriera debido a la crisis fiscal. Establece como medida transicional que la aportaci\u00f3n para el a\u00f1o fiscal 2016-2017 ser\u00e1 por $20 millones, basado en el presupuesto recomendado.<\/p>\n<p>Por otro lado, con el P de la C 2961 se establece que las asignaciones especiales que se incluir\u00e1n en el presupuesto del a\u00f1o fiscal 2016-2017 se determinar\u00e1n de acuerdo a la situaci\u00f3n fiscal existente.<\/p><div class=\"notic-content-middle\" id=\"notic-3008751747\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Asimismo, la aprobaci\u00f3n del P de la C 2962 viabiliza esfuerzos para atender de forma responsable la situaci\u00f3n financiera del BGF. Con esta medida se autoriza al Banco a reestructurar consolidaci\u00f3n de inversi\u00f3n en empr\u00e9stitos de financiamientos y obligaciones otorgados a entidades gubernamentales del Estado Libre Asociado (ELA) que son pagaderos y a suspender por el a\u00f1o fiscal 2016-2017 las transferencias mensuales que el Secretario de Hacienda realiza al Fondo Especial para la Amortizaci\u00f3n y Redenci\u00f3n de las Obligaciones Generales Evidenciadas por Bonos y Pagar\u00e9s. Esta acci\u00f3n le permitir\u00e1 al gobierno atender las necesidades apremiantes de la ciudadan\u00eda para el a\u00f1o fiscal 2016-2017, pagar las deudas generadas con suplidores de servicios y salvaguardar el buen nombre del ELA frente a sus acreedores.<\/p>\n<p>Garc\u00eda Padilla tambi\u00e9n dio paso al proyecto de la C\u00e1mara 2929 para establecer como pol\u00edtica p\u00fablica que la contrataci\u00f3n de personal bajo clasificaci\u00f3n irregular ser\u00e1 la excepci\u00f3n y no la norma en el gobierno, por lo que las agencias deber\u00e1n reducir la utilizaci\u00f3n de empleados temporales para funciones de car\u00e1cter permanente.<\/p>\n<p>De este modo, todo empleado temporal tendr\u00e1 derecho a que se le cambie su clasificaci\u00f3n a empleado de carrera si ha prestado servicios continuos en una agencia dentro del servicio p\u00fablico, a tiempo completo y ocupando el mismo puesto, por dos a\u00f1os o m\u00e1s. Para ello, la agencia para la cual presta servicios tambi\u00e9n deber\u00e1 certificar que la necesidad del puesto es permanente y que el empleado temporal posee los requisitos m\u00ednimos de preparaci\u00f3n y experiencia establecidos para el puesto as\u00ed como que ha prestado servicios satisfactorios.<\/p>\n<p>De otra parte, el Ejecutivo firm\u00f3 el proyecto del Senado 1577 que incentiva el establecimiento en Puerto Rico de una industria de mantenimiento, reparaci\u00f3n y acondicionamiento de embarcaciones mar\u00edtimas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El gobernador Alejandro Garc\u00eda Padilla firm\u00f3 varias proyectos de ley relacionados al presupuesto para el a\u00f1o fiscal 2016 &#8211; 2017 que a su vez buscan atender la delicada situaci\u00f3n de liquidez del gobierno. Se trata del proyecto de la C\u00e1mara 2960 para volver a nutrir el Fondo de Emergencia con una aportaci\u00f3n no menor al [&hellip;]<\/p>","protected":false},"author":0,"featured_media":524024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22,4,2],"tags":[],"class_list":["post-108305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/108305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=108305"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/108305\/revisions"}],"predecessor-version":[{"id":524025,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/108305\/revisions\/524025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/524024"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=108305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=108305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=108305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}