{"id":108268,"date":"2012-10-04T16:00:49","date_gmt":"2012-10-04T20:00:49","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20121004\/lvsf-changos-repiten-tortuoso-honor\/"},"modified":"2025-08-25T07:41:31","modified_gmt":"2025-08-25T07:41:31","slug":"lvsf-changos-repiten-tortuoso-honor","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20121004\/lvsf-changos-repiten-tortuoso-honor\/","title":{"rendered":"LVSF: Changos repiten tortuoso honor"},"content":{"rendered":"<p>La puntuaci\u00f3n m\u00e1s baja en la historia de un parcial en serie regular de la Liga de Voleibol Superior Masculino fue igualada en el partido de ayer miercoles entre los Changos de Naranjito y los Mets de Guaynabo.<\/p>\n<p>El primer parcial del partido fue dominado por los Mets 25-9.<\/p>\n<p>Este marcador iguala lo ocurrido el 20 de octubre de 2010, durante el tercer parcial, donde los Plataneros de Corozal dominaron a los Changos.<\/p><div class=\"notic-content-middle\" id=\"notic-1698552925\"><div class=\"notic-adlabel\">Advertisements<\/div><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/15122022\/JP-Monopoly-Launch-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/15122022\/JP-Monopoly-Launch-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/15122022\/JP-Monopoly-Launch-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/div>\n<p>Esta es la segunda marca en donde est\u00e1n involucrados los P\u00e1jaros Negros, el pasado domingo 30 de septiembre estos lograron dominar el parcial de mayor puntuaci\u00f3n al dominar a los Plataneros 40-38.<\/p>\n<p>El parcial de mayor puntuaci\u00f3n en la historia de la FPV fue en la serie semifinal de 2001 donde los Rebeldes de Moca se impusieron a los Caribes de San Sebasti\u00e1n 47-45.<\/p>","protected":false},"excerpt":{"rendered":"<p>La puntuaci\u00f3n m\u00e1s baja en la historia de un parcial en serie regular de la Liga de Voleibol Superior Masculino fue igualada en el partido de ayer miercoles entre los Changos de Naranjito y los Mets de Guaynabo. El primer parcial del partido fue dominado por los Mets 25-9. Este marcador iguala lo ocurrido el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":909163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-108268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/108268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=108268"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/108268\/revisions"}],"predecessor-version":[{"id":909213,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/108268\/revisions\/909213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/909163"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=108268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=108268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=108268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}