{"id":107483,"date":"2014-11-13T16:27:10","date_gmt":"2014-11-13T20:27:10","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20141113\/lesionado-ingeniero-de-act-tras-caer-de-puente-en-lares\/"},"modified":"2025-08-18T02:30:05","modified_gmt":"2025-08-18T02:30:05","slug":"lesionado-ingeniero-de-act-tras-caer-de-puente-en-lares","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20141113\/lesionado-ingeniero-de-act-tras-caer-de-puente-en-lares\/","title":{"rendered":"Lesionado ingeniero de ACT tras caer de puente en Lares"},"content":{"rendered":"<p>Un incidente desgraciado se report\u00f3 a las 10:35 de la ma\u00f1ana del jueves en un puente localizado en el kil\u00f3metro 52.1, de la carretera 128, en el sector Los Muros del barrio Buenos Aires de Lares, cuando un ingeniero de la Autoridad de Carreteras (ACT) sufri\u00f3 una ca\u00edda.<\/p>\n<p>De acuerdo con el narrativo polic\u00edaco, el perjudicado que fue identificado como Arnaldo Mercado P\u00e9rez, de 50 a\u00f1os, un ingeniero de esa corporaci\u00f3n p\u00fablica.<\/p><div class=\"notic-content-middle\" id=\"notic-3439952223\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Se alega que \u00e9ste se encontraba inspeccionando el puente y mientras bajaba por unas escaleras, se cay\u00f3 unos 20 pies de profundidad, en un \u00e1rea pedregosa. El ingeniero Mercado P\u00e9rez recibi\u00f3 los primeros auxilios en el lugar y fue transportado al Coliseo Manuel V\u00e9lez, donde una ambulancia a\u00e9rea lo traslad\u00f3 al Centro M\u00e9dico de R\u00edo Piedras.<\/p>\n<p>No se inform\u00f3 sobre su condici\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un incidente desgraciado se report\u00f3 a las 10:35 de la ma\u00f1ana del jueves en un puente localizado en el kil\u00f3metro 52.1, de la carretera 128, en el sector Los Muros del barrio Buenos Aires de Lares, cuando un ingeniero de la Autoridad de Carreteras (ACT) sufri\u00f3 una ca\u00edda. De acuerdo con el narrativo polic\u00edaco, el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":865054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-107483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/107483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=107483"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/107483\/revisions"}],"predecessor-version":[{"id":865110,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/107483\/revisions\/865110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/865054"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=107483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=107483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=107483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}