{"id":105768,"date":"2017-11-04T16:18:08","date_gmt":"2017-11-04T20:18:08","guid":{"rendered":"http:\/\/www.noticel.com\/el-tiempo\/huracanes\/mundo\/top-stories\/20171104\/islas-virgenes-britanicas-se-levantan-luego-del-embate-de-irma\/"},"modified":"2025-07-29T01:42:49","modified_gmt":"2025-07-29T01:42:49","slug":"islas-virgenes-britanicas-se-levantan-luego-del-embate-de-irma","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20171104\/islas-virgenes-britanicas-se-levantan-luego-del-embate-de-irma\/","title":{"rendered":"Islas V\u00edrgenes Brit\u00e1nicas se levantan luego del embate de Irma"},"content":{"rendered":"<p><i>Hab\u00edan sufrido un fuerte golpe tras paso de Irma<\/i><\/p>\n<p>A dos meses del devastador paso del hurac\u00e1n Irma, las Islas V\u00edrgenes Brit\u00e1nicas abren sus puertas nuevamente a los turistas e invitan a los que salieron a regresar.<\/p>\n<p>&#8216;Las IVB est\u00e1n abiertas para negocios&#8217;, expres\u00f3 uno de los capitanes de las compa\u00f1\u00edas de bote de la isla Tortola.<\/p>\n<p>En el video publicado en la cuenta de Facebook de Virgin Motor Yachts, otros residentes de la isla presentan la recuperaci\u00f3n que han tenido, la cual incluye el restablecimiento de los servicios de internet y se\u00f1ales de telecomunicaci\u00f3n.<\/p>\n<p>&#8216;Estamos en el camino r\u00e1pido a la recuperaci\u00f3n&#8217;, expuso uno de los representantes de las telecomunicaciones en la isla, quien no fue identificado en el video.<\/p>\n<p>De igual forma, uno de los pilotos de la aerol\u00ednea comercial InterCaribbean dijo que los vuelos comerciales han resumido.<\/p>\n<p>&#8216;Tenemos 6 tiendas abiertos y bien abastecidos&#8217;, afirm\u00f3 el gerente de uno de los supermercados en las islas.<\/p>\n<p>&#8216;Los ba\u00f1os a\u00fan son bellos&#8217;, enfatizaron un grupo de mujeres en referencia a los ba\u00f1os en la isla de Virgen Gorda, una de las que sufri\u00f3 mayor devastaci\u00f3n.<\/p>\n<p>Puede ver el video aqu\u00ed:<\/p>\n<p>{&#8216;author_name&#8217;:&#8217;Virgin Motor Yachts&#8217;,&#8217;author_url&#8217;:&#8217;https:\/\/www.facebook.com\/virginmotoryachts\/&#8217;,&#8217;provider_url&#8217;:&#8217;https:\/\/www.facebook.com&#8217;,&#8217;provider_name&#8217;:&#8217;Facebook&#8217;,&#8217;success&#8217;:true,&#8217;height&#8217;:281,&#8217;html&#8217;:&#8217;lt;div id=&#8217;fb-root&#8217;gt;lt;\/divgt;nlt;scriptgt;(function(d, s, id) {n var js, fjs = d.getElementsByTagName(s)[0];n if (d.getElementById(id)) return;n js = d.createElement(s); js.id = id;n js.src = &#8216;https:\/\/connect.facebook.net\/en_US\/sdk.js#xfbml=1&amp;version=v2.10&#8217;;n fjs.parentNode.insertBefore(js, fjs);n}(document, &#8216;script&#8217;, &#8216;facebook-jssdk&#8217;));lt;\/scriptgt;lt;div class=&#8217;fb-video&#8217; data-href=&#8217;https:\/\/www.facebook.com\/virginmotoryachts\/videos\/10159442098500117\/&#8217;gt;lt;blockquote cite=&#8217;https:\/\/www.facebook.com\/virginmotoryachts\/videos\/10159442098500117\/&#8217; class=&#8217;fb-xfbml-parse-ignore&#8217;gt;lt;a href=&#8217;https:\/\/www.facebook.com\/virginmotoryachts\/videos\/10159442098500117\/&#8217;gt;BVI is Open for Businesslt;\/agt;lt;pgt; BVI is officially OPEN for BUSINESS!!!  It&#8217;s Nov 1st, and tourists and visitors are all welcome back to BVI! Check out and SHARE this amazing video showing our beautiful islands, with ALL FOOTAGE shot POST IRMA. Huge thank you to our friends Alex England, Monday Never and Aristocat Charters for their help making this incredible video! #BVIStrong lt;\/pgt;Posted by lt;a href=&#8217;https:\/\/www.facebook.com\/virginmotoryachts\/&#8217;gt;Virgin Motor Yachtslt;\/agt; on Wednesday, November 1, 2017lt;\/blockquotegt;lt;\/divgt;&#8217;,&#8217;type&#8217;:&#8217;video&#8217;,&#8217;version&#8217;:&#8217;1.0&#8242;,&#8217;url&#8217;:&#8217;https:\/\/www.facebook.com\/virginmotoryachts\/videos\/10159442098500117\/&#8217;,&#8217;width&#8217;:500}<\/p>","protected":false},"excerpt":{"rendered":"<p>Hab\u00edan sufrido un fuerte golpe tras paso de Irma A dos meses del devastador paso del hurac\u00e1n Irma, las Islas V\u00edrgenes Brit\u00e1nicas abren sus puertas nuevamente a los turistas e invitan a los que salieron a regresar. &#8216;Las IVB est\u00e1n abiertas para negocios&#8217;, expres\u00f3 uno de los capitanes de las compa\u00f1\u00edas de bote de la [&hellip;]<\/p>","protected":false},"author":0,"featured_media":604728,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[18,19,17],"tags":[],"class_list":["post-105768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-tiempo","category-huracanes","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/105768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=105768"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/105768\/revisions"}],"predecessor-version":[{"id":604754,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/105768\/revisions\/604754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/604728"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=105768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=105768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=105768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}