{"id":104792,"date":"2015-12-17T19:02:00","date_gmt":"2015-12-17T23:02:00","guid":{"rendered":"http:\/\/www.noticel.com\/vida\/20151217\/diario-del-vaticano-critica-saga-de-star-wars-por-chabacana\/"},"modified":"2025-07-29T22:25:12","modified_gmt":"2025-07-29T22:25:12","slug":"diario-del-vaticano-critica-saga-de-star-wars-por-chabacana","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/vida-y-bienestar\/20151217\/diario-del-vaticano-critica-saga-de-star-wars-por-chabacana\/","title":{"rendered":"Diario del Vaticano critica saga de &#8216;Star Wars&#8217; por &#8216;chabacana&#8217;"},"content":{"rendered":"<p>El peri\u00f3dico del Vaticano, L&#8217;Osservatore Romano, public\u00f3 el jueves una cr\u00edtica sobre la septima y \u00faltima entrega de la saga &#8216;Star Wars&#8217;, &#8216;The Force Awakens&#8217;, una cinta que tild\u00f3 de decepcionante, confusa, sosa y chabacana.<\/p>\n<p>El diario public\u00f3 una cr\u00edtica sin firmar titulada &#8216;Confuso y descentrado&#8217; en la que se\u00f1ala que &#8216;el \u00fanico m\u00e9rito&#8217; de la pel\u00edcula es &#8216;demostrar, por comparaci\u00f3n, lo elegante, equilibrada y sobre todo apropiada que era la direcci\u00f3n de los cap\u00edtulos precedentes&#8217;.<\/p>\n<p>\u00bbThe Force Awakens&#8217; parece m\u00e1s un reinicio que una secuela. No un reinicio con clase, como pueda ser el &#8216;Batman&#8217; de (Christopher) Nolan, sino una actualizaci\u00f3n doblegada a las modas del momento y a un p\u00fablico m\u00e1s acostumbrado a las pantallas del ordenador que a las salas cinematogr\u00e1ficas&#8217;, reza la nota.<\/p>\n<p>Asimismo critic\u00f3 la direcci\u00f3n de J.J. Abrams, &#8216;modulada al m\u00e1s descuidado cine de acci\u00f3n actual, por el efecto contiguo al mundo del videojuego&#8217;.<\/p>\n<p>&#8216;En las secuencias de acci\u00f3n pura y simple, crucial, es m\u00e1s bien eficaz, pero por lo dem\u00e1s, consiste en una grabaci\u00f3n comprometida con un dinamismo gratuito y el abuso de los primeros planos que corroen gradualmente la fuerza de los personales y la envergadura \u00e9pica de la historia&#8217;, se\u00f1ala L&#8217;Osservatore.<\/p><div class=\"notic-content-middle\" id=\"notic-3426232655\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Tampoco es &#8216;convincente&#8217; para el diario de la Santa Sede &#8216;la elecci\u00f3n tan anunciada de volver a las ambientaciones reales&#8217; ya que, seg\u00fan apunt\u00f3, &#8216;son a menudo an\u00f3nimas y de escaso valor dram\u00e1tico&#8217;.<\/p>\n<p>Pero el aspecto en el que la cinta falla de &#8216;un modo m\u00e1s clamoroso&#8217; es en &#8216;la representaci\u00f3n del mal, en el dise\u00f1o de los personajes malos&#8217;.<\/p>\n<p>&#8216;El hom\u00f3logo de Darth Vader, Kylo Ren, lleva una m\u00e1scara evidentemente con la sola raz\u00f3n de emular a su predecesor. Mientras, la figura que deber\u00eda sustituir al emperador Palpatine como encarnaci\u00f3n del mal supremo representa el m\u00e1s grave defecto del filme&#8217;, critica.<\/p>\n<p>En definitiva, la \u00faltima entrega de esta hist\u00f3rica saga de ciencia ficci\u00f3n creada en 1977 por George Lucas es para L&#8217;Osservatore Romano &#8216;el resultado m\u00e1s soso y hortera que se pod\u00eda obtener&#8217;.<\/p>","protected":false},"excerpt":{"rendered":"<p>El peri\u00f3dico del Vaticano, L&#8217;Osservatore Romano, public\u00f3 el jueves una cr\u00edtica sobre la septima y \u00faltima entrega de la saga &#8216;Star Wars&#8217;, &#8216;The Force Awakens&#8217;, una cinta que tild\u00f3 de decepcionante, confusa, sosa y chabacana. El diario public\u00f3 una cr\u00edtica sin firmar titulada &#8216;Confuso y descentrado&#8217; en la que se\u00f1ala que &#8216;el \u00fanico m\u00e9rito&#8217; de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":611912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-104792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/104792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=104792"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/104792\/revisions"}],"predecessor-version":[{"id":611928,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/104792\/revisions\/611928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/611912"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=104792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=104792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=104792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}