{"id":102896,"date":"2012-04-20T06:54:00","date_gmt":"2012-04-20T10:54:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20120420\/12-arrestados-por-drogas-en-aguas-buenas-y-caguas\/"},"modified":"2025-07-24T04:15:45","modified_gmt":"2025-07-24T04:15:45","slug":"12-arrestados-por-drogas-en-aguas-buenas-y-caguas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20120420\/12-arrestados-por-drogas-en-aguas-buenas-y-caguas\/","title":{"rendered":"12 arrestados por drogas en Aguas Buenas y Caguas"},"content":{"rendered":"<p>El comandante Emilio Ramos Bracetti, director de la regi\u00f3n de Caguas, de la Polic\u00eda, inform\u00f3 en la ma\u00f1ana del viernes sobre el arresto de 12 personas por violaciones a las Leyes de Drogas y Armas en Aguas Buenas y Caguas.<\/p>\n<p>Seg\u00fan el informe preliminar, durante varios allanamientos fueron arrestadas 12 personas as\u00ed como la ocupaci\u00f3n de una pistola Miltenium, modelo PT-145, serie NVH-45650, ocho balas calibre .45, 1 bolsa de marihuana, 25 c\u00e1psulas de &#8216;crack&#8217; y 510.00 d\u00f3lares en efectivo.<\/p><div class=\"notic-content-middle\" id=\"notic-3504128659\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Sabemos que los ciudadanos de nuestra isla merecen un lugar seguro y la Polic\u00eda de Puerto Rico tiene el compromiso de erradicar los actos delictivos que afectan nuestro pa\u00eds, por lo que no nos detendremos hasta lograrlo. Para ello, la ciudadan\u00eda es parte importante en la lucha contra el crimen. Estamos enfocados en llevar un plan de seguimiento y consistencia, para disminuir los males sociales que nos aquejan y as\u00ed cumplir nuestra misi\u00f3n que va mas all\u00e1 del deber, de velar vidas y propiedades&#8217;, indic\u00f3 el comandante Ramos Bracetti en comunicado de prensa.<\/p>\n<p>Las intervenciones estuvieron a cargo de las Unidades Especializadas de la Regi\u00f3n de Caguas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El comandante Emilio Ramos Bracetti, director de la regi\u00f3n de Caguas, de la Polic\u00eda, inform\u00f3 en la ma\u00f1ana del viernes sobre el arresto de 12 personas por violaciones a las Leyes de Drogas y Armas en Aguas Buenas y Caguas. Seg\u00fan el informe preliminar, durante varios allanamientos fueron arrestadas 12 personas as\u00ed como la ocupaci\u00f3n [&hellip;]<\/p>","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-102896","post","type-post","status-publish","format-standard","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=102896"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102896\/revisions"}],"predecessor-version":[{"id":568213,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102896\/revisions\/568213"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=102896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=102896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=102896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}