{"id":102804,"date":"2012-10-09T19:46:49","date_gmt":"2012-10-09T23:46:49","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20121009\/encuentran-su-norte-en-el-drug-court\/"},"modified":"2025-08-25T08:51:44","modified_gmt":"2025-08-25T08:51:44","slug":"encuentran-su-norte-en-el-drug-court","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20121009\/encuentran-su-norte-en-el-drug-court\/","title":{"rendered":"Encuentran su norte en el &#8216;Drug Court&#8217;"},"content":{"rendered":"<p>Un d\u00eda, hace mucho tiempo, cuando andaba en los pasos de la droga, Bryan Joel Mart\u00ednez se encontr\u00f3 en un sem\u00e1foro a su maestro de lucha del Club Esparta, de Puerto Nuevo. Hoy, lo volvi\u00f3 a ver, ambos con grandes logros alcanzados, y viviendo un presente esperanzador y un futuro que luce bastante brillante.<\/p>\n<p>Al igual que nueve colegas ex delincuentes, Bryan Joel se dio cita en la tarde del jueves a la Sala 1106 de los jueces Wanda Cruz Ayala y Harry Massanett en el Tribunal de San Juan. All\u00ed, a los 10 varones se les archivaron hoy sus delitos tras completar sus procedimientos en el programa &#8216;Drug Court&#8217; de la Regi\u00f3n de San Juan que supervisa la Oficina de Administraci\u00f3n de Los Tribunales, un programa que apuesta a la rehabilitaci\u00f3n de personas que violan leyes correspondientes a los art\u00edculos 404 de ley de sustancias controladas y el 3.6 de violencia dom\u00e9stica.<\/p>\n<p>El proceso se trata mediante vistas de seguimiento en salones especializados con jueces del circuito Superior, como Cruz Ayala y Massannett y es supervisado por la directora administrativa de la Oficina de Administraci\u00f3n de los Tribunales, SoniaIvetteV\u00e9lezCol\u00f3n.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"607997273\" embed-content-groupid=\"593030475\" embed-content-id=\"607997273\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2012\/10\/09\/drug_court_8081730_ver1.0_320_240.jpg\"\/><\/p>\n<p><em>La bienvenida a estuvo a cargo de la directora administrativa de la Oficina de Administraci\u00f3n de los Tribunales, Sonia Ivette V\u00e9lez Col\u00f3n. (Suministrada)<\/em><\/p>\n<p>Este programa trabaja sentencias de 18 meses hasta cinco a\u00f1os con 1300 participantes en las 10 regiones judiciales de Puerto Rico. La mayor\u00eda son primeros ofensores y la rehabilitaci\u00f3n se trabaja en conjunto con distintos centros preparados, como Hogar Crea, y otros albergues especializados. Se estima que, luego de completarse el proceso de rehabilitaci\u00f3n en elprogama&#8217;DrugCourt&#8217;, la reincidencia entre los acusados no llega al 10%.<\/p>\n<p>En esta tarde, todos los acusados rehabilitados ven\u00edan con casos por violaciones de sustancias controladas y sus derivados, como, por ejemplo, Bryan Joel, que a sus 23 a\u00f1os de edad afirma &#8216;haber estado bastante en la calle, aunque ahora est\u00e9 aqu\u00ed&#8217;. Para sorpresa de Bryan Joel, en esa sala tambi\u00e9n estaba hoy una figura de su pasado, cargando palabras de aliento y sosiego para esta nueva etapa de su vida. Se trataba de su ex maestro de lucha libre en el Club Esparta que alberga la escuela Gabriela Mistral de Puerto Nuevo, el medallista ol\u00edmpico, Jaime Espinal.<\/p>\n<p>&#8216;Me sorprend\u00ed cuando lo vi&#8217;, le dijo Bryan Joel a NotiCel. &#8216;\u00c9l fue mi maestro de lucha desde los nueve a\u00f1os hasta los 16. Y ahora es medallista. Yo lo hab\u00eda visto hace tiempo, pero es mejor verlo como estoy ahora&#8217;.<\/p>\n<p>Espinal record\u00f3 al joven. &#8216;!Ese colorao&#8217; era mi estudiante!&#8217;, expres\u00f3.<\/p>\n<p>&#8216;La \u00faltima vez que lo vi casi ni lo reconoc\u00ed. Me lo hab\u00eda encontrado hace varios a\u00f1os en una luz, yo en mi carro. Me dijo: \u2018Mistel, me busqu\u00e9 un caso&#8217;. Y para esa edad, d\u00f3nde \u00e9l se hab\u00eda criado, que era en el \u00e1rea de Puerto Nuevo, donde yo tambi\u00e9n me cri\u00e9, ven eso como si fuera algo positivo, como si fuera algo \u2018cool&#8217;, se creen los m\u00e1s malos si eso les pasa. No lo volv\u00ed a ver, pero me hab\u00eda quedado pensando en \u00e9l. Al verlo hoy me dio mucha alegr\u00eda, pues lo veo rehabilitado y listo para ser una persona de bien. Me alegro mucho por \u00e9l&#8217;, agreg\u00f3.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"607997616\" embed-content-groupid=\"593030475\" embed-content-id=\"607997616\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2012\/10\/09\/jantony_8081732_ver1.0_320_240.jpg\"\/><\/p>\n<p><em>El boxeador ol\u00edmpico Janthony Ortiz tambi\u00e9n particip\u00f3 de la ceremonia y brind\u00f3 un mensaje de superaci\u00f3n. (Suministrada)<\/em><\/p>\n<p>Espinal fue uno de los invitados especiales a la lectura de archivo de los casos deBryanJoely sus nueve compa\u00f1eras en lo que es considerado como la &#8216;graduaci\u00f3n&#8217; del programaDrugCourt. Tambi\u00e9n estuvieron de invitados en la sala 1106 el boxeador ol\u00edmpicoJantonyOrt\u00edzy el representante a la C\u00e1mara por el Partido Popular Democr\u00e1tico (PPD), JaimePerell\u00f3; ambos ofrecieron palabras de aliento a los j\u00f3venes.<\/p>\n<p>&#8216;Esto es bien diferente a lo que yo estoy acostumbrado. Ganar una medalla ol\u00edmpica no es algo normal y yo he sido subestimado\u2026 al igual que ustedes. Al igual que ustedes, tambi\u00e9n me ca\u00ed muchas veces y me volv\u00eda a levantar. Tuve muchas situaciones dif\u00edciles, desde los 16 a\u00f1os viv\u00ed s\u00f3lo. No fue f\u00e1cil. La gente piensa que la m\u00eda es una historia bonita, pero no tan bonita como ustedes, que hoy est\u00e1n logrando algo muy importante y muy grande para ustedes&#8217;, les dijo Espinal a los graduandos del programa &#8216;Drug Court&#8217;.<\/p><div class=\"notic-content-middle\" id=\"notic-1626003590\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>&#8216;Ahora, no se pueden dejar caer. Y a la gente que est\u00e1 del otro lado de ustedes, les digo que esto es de los dos lados, tienen que ayudarlos y darles la mano. La sociedad los quiere y los necesita. Que Dios los bendiga y sigan hacia adelante&#8217;, manifest\u00f3.<\/p>\n<p>No se qued\u00f3 corto Espinal al decir eso. Las historias de estos 10 graduandos reflejan el poder de voluntad de personas que no les ha tocado vivir en las mejores circunstancias, que han tropezado con el crimen y las drogas, que han resbalado a tutipl\u00e9n pero que han logrado reponerse.<\/p>\n<p>&#8216;Por ejemplo, muchos no lo saben, pero la familia de Bryan Joel somos nosotros, pues recientemente fue que pudo encontrar una t\u00eda pol\u00edtica que era su \u00fanica familia. Este programa lo ha ayudado mucho&#8217;, expres\u00f3 en medio de la vista de archivo de casos el juez Massannett.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"607997659\" embed-content-groupid=\"593030475\" embed-content-id=\"607997659\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2012\/10\/09\/jueces_8081734_ver1.0_320_240.jpg\"\/><\/p>\n<p><em>La vista de archivo y sobreseimiento fue presidida por los honorables Harry Massanety Wanda Cruz Ayala. (Suministrada)<\/em><\/p>\n<p>Es que en esa sala hab\u00edan espectaculares historias de vida. Por ejemplo, estaba el caso deRogelioAdornoD\u00e1vila, quien estuvo 26 a\u00f1osdeambulandopor las calles del \u00e1rea metropolitana y gracias al programa &#8216;DrugCourt&#8217; se ha podido recuperar, al punto de que reci\u00e9n se mud\u00f3 a un apartamento a todo dar en el complejo de vivienda Albergue El Para\u00edso.<\/p>\n<p>Y qu\u00e9 tal el ejemplo de Angel Ramos Rosario, un ex adicto que reci\u00e9n alcanz\u00f3 un grado en barber\u00eda, o Mario Oscar De Jes\u00fas Ocasio, quien mediante &#8216;Drug Court&#8217; pudo culminar un grado asociado en ciencias de enfermer\u00eda.<\/p>\n<p>O, por ejemplo, all\u00ed estaba tambi\u00e9n Angel Bristol Rivera, quien cambi\u00f3 el \u2018crack&#8217; por la reposter\u00eda; y Christian David D\u00edaz, quien mientras se rehabilitaba en &#8216;Drug Court&#8217; culmin\u00f3 \u2018suma cum laude&#8217; un bachillerato en antropolog\u00eda y considera estudiar leyes; y Rub\u00e9n Isaac Ort\u00edz, quien estudia para convertirse en \u2018chef&#8217; y poder montar un restaurant y una fundaci\u00f3n &#8216;para ayudar a estudiar a los j\u00f3venes que no tengan buen promedio acad\u00e9mica&#8217;. De hecho, fue este ultimo joven, el que la jueza Cruz Ayala bautiz\u00f3 como &#8216;el chef Rub\u00e9n&#8217;, quien confeccion\u00f3 la comida para la recepci\u00f3n de esta peculiar graduaci\u00f3n, la cual sucedi\u00f3 luego de la vista en un sal\u00f3n del segundo piso del Tribunal de San Juan.<\/p>\n<p>Entre los h\u00e9roes de estos j\u00f3venes, aparte de los dos jueces que supervisaron sus rehabilitaciones, estuvieron la abogada Mar\u00eda Soledad Miranda, de la Oficina de Asistencia Legal; la coordinadora del programa, Amneris S\u00e1nchez Vel\u00e1zquez; y el oficial de probatoria Alejandro Mart\u00ednez, quien explic\u00f3 a NotiCel que &#8216;esto se trata de justicia terap\u00e9utica, de rehabilitar ofreciendo las herramientas necesarias para evitar la reincidencia en vez de dar un enfoque completamente punitivo&#8217;. Estos tres ejemplares funcionarios p\u00fablicos, al igual que otros cuyos nombres se nos escapan, recibieron una ovaci\u00f3n de parte de los graduandos.<\/p>\n<p>&#8216;Esto es un ejemplo, a su m\u00e1xima expresi\u00f3n, del servicio p\u00fablico en toda su entrega&#8217;, resumi\u00f3 el representante Perell\u00f3 en alusi\u00f3n a los funcionarios del programa Drug Court y a los jueces Cruz Ayala y Massannett, que en la tarde de hoy parec\u00edan m\u00e1s padres orgullosos que miembros de la judicatura.<\/p>\n<p>Claro, los protagonistas de todo esto eran los muchachos que hoy regresaban a la sociedad con su r\u00e9cord limpio tras cumplir su rehabilitaci\u00f3n. Y all\u00ed iban ante el mundo, con la frente en alta, y apostando a que ahora la verdadera lucha ser\u00e1 para mantenerse al margen del peligro de las drogas. Si no, preg\u00fantenle al &#8216;chef Rub\u00e9n&#8217;.<\/p>\n<p>&#8216;Dice Paulo Coehlo que \u2018s\u00f3lo una cosa convierte en imposible un sue\u00f1o\u2026 el miedo a fracasar&#8217;. Creo en eso. Para m\u00ed, la vida es una escuela de la cuna a la tumba. Por cada bomba que explota hay millones de gestos que no hacen ruido. Nosotros nos levantamos. Y vamos a nosotros&#8217;, puntualiz\u00f3 el joven rehabilitado.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda, hace mucho tiempo, cuando andaba en los pasos de la droga, Bryan Joel Mart\u00ednez se encontr\u00f3 en un sem\u00e1foro a su maestro de lucha del Club Esparta, de Puerto Nuevo. Hoy, lo volvi\u00f3 a ver, ambos con grandes logros alcanzados, y viviendo un presente esperanzador y un futuro que luce bastante brillante. Al [&hellip;]<\/p>","protected":false},"author":0,"featured_media":909699,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-102804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=102804"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102804\/revisions"}],"predecessor-version":[{"id":909716,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102804\/revisions\/909716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/909699"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=102804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=102804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=102804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}