{"id":102340,"date":"2011-10-22T22:28:00","date_gmt":"2011-10-23T02:28:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20111022\/ico-zayas-pretende-radicar-el-miercoles\/"},"modified":"2025-08-28T21:48:07","modified_gmt":"2025-08-28T21:48:07","slug":"ico-zayas-pretende-radicar-el-miercoles","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20111022\/ico-zayas-pretende-radicar-el-miercoles\/","title":{"rendered":"&#8216;Ico&#8217; Zayas pretende radicar el mi\u00e9rcoles"},"content":{"rendered":"<p>Ponce &#8211; El ex alcalde de Ponce, Francisco &#8216;Ico&#8217; Zayas Seijo, oficializ\u00f3 su candidatura a la alcald\u00eda de la ciudad se\u00f1orial y anunci\u00f3 que radicar\u00e1 el pr\u00f3ximo mi\u00e9rcoles los documentos solicitados por el Partido Popular Democr\u00e1tico (PPD) para dicho puesto.<\/p>\n<p>&#8216;Yo tengo todos los papeles requisitos para el alcalde\u2026Yo espero para el mi\u00e9rcoles que viene tener todo listo.&#8217;, explic\u00f3 el l\u00edder popular.<\/p>\n<p>El ex alcalde asegur\u00f3 que ante la inacci\u00f3n del PPD en Ponce, y ante la &#8216;falta de obra&#8217; de la alcaldesa Mar\u00eda &#8216;Mayita&#8217; Mel\u00e9ndez, decidi\u00f3 salir de su retiro y retomar su carrera pol\u00edtica.<\/p>\n<p>&#8216;El PPD lo que tiene es un silencio sepulcral en Ponce, y cu\u00e1l ha sido la obra de &#8216;Mayita&#8217;, ante esto tengo que regresar&#8217;, se\u00f1al\u00f3 en entrevista radial (WPAB).<\/p>","protected":false},"excerpt":{"rendered":"<p>Ponce &#8211; El ex alcalde de Ponce, Francisco &#8216;Ico&#8217; Zayas Seijo, oficializ\u00f3 su candidatura a la alcald\u00eda de la ciudad se\u00f1orial y anunci\u00f3 que radicar\u00e1 el pr\u00f3ximo mi\u00e9rcoles los documentos solicitados por el Partido Popular Democr\u00e1tico (PPD) para dicho puesto. &#8216;Yo tengo todos los papeles requisitos para el alcalde\u2026Yo espero para el mi\u00e9rcoles que viene [&hellip;]<\/p>","protected":false},"author":0,"featured_media":928157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-102340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=102340"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102340\/revisions"}],"predecessor-version":[{"id":928193,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102340\/revisions\/928193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/928157"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=102340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=102340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=102340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}