{"id":102260,"date":"2014-11-07T18:50:39","date_gmt":"2014-11-07T22:50:39","guid":{"rendered":"http:\/\/www.noticel.com\/hack\/20141107\/facebook-no-fue-creado-para-ser-cool-ni-conectar-con-las-chicas\/"},"modified":"2025-08-17T16:57:27","modified_gmt":"2025-08-17T16:57:27","slug":"facebook-no-fue-creado-para-ser-cool-ni-conectar-con-las-chicas","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/mas\/otros\/20141107\/facebook-no-fue-creado-para-ser-cool-ni-conectar-con-las-chicas\/","title":{"rendered":"Facebook no fue creado para ser &#8216;cool&#8217; ni conectar con las chicas"},"content":{"rendered":"<p>En sus inicios, el gigante de las redes sociales, Facebook, realizaba sesiones de preguntas y respuestas entre los empleados y su fundador, Mark Zuckerberg. Este jueves, la pr\u00e1ctica se retom\u00f3 junto al Principal Ejecutivo y otros altos funcionarios de la red y el p\u00fablico general.<\/p>\n<p>Seg\u00fan rese\u00f1ara la revista <a href=\"http:\/\/time.com\/3568439\/mark-zuckerberg-facebook-interview\/\" target=\"_blank\">Time<\/a>, Zuckerberg admiti\u00f3 que su prop\u00f3sito nunca fue que Facebook fuera \u2018cool&#8217;, sino una manera de facilitar la conexi\u00f3n entre las personas, hasta llegar al punto de tornarse algo rutinario y confiable, como encender un interruptor o abrir la llave de agua.<\/p>\n<p>De otro lado, indic\u00f3 que el usuario promedio apenas ve 100 de 1,500 historias del muro de noticias (newsfeed), pero espera que con el tiempo se convierta en un peri\u00f3dico personalizado para cada cual, aunque muchas empresas se quejen de que sus p\u00e1ginas alcanzan cada vez menos p\u00fablico. Adem\u00e1s, Zuckerberg aprovech\u00f3 para recordar sus planes de proveer internet a trav\u00e9s de aviones no tripulados, o drones, matenidos por energ\u00eda solar.<\/p><div class=\"notic-content-middle\" id=\"notic-3046100950\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.facebook.com\/magnapremiumlager\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"106-2026-21_Magna Verano Display v.02\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30092558\/106-2026-21_Magna-Verano-Display-v.02_970x90-2-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>En temas m\u00e1s amenos, el Fundador de Facebook admiti\u00f3 que su afici\u00f3n por las camisetas grises se debe a que prefiere no estar tan atento a lo que usa porque siente una mayor responsabilidad, y hasta suerte, de servir a m\u00e1s de un bill\u00f3n de personas con la red social. Asimismo, admiti\u00f3 que la pel\u00edcula &#8216;Social Network&#8217; fue un tanto dolorosa pues la intenci\u00f3n de crear Facebook no fue para \u2018conectar&#8217; con el sexo opuesto sino con los seres queridos.<\/p>\n<p>De igual modo, indic\u00f3 que no le agrada que lo asocien \u00fanicamente a \u00e9l con la popular red social pues no es la \u00fanica persona detr\u00e1s del producto, y a diario se rodea de un equipo profesional que lo apoya.<\/p>","protected":false},"excerpt":{"rendered":"<p>En sus inicios, el gigante de las redes sociales, Facebook, realizaba sesiones de preguntas y respuestas entre los empleados y su fundador, Mark Zuckerberg. Este jueves, la pr\u00e1ctica se retom\u00f3 junto al Principal Ejecutivo y otros altos funcionarios de la red y el p\u00fablico general. Seg\u00fan rese\u00f1ara la revista Time, Zuckerberg admiti\u00f3 que su prop\u00f3sito [&hellip;]<\/p>","protected":false},"author":0,"featured_media":860359,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-102260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=102260"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102260\/revisions"}],"predecessor-version":[{"id":860411,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/102260\/revisions\/860411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/860359"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=102260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=102260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=102260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}