{"id":1017054,"date":"2026-08-07T13:59:48","date_gmt":"2026-08-07T17:59:48","guid":{"rendered":""},"modified":"2026-08-07T14:03:46","modified_gmt":"2026-08-07T18:03:46","slug":"la-aaa-inicia-gestiones-para-dragado-en-seco-de-carraizo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20260807\/la-aaa-inicia-gestiones-para-dragado-en-seco-de-carraizo\/","title":{"rendered":"La AAA inicia gestiones para dragado en seco de Carra\u00edzo"},"content":{"rendered":"<p>La Autoridad de Acueductos y Alcantarillados (AAA) comenz\u00f3 el viernes la planificaci\u00f3n y coordinaci\u00f3n de permisos para realizar un dragado en seco en las orillas del embalse Carra\u00edzo, con una proyecci\u00f3n preliminar de remover 500,000 yardas c\u00fabicas o m\u00e1s de material para aumentar su capacidad de almacenamiento.<\/p>\n\n\n\n<p>El presidente ejecutivo de la AAA, Luis Reinaldo Gonz\u00e1lez Delgado, aclar\u00f3 que todav\u00eda no existe una fecha para el comienzo de la remoci\u00f3n f\u00edsica del material porque primero deben definir el alcance de los trabajos, los accesos para la maquinaria y los requisitos de permisos.<\/p>\n\n\n\n<p>\u201cNo tenemos fecha de comienzo porque primero queremos cuadrar lo que es la permisolog\u00eda. De ah\u00ed hacemos entonces lo que es el \u00e1mbito de trabajo, que es lo que estamos desarrollando en conjunto\u201d, expres\u00f3 Gonz\u00e1lez Delgado a preguntas de la prensa.<\/p>\n\n\n\n<p>El secretario del Departamento de Recursos Naturales y Ambientales (DRNA), Waldemar Quiles, sostuvo que la planificaci\u00f3n y la evaluaci\u00f3n de permisos forman parte del proyecto, aunque todav\u00eda no haya maquinaria removiendo material.<\/p>\n\n\n\n<p>\u201cEl proyecto ya comenz\u00f3 porque la planificaci\u00f3n es parte del proyecto, la permisolog\u00eda es parte del proyecto. La parte f\u00edsica de tener maquinaria es una fase dentro del proyecto\u201d, indic\u00f3 Quiles.<\/p>\n\n\n\n<p>Los trabajos aprovechar\u00edan las \u00e1reas de la ribera que quedaron expuestas por el descenso del embalse. Gonz\u00e1lez Delgado explic\u00f3 que la AAA toma como referencia una intervenci\u00f3n realizada en La Plata durante 2015, cuando se removieron m\u00e1s de 500,000 yardas c\u00fabicas.<\/p>\n\n\n\n<p>\u201cAqu\u00ed tenemos una zona amplia y estamos esperando que sean 500,000 yardas c\u00fabicas o m\u00e1s las que podamos retirar y ganar en espacio en t\u00e9rminos de lo que es la orilla\u201d, sostuvo.<\/p>\n\n\n\n<p>La iniciativa ser\u00eda distinta al dragado que concluy\u00f3 en marzo en el centro del embalse. Seg\u00fan Gonz\u00e1lez Delgado, aquel proyecto se concentr\u00f3 en el curso principal del agua y removi\u00f3 material del fondo mediante una draga, mientras el trabajo propuesto ahora utilizar\u00eda maquinaria desde las \u00e1reas secas de la ribera.<\/p>\n\n\n\n<p>El funcionario explic\u00f3 que esas zonas no pod\u00edan trabajarse durante el dragado anterior porque permanec\u00edan bajo agua. El descenso provocado por la sequ\u00eda permite ahora acceder al terreno desde la orilla.<\/p><div class=\"notic-content-middle\" id=\"notic-360566575\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>Adem\u00e1s del dragado en seco, la AAA planifica remover escombros acumulados frente a las tomas de agua de la represa. La preocupaci\u00f3n aumenta a medida que baja el nivel de Carra\u00edzo porque las obstrucciones pueden limitar la entrada de agua hacia la Planta de Filtros Sergio Cuevas.<\/p>\n\n\n\n<p>\u201cTenemos obstrucci\u00f3n en lo que son las \u00e1reas de las parrillas para poder tener abasto de agua, sobre todo cuando seguimos descendiendo. La parte cr\u00edtica es que, si seguimos descendiendo en el nivel, tengamos que tomar el agua mucho m\u00e1s profunda y que no podamos tener entrada de agua suficiente\u201d, explic\u00f3 Gonz\u00e1lez Delgado.<\/p>\n\n\n\n<p>Quiles precis\u00f3 que en las tomas se trata de una limpieza de escombros, no de dragado de sedimentos. Entre el material acumulado mencion\u00f3 bamb\u00fa, troncos, vegetaci\u00f3n y basura que llega al embalse a trav\u00e9s de los r\u00edos.<\/p>\n\n\n\n<p>El secretario del DRNA indic\u00f3 que la agencia orient\u00f3 a la AAA sobre c\u00f3mo ejecutar los trabajos desde terreno seco sin entrar con maquinaria al agua, lo que podr\u00eda evitar un proceso de permisos con el Cuerpo de Ingenieros de Estados Unidos. Se\u00f1al\u00f3 que solicitar uno de esos permisos podr\u00eda tomar al menos 60 d\u00edas.<\/p>\n\n\n\n<p>Mientras contin\u00faan las gestiones, la AAA mantiene el plan de interrupciones programadas para los abonados que dependen de Carra\u00edzo. Gonz\u00e1lez Delgado advirti\u00f3 que, si no llueve y el nivel sigue descendiendo, podr\u00edan ser necesarias medidas adicionales para preservar el abasto.<\/p>\n\n\n\n<p>Record\u00f3 que durante sequ\u00edas anteriores hubo periodos de hasta tres d\u00edas sin servicio y explic\u00f3 que la AAA procura mantener el nivel de Carra\u00edzo por encima de los 30 metros, donde se encuentra la \u00faltima entrada disponible para captar agua.<\/p>\n\n\n\n<p>\u201cSi no tenemos lluvia y los niveles del embalse siguen bajando, hay que tomar determinaciones para poder salvaguardar el abasto de agua y no caer en una situaci\u00f3n peor a la que estamos ahora mismo experimentando\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>La AAA mantiene, adem\u00e1s, al embalse La Plata bajo observaci\u00f3n y aplica ajustes operacionales para prolongar su reserva sin implantar por el momento un plan de interrupciones programadas. Entre las medidas est\u00e1n la operaci\u00f3n de v\u00e1lvulas, la reducci\u00f3n de presi\u00f3n y cambios en el manejo de las reservas.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Autoridad de Acueductos y Alcantarillados (AAA) comenz\u00f3 el viernes la planificaci\u00f3n y coordinaci\u00f3n de permisos para realizar un dragado en seco en las orillas del embalse Carra\u00edzo, con una proyecci\u00f3n preliminar de remover 500,000 yardas c\u00fabicas o m\u00e1s de material para aumentar su capacidad de almacenamiento. El presidente ejecutivo de la AAA, Luis Reinaldo [&hellip;]<\/p>","protected":false},"author":101,"featured_media":1017055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3,2],"tags":[136,4020,3724],"class_list":["post-1017054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","category-ultima-hora","tag-aaa","tag-carraizo","tag-dragado"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1017054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1017054"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1017054\/revisions"}],"predecessor-version":[{"id":1017056,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1017054\/revisions\/1017056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1017055"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1017054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1017054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1017054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}