{"id":1017026,"date":"2026-08-07T12:09:14","date_gmt":"2026-08-07T16:09:14","guid":{"rendered":""},"modified":"2026-08-07T12:21:25","modified_gmt":"2026-08-07T16:21:25","slug":"edward-oneill-achaca-al-convicto-angel-perez-irregularidades-detectadas-por-la-contralora","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20260807\/edward-oneill-achaca-al-convicto-angel-perez-irregularidades-detectadas-por-la-contralora\/","title":{"rendered":"Edward O&#8217;Neill achaca al convicto \u00c1ngel P\u00e9rez irregularidades detectadas por la Contralora"},"content":{"rendered":"<p>El Municipio Aut\u00f3nomo de Guaynabo sostuvo hoy que los se\u00f1alamientos contenidos en el reciente informe de la Oficina del Contralor de Puerto Rico sobre contrataci\u00f3n de obras, procesos de subasta y pagos indebidos\u00a0se originaron bajo la administraci\u00f3n del exalcalde \u00c1ngel P\u00e9rez Otero, y que varias de esas situaciones fueron identificadas desde el proceso de transici\u00f3n por la administraci\u00f3n entrante del alcalde Edward A. O\u2019Neill Rosa.<\/p>\n\n\n\n<p>El informe de la Contralora no hace es distinci\u00f3n y la expresi\u00f3n p\u00fablica del Municipio de Guaynabo surge luego de la publicaci\u00f3n de la auditor\u00eda.<\/p>\n\n\n\n<p>El informe rese\u00f1ado p\u00fablicamente examina operaciones municipales entre el 1 de enero de 2021 y el 30 de junio de 2024 y se\u00f1ala, entre otros asuntos, obras contratadas mediante enmiendas sin los procesos requeridos, pagos indebidos y deficiencias relacionadas con fianzas y procedimientos de contrataci\u00f3n.&nbsp;No obstante, la propia contestaci\u00f3n sometida por el Municipio a la Oficina del Contralor establece que algunas de las contrataciones examinadas se remontan incluso a 2019 y que, al asumir el cargo en enero de 2022, la nueva administraci\u00f3n identific\u00f3 la pr\u00e1ctica relacionada con proyectos contratados por costos unitarios mediante \u00f3rdenes de trabajo.&nbsp;<\/p>\n\n\n\n<p>El alcalde O\u2019Neill Rosa enfatiz\u00f3 que resulta indispensable establecer con claridad la cronolog\u00eda de los hechos para evitar que se atribuyan a su administraci\u00f3n pr\u00e1cticas que fueron heredadas de la administraci\u00f3n de P\u00e9rez Otero y que, precisamente, comenzaron a ser atendidas y corregidas tras su llegada a la Alcald\u00eda.<\/p>\n\n\n\n<p>\u201cEstos hallazgos no son producto de pr\u00e1cticas establecidas por nuestra administraci\u00f3n. Por el contrario, fueron situaciones que comenzamos a identificar desde el proceso de transici\u00f3n y que hemos atendido con responsabilidad, transparencia y firmeza. Desde que asumimos la administraci\u00f3n municipal hemos sido rigurosos en el manejo de los fondos p\u00fablicos, en los procesos de subasta, contrataci\u00f3n y compras, y en toda gesti\u00f3n que comprometa recursos del pueblo de Guaynabo. Aqu\u00ed no hemos mirado hacia otro lado: donde se ha identificado una irregularidad, hemos actuado y continuaremos actuando\u201d, expres\u00f3 O\u2019Neill Rosa en declaraciones escritas.<\/p>\n\n\n\n<p>Durante el proceso de transici\u00f3n entre ambas administraciones ya se hab\u00eda se\u00f1alado oposici\u00f3n a algunas de estas pr\u00e1cticas por entenderlas contrarias a la ley. La contestaci\u00f3n municipal al Contralor establece espec\u00edficamente que la administraci\u00f3n de O\u2019Neill procedi\u00f3 a\u00a0descontinuar inmediatamente la pr\u00e1ctica de contrataci\u00f3n por costos unitarios mediante \u00f3rdenes de trabajo\u00a0que hab\u00eda sido adoptada durante la administraci\u00f3n anterior.\u00a0Asimismo, respecto a otro de los proyectos examinados, el Municipio consign\u00f3 que la situaci\u00f3n hab\u00eda sido se\u00f1alada durante el proceso de transici\u00f3n y que la administraci\u00f3n entrante manifest\u00f3 su total oposici\u00f3n a ese procedimiento.\u00a0<\/p>\n\n\n\n<p>El proceso de transici\u00f3n entrante fue presidido por el CPA Manuel D\u00edaz Salda\u00f1a y permiti\u00f3 identificar situaciones administrativas y fiscales que posteriormente fueron objeto de evaluaci\u00f3n y seguimiento, dice el comunicado de Guaynabo. A ello se sum\u00f3 el trabajo de la\u00a0Oficina de Auditor\u00eda Interna del Municipio, cuyos an\u00e1lisis fueron compartidos y discutidos con los auditores de la Oficina del Contralor durante el proceso de fiscalizaci\u00f3n.<\/p>\n\n\n\n<p>Como resultado de esas revisiones, el Municipio no se limit\u00f3 a identificar las situaciones, sino que tom\u00f3 acciones concretas. En dos de los casos relacionados con pagos cuestionados,\u00a0ya existen reclamaciones judiciales dirigidas al recobro de la totalidad de las cantidades pagadas a los contratistas. La documentaci\u00f3n municipal establece que dichas acciones surgieron precisamente de evaluaciones realizadas por Auditor\u00eda Interna, que concluy\u00f3 que las contrataciones eran contrarias a derecho.\u00a0<\/p>\n\n\n\n<p>De igual manera, ante errores identificados en el c\u00f3mputo de determinadas partidas de construcci\u00f3n, Auditor\u00eda Interna detect\u00f3 la situaci\u00f3n y el importe correspondiente fue deducido de cantidades retenidas; en otras \u00f3rdenes de trabajo, las partidas han sido consideradas durante el proceso de liquidaci\u00f3n con el prop\u00f3sito de\u00a0recobrar lo pagado indebidamente.\u00a0<\/p>\n\n\n\n<p>La administraci\u00f3n municipal tambi\u00e9n fortaleci\u00f3 sus procedimientos de adquisici\u00f3n. Entre las medidas adoptadas figura un nuevo\u00a0Reglamento de Adquisiciones de Bienes y Servicios No Profesionales, que incorpora controles en el Portal de Subastas en L\u00ednea para impedir que los licitadores retiren o modifiquen ofertas despu\u00e9s de la fecha y hora l\u00edmite de radicaci\u00f3n.\u00a0<\/p>\n\n\n\n<p>Asimismo, en el caso se\u00f1alado sobre servicios profesionales de inspecci\u00f3n y supervisi\u00f3n de obras relacionados con una firma cuya situaci\u00f3n de licencia fue cuestionada, el propio Municipio inform\u00f3 al Contralor que el asunto hab\u00eda sido detectado por Auditor\u00eda Interna y que\u00a0se radic\u00f3 una demanda para procurar el recobro de la totalidad de lo pagado a la firma.\u00a0<\/p>\n\n\n\n<p>\u201cNuestra responsabilidad no termina identificando lo que estuvo mal. Nuestra responsabilidad es corregirlo, establecer controles para que no vuelva a ocurrir y, cuando corresponda, acudir a los tribunales o hacer los referidos pertinentes para proteger y recuperar los fondos p\u00fablicos. Eso es precisamente lo que hemos hecho\u201d, sostuvo el alcalde.<\/p>\n\n\n\n<p>O\u2019Neill Rosa a\u00f1adi\u00f3 que su administraci\u00f3n continuar\u00e1 colaborando plenamente con la Oficina del Contralor y con cualquier otra entidad fiscalizadora. De hecho, la contestaci\u00f3n oficial remitida al organismo fiscalizador el 2 de junio de 2025 incluy\u00f3 los comentarios del Municipio y las acciones correctivas tomadas hasta ese momento, adem\u00e1s de reiterar su disponibilidad para proporcionar cualquier informaci\u00f3n adicional requerida.&nbsp;<\/p>\n\n\n\n<p>El Municipio indic\u00f3 que, adem\u00e1s de las medidas administrativas y judiciales ya encaminadas,\u00a0se han realizado los referidos correspondientes relacionados con los hallazgos, mientras contin\u00faa fortaleciendo sus mecanismos internos de fiscalizaci\u00f3n y cumplimiento.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Municipio Aut\u00f3nomo de Guaynabo sostuvo hoy que los se\u00f1alamientos contenidos en el reciente informe de la Oficina del Contralor de Puerto Rico sobre contrataci\u00f3n de obras, procesos de subasta y pagos indebidos\u00a0se originaron bajo la administraci\u00f3n del exalcalde \u00c1ngel P\u00e9rez Otero, y que varias de esas situaciones fueron identificadas desde el proceso de transici\u00f3n [&hellip;]<\/p>","protected":false},"author":100,"featured_media":1000773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3,2],"tags":[5757,1152,458],"class_list":["post-1017026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","category-ultima-hora","tag-angel-perez","tag-contralora","tag-guaynabo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1017026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1017026"}],"version-history":[{"count":3,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1017026\/revisions"}],"predecessor-version":[{"id":1017031,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1017026\/revisions\/1017031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1000773"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1017026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1017026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1017026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}