{"id":1016895,"date":"2026-08-06T16:55:12","date_gmt":"2026-08-06T20:55:12","guid":{"rendered":""},"modified":"2026-08-06T18:03:57","modified_gmt":"2026-08-06T22:03:57","slug":"asmaticos-y-el-polvo-del-sahara","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/opiniones\/20260806\/asmaticos-y-el-polvo-del-sahara\/","title":{"rendered":"Asm\u00e1ticos y el polvo del Sahara"},"content":{"rendered":"<p>El polvo del Sahara, el humo de incendios y las altas temperaturas pueden desencadenar crisis respiratorias. \u00bfEst\u00e1 preparado para protegerse?<\/p>\n\n\n\n<p>En C\u00f3mo Vivir Saludable, Keila Narv\u00e1ez, coordinadora de la Unidad de Prevenci\u00f3n y Manejo del Asma del Departamento de Salud, comparte recomendaciones para prevenir complicaciones, reconocer se\u00f1ales de alerta y saber cu\u00e1ndo buscar ayuda.<\/p>\n\n\n\n<p>Vea la entrevista completa en nuestro canal de YouTube.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ep. 48 - Asm\u00e1ticos y el polvo del Sahara\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/CO5rJGdXYxQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>El polvo del Sahara, el humo de incendios y las altas temperaturas pueden desencadenar crisis respiratorias. \u00bfEst\u00e1 preparado para protegerse? En C\u00f3mo Vivir Saludable, Keila Narv\u00e1ez, coordinadora de la Unidad de Prevenci\u00f3n y Manejo del Asma del Departamento de Salud, comparte recomendaciones para prevenir complicaciones, reconocer se\u00f1ales de alerta y saber cu\u00e1ndo buscar ayuda. Vea [&hellip;]<\/p>","protected":false},"author":133,"featured_media":1016900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[48],"tags":[5906],"class_list":["post-1016895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones","tag-polvo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1016895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1016895"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1016895\/revisions"}],"predecessor-version":[{"id":1016908,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1016895\/revisions\/1016908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1016900"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1016895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1016895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1016895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}