{"id":1016815,"date":"2026-08-06T09:36:21","date_gmt":"2026-08-06T13:36:21","guid":{"rendered":""},"modified":"2026-08-06T09:41:23","modified_gmt":"2026-08-06T13:41:23","slug":"sequia-extrema-alcanza-el-litoral-sur-de-puerto-rico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20260806\/sequia-extrema-alcanza-el-litoral-sur-de-puerto-rico\/","title":{"rendered":"Sequ\u00eda extrema alcanza el litoral sur de Puerto Rico"},"content":{"rendered":"<p>El litoral sur de Puerto Rico entr\u00f3 por primera vez este a\u00f1o en la categor\u00eda de sequ\u00eda extrema, mientras m\u00e1s de dos terceras partes de la isla permanecen bajo alg\u00fan nivel de sequ\u00eda, seg\u00fan la actualizaci\u00f3n semanal del Monitor de Sequ\u00eda de los Estados Unidos, con datos v\u00e1lidos al 4 de agosto.<\/p>\n\n\n\n<p>La actualizaci\u00f3n refleja que el\u00a09.5%\u00a0del territorio se encuentra bajo sequ\u00eda extrema, el\u00a026.1%\u00a0bajo sequ\u00eda severa y el\u00a032.1%\u00a0bajo sequ\u00eda moderada. En conjunto, el\u00a067.8%\u00a0de Puerto Rico registra condiciones de sequ\u00eda, mientras otro\u00a011.2%\u00a0presenta condiciones anormalmente secas.<\/p><div class=\"notic-content-middle\" id=\"notic-154753714\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n\n\n\n<p>El mapa muestra que la nueva zona de sequ\u00eda extrema se concentra en municipios del litoral sur, donde el d\u00e9ficit de lluvia se ha intensificado durante las \u00faltimas semanas. A su vez, la sequ\u00eda severa se extiende por amplios sectores del sur y el este de la isla, mientras la sequ\u00eda moderada abarca gran parte del resto del territorio.<\/p>\n\n\n\n<p>El Monitor de Sequ\u00eda de los Estados Unidos clasifica la intensidad de la sequ\u00eda en cinco categor\u00edas, desde condiciones anormalmente secas hasta sequ\u00eda excepcional. La herramienta, elaborada semanalmente por agencias federales y el Centro Nacional de Mitigaci\u00f3n de la Sequ\u00eda, sirve de referencia para la planificaci\u00f3n del manejo de los recursos de agua y para la activaci\u00f3n de determinados programas de asistencia relacionados con la sequ\u00eda.<\/p>","protected":false},"excerpt":{"rendered":"<p>El litoral sur de Puerto Rico entr\u00f3 por primera vez este a\u00f1o en la categor\u00eda de sequ\u00eda extrema, mientras m\u00e1s de dos terceras partes de la isla permanecen bajo alg\u00fan nivel de sequ\u00eda, seg\u00fan la actualizaci\u00f3n semanal del Monitor de Sequ\u00eda de los Estados Unidos, con datos v\u00e1lidos al 4 de agosto. La actualizaci\u00f3n refleja [&hellip;]<\/p>","protected":false},"author":101,"featured_media":1016816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3,2],"tags":[237,6107],"class_list":["post-1016815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","category-ultima-hora","tag-lluvia","tag-sequia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1016815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1016815"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1016815\/revisions"}],"predecessor-version":[{"id":1016817,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1016815\/revisions\/1016817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1016816"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1016815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1016815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1016815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}