{"id":1015907,"date":"2026-07-31T16:27:43","date_gmt":"2026-07-31T20:27:43","guid":{"rendered":""},"modified":"2026-07-31T16:33:20","modified_gmt":"2026-07-31T20:33:20","slug":"un-bochorno-la-postura-del-actual-liderato-del-ppd-dice-jorge-colberg","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260731\/un-bochorno-la-postura-del-actual-liderato-del-ppd-dice-jorge-colberg\/","title":{"rendered":"\u201cUn bochorno\u201d la postura del actual liderato del PPD, dice Jorge Colberg"},"content":{"rendered":"<p>Jorge Colberg Toro expres\u00f3 sin tapujos su apreciaci\u00f3n a lo que aconteci\u00f3 durante la reciente actividad del Partido Popular Democr\u00e1tico (PPD) para celebrar el Estado Libre Asociado (ELA) en Cayey.<\/p>\n\n\n\n<p>El analista pol\u00edtico de Pelota Dura que transmite NotiUno 630 AM, catalog\u00f3 como \u201cun bochorno\u201d la postura del actual liderato del PPD.<\/p>\n\n\n\n<p>\u201cEl 25 de julio sentaron al liderato en la tarima. \u00bfUstedes saben d\u00f3nde sentaron a dos exgobernadores del Partido Popular, a Sila Calder\u00f3n y Alejandro Garc\u00eda Padilla? \u00a1En el piso, en el piso! No le dieron asientos ni en la tarima\u201d, expres\u00f3 Colberg Toro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/31162327\/WhatsApp-Image-2026-07-25-at-4.57.26-PM-1024x683.jpeg\" alt=\"\" class=\"wp-image-1015910\" srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/31162327\/WhatsApp-Image-2026-07-25-at-4.57.26-PM-1024x683.jpeg 1024w, https:\/\/cdn.noticel.com\/2026\/07\/31162327\/WhatsApp-Image-2026-07-25-at-4.57.26-PM-300x200.jpeg 300w, https:\/\/cdn.noticel.com\/2026\/07\/31162327\/WhatsApp-Image-2026-07-25-at-4.57.26-PM-768x512.jpeg 768w, https:\/\/cdn.noticel.com\/2026\/07\/31162327\/WhatsApp-Image-2026-07-25-at-4.57.26-PM-1536x1024.jpeg 1536w, https:\/\/cdn.noticel.com\/2026\/07\/31162327\/WhatsApp-Image-2026-07-25-at-4.57.26-PM-18x12.jpeg 18w, https:\/\/cdn.noticel.com\/2026\/07\/31162327\/WhatsApp-Image-2026-07-25-at-4.57.26-PM.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>La exgobernadora Sila Calder\u00f3n acudi\u00f3 a la actividad del 25 de julio. (Benjam\u00edn Hern\u00e1ndez)<\/em><\/figcaption><\/figure>\n\n\n\n<p>\u201cEs una falta de respeto del liderato del Partido Popular\u201d, insisti\u00f3.<\/p>\n\n\n\n<p>El acto oficial de conmemoraci\u00f3n del 74 aniversario de la firma de la Constituci\u00f3n del ELA tuvo lugar en el Teatro Municipal en Cayey. El comisionado residente en Washington DC y presidente del PPD, Pablo Jos\u00e9 Hern\u00e1ndez Rivera, ofreci\u00f3 el mensaje principal.<\/p>\n\n\n\n<p>\u201cMe perdona Manuel Calder\u00f3n, me perdona Pablo Jos\u00e9, y no s\u00e9 ni el nombre del comisionado electoral. Respeten la historia del Partido Popular. Respeten a las figuras que se echaron al hombro al Partido Popular. Cuando ellos estaban en kindergarten. Cuando estaban en kindergarten, Sila Calder\u00f3n estaba buscando votos para el Partido Popular y Alejandro Garc\u00eda Padilla estaba fajado buscando votos para el Partido Popular. No vengan con ese cuento aqu\u00ed y con esos moralistas ahora\u201d, expres\u00f3 Colberg Toro.<\/p>","protected":false},"excerpt":{"rendered":"<p>Jorge Colberg Toro expres\u00f3 sin tapujos su apreciaci\u00f3n a lo que aconteci\u00f3 durante la reciente actividad del Partido Popular Democr\u00e1tico (PPD) para celebrar el Estado Libre Asociado (ELA) en Cayey. El analista pol\u00edtico de Pelota Dura que transmite NotiUno 630 AM, catalog\u00f3 como \u201cun bochorno\u201d la postura del actual liderato del PPD. \u201cEl 25 de [&hellip;]<\/p>","protected":false},"author":100,"featured_media":1015908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1015907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1015907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1015907"}],"version-history":[{"count":5,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1015907\/revisions"}],"predecessor-version":[{"id":1015915,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1015907\/revisions\/1015915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1015908"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1015907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1015907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1015907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}