{"id":1012979,"date":"2026-07-14T18:22:04","date_gmt":"2026-07-14T22:22:04","guid":{"rendered":""},"modified":"2026-07-14T18:25:13","modified_gmt":"2026-07-14T22:25:13","slug":"vicepresidente-electo-de-colombia-busca-establecer-lazos-de-mayor-alcance-con-ee-uu","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260714\/vicepresidente-electo-de-colombia-busca-establecer-lazos-de-mayor-alcance-con-ee-uu\/","title":{"rendered":"Vicepresidente electo de Colombia busca establecer lazos de \u00abmayor alcance\u00bb con EE.UU."},"content":{"rendered":"<p><\/p>\n\n\n\n<p>WASHINGTON \u2014 El vicepresidente electo de Colombia, Jos\u00e9 Manuel Restrepo, y varios de los ministros designados del futuro Gobierno de Abelardo de la Espriella afirmaron este martes en Washington que el pa\u00eds suramericano busca establecer lazos estrat\u00e9gicos \u00abde mayor alcance\u00bb con Estados Unidos y retomar iniciativas \u00abperdidas\u00bb.<\/p>\n\n\n\n<p>Durante su visita a la capital estadounidense, la delegaci\u00f3n colombiana ofreci\u00f3 detalles sobre la agenda de la Administraci\u00f3n del ultraderechista De la Espriella, que quiere ampliar el comercio bilateral y atraer una mayor inversi\u00f3n internacional hacia la naci\u00f3n suramericana.<\/p>\n\n\n\n<p>\u00abEste representa un nuevo momento en la relaci\u00f3n entre Colombia y Estados Unidos. Quiz\u00e1s un momento en el que podamos establecer una asociaci\u00f3n estrat\u00e9gica de mayor alcance\u00bb, dijo Restrepo en un evento en ingl\u00e9s en el Atlantic Council, un centro de pensamiento con el que el economista colabor\u00f3 como investigador.<\/p>\n\n\n\n<p>Seg\u00fan el \u00abnumero dos\u00bb de De la Espriella, lleg\u00f3 a Washington \u00abpara desarrollar programas estrat\u00e9gicos de infraestructura y retomar iniciativas que se perdieron durante los \u00faltimos a\u00f1os\u00bb.<\/p>\n\n\n\n<p>\u00abEstamos aqu\u00ed para fortalecer la seguridad econ\u00f3mica y nacional, tanto en nuestro pa\u00eds como en Estados Unidos. Al considerar a Colombia como un socio estrat\u00e9gico y una plataforma para la democratizaci\u00f3n de Venezuela, creemos posible establecer un modelo de asociaci\u00f3n en el que todas las partes salgan ganando\u00bb, agreg\u00f3.<\/p>\n\n\n\n<p>Restrepo incluso consider\u00f3 la posibilidad de \u00abimportar combustible desde Venezuela\u00bb, que ha acercado posiciones con Washington despu\u00e9s de la captura de Nicol\u00e1s Maduro por parte de Estados Unidos y negociaran con el nuevo Gobierno de la chavista Delcy Rodr\u00edguez la gesti\u00f3n de las ventas del crudo venezolano.<\/p><div class=\"notic-content-middle\" id=\"notic-1094435525\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n\n\n\n<p>\u00abEs necesario mejorar la gesti\u00f3n p\u00fablica, lo cual implica cooperaci\u00f3n con el sector privado y asistencia t\u00e9cnica. Hemos acudido, por ejemplo, al FMI y al Departamento del Tesoro para solicitar apoyo en este proceso\u00bb, a\u00f1adi\u00f3 Restrepo sobre su estancia en EE.UU., donde tambi\u00e9n fue recibido en la sede del Banco Mundial.<\/p>\n\n\n\n<p>El vicepresidente electo colombiano viaj\u00f3 a Washington junto a los ministros designados de Exteriores, Omar Bula Escobar, de Hacienda, Miguel G\u00f3mez Mart\u00ednez, y de Comercio, Mauricio G\u00f3mez Am\u00edn.<\/p>\n\n\n\n<p>Esta visita coincide con nuevas acusaciones del presidente saliente, el izquierdista Gustavo Petro, que conden\u00f3 el \u00abasesinato\u00bb de un ciudadano colombiano durante un operativo migratorio en Maine y pidi\u00f3 a su hom\u00f3logo estadounidense, Donald Trump, que se pronunciara en un \u00abmensaje al pueblo colombiano\u00bb.<\/p>\n\n\n\n<p>A la luz de las diferencias entre Petro y Trump, Bula insisti\u00f3 en que para el nuevo Gobierno colombiano, \u00abno solo se trata de recuperar el tiempo perdido en los \u00faltimos cuatro a\u00f1os, sino tambi\u00e9n de reconocer que nos encontramos en una coyuntura geopol\u00edtica mundial crucial\u00bb.<\/p>\n\n\n\n<p>\u00abEste es el momento de definir el lugar que ocupar\u00e1 Colombia en el futuro. En primer lugar, por supuesto, est\u00e1 la reconstrucci\u00f3n de la relaci\u00f3n que manten\u00edamos anteriormente con Estados Unidos e Israel, as\u00ed como con pa\u00edses afines\u00bb, indic\u00f3 el pr\u00f3ximo canciller.<\/p>","protected":false},"excerpt":{"rendered":"<p>WASHINGTON \u2014 El vicepresidente electo de Colombia, Jos\u00e9 Manuel Restrepo, y varios de los ministros designados del futuro Gobierno de Abelardo de la Espriella afirmaron este martes en Washington que el pa\u00eds suramericano busca establecer lazos estrat\u00e9gicos \u00abde mayor alcance\u00bb con Estados Unidos y retomar iniciativas \u00abperdidas\u00bb. Durante su visita a la capital estadounidense, la [&hellip;]<\/p>","protected":false},"author":102,"featured_media":1012980,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[16,3],"tags":[232,117],"class_list":["post-1012979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados-unidos","category-noticias","tag-colombia","tag-estados-unidos"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1012979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1012979"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1012979\/revisions"}],"predecessor-version":[{"id":1012983,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1012979\/revisions\/1012983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1012980"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1012979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1012979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1012979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}