{"id":1009794,"date":"2026-06-27T10:35:42","date_gmt":"2026-06-27T14:35:42","guid":{"rendered":"https:\/\/noticel.com\/?p=1009794"},"modified":"2026-06-27T10:41:50","modified_gmt":"2026-06-27T14:41:50","slug":"victorias-para-indios-y-leones-en-el-bsn","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20260627\/victorias-para-indios-y-leones-en-el-bsn\/","title":{"rendered":"Victorias para Indios y Leones en el BSN"},"content":{"rendered":"<p>Los Indios de Mayag\u00fcez y los Leones de Ponce terminaron con victorias como visitantes en la noche del viernes en el Baloncesto Superior Nacional.<\/p>\n\n\n\n<p>Ambos equipos buscan el ultimo boleto de la Conferencia B para la postemporada.<\/p>\n\n\n\n<p>Mayag\u00fcez derrot\u00f3 88-85 a los Gigantes de Carolina\/Can\u00f3vanas. Con el triunfo, los Indios mejoran su r\u00e9cord a 13-20, mientras los Gigantes caen a 17-15.<\/p>\n\n\n\n<p>El primer parcial termin\u00f3 empatado a 21 y los Indios aprovecharon un segundo periodo de 21-19 para marcharse al descanso con ventaja de 42-40. Los Gigantes reaccionaron tras el intermedio y ganaron el tercer parcial 30-29, aunque Mayag\u00fcez conserv\u00f3 una m\u00ednima ventaja de 71-70 entrando al cuarto periodo.<\/p>\n\n\n\n<p>En el cierre, Tremont Waters acerc\u00f3 a los Gigantes con dos tiros libres para colocar el marcador 88-85 con 1:12 por jugar, pero la defensa de Mayag\u00fcez respondi\u00f3 en las posesiones finales para asegurar una valiosa victoria en la carretera.<\/p>\n\n\n\n<p>El encuentro fue uno de los m\u00e1s parejos de la temporada, con 44 cambios de liderato. Adem\u00e1s, ambos equipos anotaron 44 puntos en la pintura.<\/p>\n\n\n\n<p>Tyrell Harrison encabez\u00f3 la ofensiva de los Indios con un dominante doble-doble de 26 puntos y 19 rebotes. Benito Santiago a\u00f1adi\u00f3 15 puntos, todos mediante cinco triples, mientras Jared Ruiz aport\u00f3 12.<\/p>\n\n\n\n<p>Por los Gigantes, Jaylen Nowell termin\u00f3 con 20 puntos y Scottie James registr\u00f3 un doble-doble de 17 puntos y 11 rebotes.<\/p>\n\n\n\n<p>De otra parte, los Leones le ganaron 109-95 a los Santeros de Aguada.<\/p>\n\n\n\n<p>Ponce tom\u00f3 el control desde temprano al ganar el primer parcial 20-18 y ampli\u00f3 la ventaja con un dominante segundo periodo de 34-28 para irse al descanso al frente 54-46.<\/p>\n\n\n\n<p>Los ponce\u00f1os, dirigidos por Carlos Rivera, sentenciaron el encuentro en el tercer parcial, que dominaron 30-22 para abrir una ventaja de 84-68. Aunque los Santeros ganaron el \u00faltimo periodo 27-25, los Leones mantuvieron el control y llegaron a disfrutar de una ventaja m\u00e1xima de 20 puntos.<\/p>\n\n\n\n<p>Jezreel de Jes\u00fas tuvo una noche espectacular con 43 puntos. Thomas Robinson a\u00f1adi\u00f3 24 puntos y 7 rebotes, mientras Brady Manek aport\u00f3 16 puntos y 9 rebotes.<\/p>\n\n\n\n<p>Por Aguada, Rigoberto Mendoza termin\u00f3 con 31 puntos y 10 rebotes. Iv\u00e1n Gand\u00eda, Joel Soriano y Jase Febres a\u00f1adieron 10 puntos cada uno.<\/p>\n\n\n\n<p>Mientras la Conferencia A ya tiene definidos sus cuatro clasificados, la lucha por el \u00faltimo boleto disponible en la Conferencia B contin\u00faa abierta, con Indios y Leones neg\u00e1ndose a bajar los brazos en la recta final de la temporada regular.<\/p>\n\n\n\n<p>Hoy, s\u00e1bado, hay tres juegos en calendario: Arecibo en San Germ\u00e1n, Bayam\u00f3n en Ponce y Aguada en Quebradillas. Todos a las 8:00 pm.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los Indios de Mayag\u00fcez y los Leones de Ponce terminaron con victorias como visitantes en la noche del viernes en el Baloncesto Superior Nacional. Ambos equipos buscan el ultimo boleto de la Conferencia B para la postemporada. Mayag\u00fcez derrot\u00f3 88-85 a los Gigantes de Carolina\/Can\u00f3vanas. Con el triunfo, los Indios mejoran su r\u00e9cord a 13-20, [&hellip;]<\/p>","protected":false},"author":101,"featured_media":1009795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[33,31],"tags":[161,2505],"class_list":["post-1009794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-deportes","tag-bsn","tag-temporada-2026"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1009794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1009794"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1009794\/revisions"}],"predecessor-version":[{"id":1009797,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1009794\/revisions\/1009797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1009795"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1009794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1009794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1009794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}