{"id":1009073,"date":"2026-06-24T10:43:49","date_gmt":"2026-06-24T14:43:49","guid":{"rendered":""},"modified":"2026-06-24T13:36:16","modified_gmt":"2026-06-24T17:36:16","slug":"el-lider-izquierdista-ivan-cepeda-acepta-la-derrota-y-reconoce-triunfo-de-de-la-espriella-en-colombia","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20260624\/el-lider-izquierdista-ivan-cepeda-acepta-la-derrota-y-reconoce-triunfo-de-de-la-espriella-en-colombia\/","title":{"rendered":"El l\u00edder izquierdista Iv\u00e1n Cepeda acepta la derrota y reconoce triunfo de De la Espriella en Colombia"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<p>El candidato de izquierda Iv\u00e1n Cepeda reconoci\u00f3 este mi\u00e9rcoles la derrota en las elecciones presidenciales del pasado domingo en Colombia y acept\u00f3 el triunfo del candidato de ultraderecha Abelardo de la Espriella, quien obtuvo 12.9 millones de votos (49.78%) y le gan\u00f3 por menos de un punto porcentual de diferencia.<\/p>\n\n\n\n<p>\u00abNo aceptaremos que se vulneren las libertades p\u00fablicas, que se estigmatice a los movimientos sociales o que se pretenda tratar a la juventud y a la ciudadan\u00eda organizada como enemigos internos\u00bb, afirm\u00f3 Cepeda en una declaraci\u00f3n p\u00fablica.<\/p>\n\n\n\n<p>\u00abComo candidato del (partido) Pacto Hist\u00f3rico y la (coalici\u00f3n) Alianza por la Vida, como lo anunci\u00e9 oportunamente y en este estadio del escrutinio, he decidido aceptar el resultado que surge de dicho proceso y que se\u00f1ala que Abelardo de la Espriella es el nuevo presidente de la Rep\u00fablica\u00bb, manifest\u00f3 Cepeda en una declaraci\u00f3n p\u00fablica.<\/p>\n\n\n\n<p>El dirigente de izquierda asegur\u00f3 que toma esa decisi\u00f3n \u00abcomo un acto de responsabilidad democr\u00e1tica\u00bb y afirm\u00f3 que busca contribuir \u00aba la convivencia, a la paz y al di\u00e1logo entre colombianos\u00bb.<\/p>\n\n\n\n<p>\u00abLo hago porque creemos profundamente en la democracia y porque estamos convencidos de que las diferencias pol\u00edticas deben resolverse mediante la participaci\u00f3n ciudadana, el respeto a las instituciones y la deliberaci\u00f3n p\u00fablica\u00bb, agreg\u00f3.<\/p>\n\n\n\n<p>Cepeda destac\u00f3 adem\u00e1s lo ajustado del resultado electoral y se\u00f1al\u00f3 que &nbsp;\u00abla votaci\u00f3n muestra una diferencia extraordinariamente estrecha entre las dos opciones que disputamos la confianza del pueblo colombiano\u00bb.<\/p>\n\n\n\n<p>Seg\u00fan el senador, que al terminar en el segundo lugar de las votaciones volver\u00e1 a ocupar ese cargo para el periodo 2026-2030, esa estrecha diferencia refleja tanto la intensidad del debate pol\u00edtico vivido durante la campa\u00f1a como la responsabilidad que tendr\u00e1n las distintas fuerzas pol\u00edticas frente al futuro del pa\u00eds.<\/p>\n\n\n\n<p>El dirigente tambi\u00e9n indic\u00f3 que el proceso de escrutinio llevado a cabo por las autoridades electorales se encuentra \u00abpr\u00e1cticamente concluido\u00bb y agradeci\u00f3 a los miles de testigos, abogados y observadores electorales que participaron en la vigilancia de los comicios por parte del Pacto Hist\u00f3rico y la Alianza por la Vida.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Oposici\u00f3n al nuevo Gobierno<\/strong><\/h2>\n\n\n\n<p>Aunque acept\u00f3 la victoria de De la Espriella, Cepeda dej\u00f3 claro que ejercer\u00e1 una labor de vigilancia frente al nuevo Gobierno y asegur\u00f3 que defender\u00e1 la democracia y las libertades p\u00fablicas.<\/p>\n\n\n\n<p>\u00abDefenderemos la democracia con toda nuestra energ\u00eda moral y pol\u00edtica\u00bb, afirm\u00f3, antes de advertir que no aceptar\u00e1 que se vulneren las libertades p\u00fablicas, que se estigmatice a los movimientos sociales o que se trate a la juventud y a la ciudadan\u00eda organizada \u00abcomo enemigos internos\u00bb.<\/p>\n\n\n\n<p>Asimismo, sostuvo que tampoco aceptar\u00e1 \u00abtratos machistas u hom\u00f3fobos por parte del presidente de la Rep\u00fablica\u00bb ni restricciones a la libertad de expresi\u00f3n y opini\u00f3n.<\/p>\n\n\n\n<p>La aceptaci\u00f3n de los resultados por parte del candidato de izquierda se produce tres d\u00edas despu\u00e9s de la segunda vuelta presidencial y contribuye a despejar las dudas sobre el desenlace de unos comicios marcados por la estrechez del resultado entre los dos aspirantes.<\/p>","protected":false},"excerpt":{"rendered":"<p>El candidato de izquierda Iv\u00e1n Cepeda reconoci\u00f3 este mi\u00e9rcoles la derrota en las elecciones presidenciales del pasado domingo en Colombia y acept\u00f3 el triunfo del candidato de ultraderecha Abelardo de la Espriella, quien obtuvo 12.9 millones de votos (49.78%) y le gan\u00f3 por menos de un punto porcentual de diferencia. \u00abNo aceptaremos que se vulneren [&hellip;]<\/p>","protected":false},"author":102,"featured_media":1009074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17,3,2],"tags":[232,6071],"class_list":["post-1009073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","category-noticias","category-ultima-hora","tag-colombia","tag-presidencia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1009073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1009073"}],"version-history":[{"count":3,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1009073\/revisions"}],"predecessor-version":[{"id":1009131,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1009073\/revisions\/1009131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1009074"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1009073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1009073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1009073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}