{"id":100895,"date":"2015-04-01T09:40:57","date_gmt":"2015-04-01T13:40:57","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20150401\/ingles-de-agp-provoco-allanamiento-a-lugaro-pa-reirse\/"},"modified":"2025-08-18T04:37:01","modified_gmt":"2025-08-18T04:37:01","slug":"ingles-de-agp-provoco-allanamiento-a-lugaro-pa-reirse","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20150401\/ingles-de-agp-provoco-allanamiento-a-lugaro-pa-reirse\/","title":{"rendered":"Ingl\u00e9s de AGP provoc\u00f3 allanamiento a L\u00fagaro (pa&#8217; re\u00edrse)"},"content":{"rendered":"<p>San Juan, Puerto Rico &#8211; Fuentes confidenciales y de entero (des)credito informan que lo que propuls\u00f3 la investigaci\u00f3n de la FBI a la compa\u00f1\u00eda American Aponte y Associates, empresa de la dizque candidata independiente a la gobernaci\u00f3n Alexandra L\u00fagaro, fue el ingles goleta del gobernador de Puerto Rico, Alejandro Garc\u00eda Padilla. La empresa de L\u00fagaro tiene millones de d\u00f3lares en contratos para dar tutor\u00edas de ingles para el Departamento de Educaci\u00f3n y las dolorosas entrevistas en ingles que el gobernador a dado recientemente levantaron la suspicacia de la agencia federal, ya que si se est\u00e1n gastando millones de d\u00f3lares en tutor\u00edas para aprender El Dif\u00edcil, pues es inconcebible que el gobernador lo hable as\u00ed de mata&#8217;o.<\/p>\n<p>&#8216;Muchacho, cuando escuchamos al gobernador referirse a Puerto Rico como down there en esa entrevista televisiva con Bloomberg&#8217;, explic\u00f3 el agente Ra\u00fal Mart\u00ednez, de la FBI refiri\u00e9ndose espec\u00edficamente al minuto 5:08 del video (chequeen: we&#8217;ll wait!), &#8216;despu\u00e9s de escupir el caf\u00e9 me pregunt\u00e9: \u2018Pero la nena esa no tiene millones en contratos de tutor\u00edas en ingl\u00e9s con el gobierno? C\u00f3mo es posible que un gobernador se exprese as\u00ed en el idioma de Shakespeare?&#8217;. Agarr\u00e9 el tel\u00e9fono y en media hora me dieron la orden de allanamiento&#8217;. La investigaci\u00f3n inicial se enfoc\u00f3 en por qu\u00e9 la empresa American Aponte y Associates no secuestr\u00f3 al gobernador para encerrarlo en un s\u00f3tano y darle tutor\u00edas de ingl\u00e9s a la tr\u00e1gala hasta que dejara de dar entrevistas bochornosas cuando incidentalmente encontraron que hab\u00eda posible fraude por no satisfacer los contratos con el Departamento de Educaci\u00f3n.<\/p>\n<p>Por otro lado, se inform\u00f3 que la FBI est\u00e1 explorando una segunda investigaci\u00f3n para meter preso al gobernador por asesinar el ingl\u00e9s una y otra vez en cada entrevista.<\/p>\n<p>Para m\u00e1s humor, vea <a href=\"http:\/\/elname.com\">El\u00d1ame.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>San Juan, Puerto Rico &#8211; Fuentes confidenciales y de entero (des)credito informan que lo que propuls\u00f3 la investigaci\u00f3n de la FBI a la compa\u00f1\u00eda American Aponte y Associates, empresa de la dizque candidata independiente a la gobernaci\u00f3n Alexandra L\u00fagaro, fue el ingles goleta del gobernador de Puerto Rico, Alejandro Garc\u00eda Padilla. La empresa de L\u00fagaro [&hellip;]<\/p>","protected":false},"author":0,"featured_media":866006,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-100895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/100895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=100895"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/100895\/revisions"}],"predecessor-version":[{"id":866028,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/100895\/revisions\/866028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/866006"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=100895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=100895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=100895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}