{"id":1008397,"date":"2026-06-21T05:46:00","date_gmt":"2026-06-21T09:46:00","guid":{"rendered":"https:\/\/noticel.com\/?p=1008397"},"modified":"2026-06-21T00:16:55","modified_gmt":"2026-06-21T04:16:55","slug":"descubren-una-version-mas-simple-y-antigua-del-monumento-megalitico-ingles-de-stonehenge","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260621\/descubren-una-version-mas-simple-y-antigua-del-monumento-megalitico-ingles-de-stonehenge\/","title":{"rendered":"Descubren una versi\u00f3n m\u00e1s simple y antigua del monumento megal\u00edtico ingl\u00e9s de Stonehenge"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>LONDRES \u2014 Arque\u00f3logos brit\u00e1nicos han descubierto una versi\u00f3n m\u00e1s simple y m\u00e1s antigua de Stonehenge, el monumento megal\u00edtico ubicado en el sur de Inglaterra, y junto a los restos hallados tambi\u00e9n se encontraron cer\u00e1micas y huesos de animales.<\/p>\n\n\n\n<p>De la estructura, descubierta a unos cinco kil\u00f3metros del famoso monumento de grandes bloques de piedra alineados astron\u00f3micamente, solo quedan dos fosas, pero los arque\u00f3logos afirman que sosten\u00edan postes de madera alineados con el sol durante los solsticios de verano e invierno, al igual que Stonehenge.<\/p>\n\n\n\n<p>La excavaci\u00f3n estuvo a cargo de Phil Harding, de la empresa brit\u00e1nica dedicada a servicios arqueol\u00f3gicos Wessex Archeology, y ha sido dada a conocer pocos d\u00edas antes del solsticio de verano -el 21 de junio-, el d\u00eda m\u00e1s largo del a\u00f1o, cuando miles de personas acuden a Stonehenge para contemplar el amanecer.<\/p>\n\n\n\n<p>La estructura, de 5,000 a\u00f1os de antig\u00fcedad, es unos 500 a\u00f1os anterior al monumento principal de Stonehenge y fue hallada en la localidad de Bulford, en el condado de Wiltshire (sur ingl\u00e9s).<\/p>\n\n\n\n<p>Los arque\u00f3logos indicaron que la estructura probablemente sirvi\u00f3 para ceremonias religiosas.<\/p>\n\n\n\n<p>Cuando Harding hall\u00f3 las fosas, not\u00f3 que parec\u00edan estar alineadas con el sol, al igual que Stonehenge. \u00abTom\u00e9 mi l\u00e1piz y mi regla, las un\u00ed y me di cuenta de que apuntaban en la direcci\u00f3n general del amanecer en el solsticio de verano\u00bb, agreg\u00f3 a los medios.<\/p><div class=\"notic-content-middle\" id=\"notic-3212323889\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n\n\n\n<p>La estructura fue hallada hace diez a\u00f1os cuando se despej\u00f3 el terreno para la construcci\u00f3n de nuevas viviendas militares, pero reci\u00e9n ahora se ha podido hacer un an\u00e1lisis detallado de la alineaci\u00f3n.<\/p>\n\n\n\n<p>Las fosas conten\u00edan cer\u00e1mica, huesos de animales y carb\u00f3n vegetal, lo que sugiere que un gran n\u00famero de personas se reunieron durante un per\u00edodo relativamente corto para celebrar el Sol.<\/p>\n\n\n\n<p>Una de las fosas, que se cree pudo haber sido un \u00abpunto de observaci\u00f3n\u00bb para el solsticio, conten\u00eda un cuchillo con una forma muy rara que al parecer fue colocado all\u00ed deliberadamente, tal vez como una referencia simb\u00f3lica al disco solar, seg\u00fan los expertos.<\/p>\n\n\n\n<p>Matt Leivers, director de investigaci\u00f3n de Wessex Archaeology, afirm\u00f3 que le parece \u00abinconcebible, dada la coincidencia de fechas, que las personas que estuvieron en Bulford y las que estuvieron en Stonehenge durante su primera fase no se conocieran\u00bb.<\/p>\n\n\n\n<p>Stonehenge est\u00e1 ubicado a unos 130 kil\u00f3metros al oeste de Londres y fue declarado por la Unesco como Patrimonio de la Humanidad en 1986.<\/p>","protected":false},"excerpt":{"rendered":"<p>LONDRES \u2014 Arque\u00f3logos brit\u00e1nicos han descubierto una versi\u00f3n m\u00e1s simple y m\u00e1s antigua de Stonehenge, el monumento megal\u00edtico ubicado en el sur de Inglaterra, y junto a los restos hallados tambi\u00e9n se encontraron cer\u00e1micas y huesos de animales. De la estructura, descubierta a unos cinco kil\u00f3metros del famoso monumento de grandes bloques de piedra alineados [&hellip;]<\/p>","protected":false},"author":102,"featured_media":1008398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17,3],"tags":[4364,4382],"class_list":["post-1008397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","category-noticias","tag-arqueologia","tag-inglaterra"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1008397"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008397\/revisions"}],"predecessor-version":[{"id":1008445,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008397\/revisions\/1008445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1008398"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1008397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1008397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1008397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}