{"id":1008279,"date":"2026-06-19T16:32:41","date_gmt":"2026-06-19T20:32:41","guid":{"rendered":""},"modified":"2026-06-20T09:36:20","modified_gmt":"2026-06-20T13:36:20","slug":"oscar-collazo-sube-de-categoria-para-probar-suerte-en-las-112-libras","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20260619\/oscar-collazo-sube-de-categoria-para-probar-suerte-en-las-112-libras\/","title":{"rendered":"Oscar Collazo sube de categor\u00eda para probar suerte en las 112 libras"},"content":{"rendered":"<p>Oscar \u201cEl Pupilo\u201d Collazo subir\u00e1 a las 112 libras para disputar con Neider Vald\u00e9z Aguilar (15-3-3, 12 KO) el cetro Internacional de la Organizaci\u00f3n Mundial de Boxeo (OMB).<\/p>\n\n\n\n<p>Para el p\u00fagil puertorrique\u00f1a representa un dr\u00e1stico cambio dado que ten\u00eda en agenda arriesgar el cintur\u00f3n de las 105 libras durante la cartelera que tendr\u00e1 como escenario el Frontwave Arena en Oceanside, California.<\/p>\n\n\n\n<p>\u201cEl rival lleg\u00f3 pesado. Tomamos la oportunidad porque quiero hacer historia en las 112 libras\u201d, sostuvo Collazo desde la sede del evento. El boricua marc\u00f3 110 libras para el compromiso a 12 asaltos.<\/p>\n\n\n\n<p>Collazo aclar\u00f3 que, por el momento, no dejar\u00e1 vacantes los t\u00edtulos de las 105 libras.<\/p><div class=\"notic-content-middle\" id=\"notic-3593222938\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n\n\n\n<p>\u201cDespu\u00e9s se determinar\u00e1 si me quedo o bajo. La meta es cuadrar las peleas grandes, es lo que queremos porque da m\u00e1s motivaci\u00f3n\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Originalmente, Collazo tuvo en agenda un duelo contra el filipino Joey Canoy. Sin embargo, no obtuvo el visado necesario para ingresar a Estados Unidos. Luego de unas negociaciones, la OMB accedi\u00f3 que Vald\u00e9z Aguilar ocupara el lugar de Canoy.<\/p>\n\n\n\n<p>\u201cPr\u00e1cticamente se cuadr\u00f3 el jueves con la OMB. El rival no lleg\u00f3 en peso y era hora de hacer cosas diferentes porque el tiempo pasa. Tan pronto se acord\u00f3 comenc\u00e9 a tomar l\u00edquido que es lo que el cuerpo pide y llegu\u00e9. Me siento c\u00f3modo en el peso hasta las 110 libras\u201d, explic\u00f3.<\/p>\n\n\n\n<p>\u201cSi se puede acabar temprano aprovecho. La mano llegar\u00e1, es cuesti\u00f3n de ir con calma, vivo y bien pendiente. No me tirar\u00e9 a lo loco, hay que seguir el plan con una defensa activa\u201d, concluy\u00f3 Collazo (14-0, 11 KO).<\/p>","protected":false},"excerpt":{"rendered":"<p>Oscar \u201cEl Pupilo\u201d Collazo subir\u00e1 a las 112 libras para disputar con Neider Vald\u00e9z Aguilar (15-3-3, 12 KO) el cetro Internacional de la Organizaci\u00f3n Mundial de Boxeo (OMB). Para el p\u00fagil puertorrique\u00f1a representa un dr\u00e1stico cambio dado que ten\u00eda en agenda arriesgar el cintur\u00f3n de las 105 libras durante la cartelera que tendr\u00e1 como escenario [&hellip;]<\/p>","protected":false},"author":93,"featured_media":1008280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[34,31],"tags":[100,101,1146],"class_list":["post-1008279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxeo","category-deportes","tag-boxeo","tag-omb","tag-oscar-collazo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1008279"}],"version-history":[{"count":4,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008279\/revisions"}],"predecessor-version":[{"id":1008286,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008279\/revisions\/1008286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1008280"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1008279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1008279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1008279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}