{"id":1008040,"date":"2026-06-18T15:31:48","date_gmt":"2026-06-18T19:31:48","guid":{"rendered":""},"modified":"2026-06-18T15:52:56","modified_gmt":"2026-06-18T19:52:56","slug":"justicia-confirma-tribunal-supremo-denego-solicitud-para-frenar-juicio-contra-anthonieska","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260618\/justicia-confirma-tribunal-supremo-denego-solicitud-para-frenar-juicio-contra-anthonieska\/","title":{"rendered":"Justicia confirma Tribunal Supremo deneg\u00f3 solicitud para frenar juicio contra Anthonieska"},"content":{"rendered":"<p>La secretaria del Departamento de Justicia, Lourdes L. G\u00f3mez Torres, confirm\u00f3 hoy que el Tribunal Supremo de Puerto Rico deneg\u00f3 todas las solicitudes de paralizaci\u00f3n de los procedimientos y peticiones de\u00a0<em>certiorari\u00a0<\/em>presentadas por la defensa de Anthonieska Avil\u00e9s Cabrera.<\/p>\n\n\n\n<p>\u00abTal y como lo ha sido la postura del Ministerio P\u00fablico, mediante esta decisi\u00f3n prevalece la determinaci\u00f3n del Tribunal de Primera Instancia, que aval\u00f3 que Anthonieska Avil\u00e9s Cabrera sea procesada por asesinato en primer grado, es decir, que la acusada provoc\u00f3 la muerte de Gabriela Nicole Pratts Rosario a prop\u00f3sito y con conocimiento. De igual forma, se mantiene la determinaci\u00f3n en torno a que la acusada es procesable, esto significa que comprende la naturaleza del proceso penal en su contra y que puede colaborar adecuadamente con su defensa\u00bb, explic\u00f3 la secretaria de Justicia.<\/p><div class=\"notic-content-middle\" id=\"notic-1996929410\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n\n\n\n<p>La secretaria reafirm\u00f3 que \u00abno vamos a descansar hasta hacerle justicia a Gabriela Nicole y a su familia. Nuestro compromiso es procurar que este caso se atienda con la seriedad, sensibilidad y diligencia que merece, en cumplimiento con nuestro deber de representar los intereses del pueblo y de las v\u00edctimas de delito\u201d, expres\u00f3 la secretaria de Justicia.<\/p>","protected":false},"excerpt":{"rendered":"<p>La secretaria del Departamento de Justicia, Lourdes L. G\u00f3mez Torres, confirm\u00f3 hoy que el Tribunal Supremo de Puerto Rico deneg\u00f3 todas las solicitudes de paralizaci\u00f3n de los procedimientos y peticiones de\u00a0certiorari\u00a0presentadas por la defensa de Anthonieska Avil\u00e9s Cabrera. \u00abTal y como lo ha sido la postura del Ministerio P\u00fablico, mediante esta decisi\u00f3n prevalece la determinaci\u00f3n [&hellip;]<\/p>","protected":false},"author":100,"featured_media":999098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3],"tags":[174,187],"class_list":["post-1008040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","tag-justicia","tag-tribunal-supremo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1008040"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008040\/revisions"}],"predecessor-version":[{"id":1008041,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1008040\/revisions\/1008041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/999098"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1008040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1008040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1008040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}