{"id":1005373,"date":"2026-06-07T14:44:27","date_gmt":"2026-06-07T18:44:27","guid":{"rendered":""},"modified":"2026-06-07T15:05:21","modified_gmt":"2026-06-07T19:05:21","slug":"alcaldes-de-sj-y-bayamon-acuerdan-colaborar-en-seguridad","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260607\/alcaldes-de-sj-y-bayamon-acuerdan-colaborar-en-seguridad\/","title":{"rendered":"Alcaldes de SJ y Bayam\u00f3n acuerdan colaborar en seguridad"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>BAYAMON &#8211; Los alcaldes de\u00a0San Juan\u00a0y\u00a0Bayam\u00f3n, Miguel \u00a0Romero Lugo y Ram\u00f3n Luis Rivera Cruz firmaron el domingo un acuerdo colaborativo de seguridad que permitir\u00e1 el intercambio de tecnolog\u00eda, informaci\u00f3n y recursos especializados entre ambas ciudades para fortalecer la prevenci\u00f3n del crimen, apoyar investigaciones criminales, agilizar la respuesta a emergencias y reforzar la protecci\u00f3n de la ciudadan\u00eda.<\/p>\n\n\n\n<p>\u201cLa seguridad de nuestros ciudadanos exige que los gobiernos municipales identifiquen nuevas maneras de trabajar juntos. Este acuerdo nace de la convicci\u00f3n de que siempre podemos hacer m\u00e1s para proteger a nuestras comunidades y fortalecer las herramientas disponibles para combatir el crimen y responder a emergencias. Cuando encontramos oportunidades para colaborar, tenemos la responsabilidad de aprovecharlas. Eso es exactamente lo que estamos haciendo hoy\u201d, dijo el alcalde de San Juan en declaraciones escritas.<\/p>\n\n\n\n<p>\u201cLas herramientas tecnol\u00f3gicas han transformado la manera en que se realizan investigaciones y se atienden incidentes de seguridad. Integrar capacidades permite acceder a informaci\u00f3n de manera m\u00e1s r\u00e1pida y utilizar mejor los recursos disponibles. Esa coordinaci\u00f3n fortalece el trabajo diario de nuestros equipos y mejora la capacidad de respuesta operacional. Ese es uno de los principales beneficios de esta alianza\u201d, a\u00f1adi\u00f3 el alcalde de Bayam\u00f3n,&nbsp;Ram\u00f3n Luis Rivera Cruz.<\/p>\n\n\n\n<p>Como parte de la colaboraci\u00f3n, ambos municipios podr\u00e1n compartir im\u00e1genes, grabaciones y datos captados por sus respectivos sistemas de vigilancia cuando los incidentes ocurran dentro de sus jurisdicciones o tengan impacto en ambas ciudades. Adem\u00e1s, integrar\u00e1n plataformas tecnol\u00f3gicas especializadas que permitir\u00e1n agilizar el acceso a informaci\u00f3n necesaria para apoyar investigaciones criminales, operativos de seguridad y situaciones de emergencia.<\/p>\n\n\n\n<p>Actualmente, el&nbsp;Municipio de San Juan&nbsp;cuenta con cerca de 1,200 c\u00e1maras de vigilancia instaladas en sectores estrat\u00e9gicos de la ciudad, 22 lectores de tablillas, sistemas de inteligencia artificial para la identificaci\u00f3n de veh\u00edculos, cinco torres de vigilancia solar aut\u00f3nomas, tres centros de comando m\u00f3viles, una flota de cuatro drones y un&nbsp;Laboratorio de Evidencia Digital&nbsp;que apoya investigaciones y el an\u00e1lisis de evidencia tecnol\u00f3gica relacionada con asuntos de seguridad p\u00fablica.<\/p>\n\n\n\n<p>Por su parte, Bayam\u00f3n&nbsp;cuenta con el&nbsp;Centro de Tecnolog\u00eda Avanzada en Sistemas de Seguridad (TASS), 235 c\u00e1maras de vigilancia distribuidas estrat\u00e9gicamente en la ciudad, 54 c\u00e1maras con sistemas de foto-lectura de tablillas ubicadas en v\u00edas principales y un&nbsp;Fusion Center&nbsp;para monitoreo e inteligencia criminal. Adem\u00e1s, opera nueve torres de vigilancia electr\u00f3nica en tiempo real equipadas con c\u00e1maras de alta definici\u00f3n, tecnolog\u00eda termal, detecci\u00f3n de disparos y sistemas de fotolectura de tablillas. Su infraestructura tecnol\u00f3gica tambi\u00e9n incluye un centro de comando m\u00f3vil, drones de vigilancia, un&nbsp;drone&nbsp;de carga, un&nbsp;drone&nbsp;submarino y una fuerza policiaca municipal equipada en su totalidad con c\u00e1maras corporales (Body Cams).<\/p>\n\n\n\n<p>El acuerdo tambi\u00e9n promueve el intercambio de adiestramientos entre los cuerpos de ley y orden municipales con el prop\u00f3sito de fortalecer capacidades operacionales, mejorar la coordinaci\u00f3n intermunicipal y compartir conocimiento y experiencias en \u00e1reas especializadas de seguridad p\u00fablica.<\/p>\n\n\n\n<p>Adem\u00e1s del intercambio de informaci\u00f3n, el acuerdo permite el pr\u00e9stamo temporal de equipo especializado de vigilancia entre ambos municipios para reforzar operativos de seguridad y eventos especiales, incluyendo cinco torres de vigilancia solar aut\u00f3nomas y tres centros de comando m\u00f3viles. Asimismo, permitir\u00e1 que el Municipio de San Juan ponga a disposici\u00f3n su Laboratorio de Evidencia Digital para apoyar el an\u00e1lisis, procesamiento y manejo de evidencia tecnol\u00f3gica relacionada con investigaciones y asuntos de seguridad p\u00fablica. Como parte de la colaboraci\u00f3n, San Juan tambi\u00e9n podr\u00e1 brindar apoyo especializado mediante su flota de cuatro drones para labores de vigilancia, monitoreo, b\u00fasqueda y manejo de emergencias, sujeto a las autorizaciones y reglamentaci\u00f3n aplicable de la&nbsp;Administraci\u00f3n Federal de Aviaci\u00f3n (FAA).<\/p>\n\n\n\n<p>El acuerdo tendr\u00e1 vigencia&nbsp;hasta el 31 de diciembre de 2028.<\/p>","protected":false},"excerpt":{"rendered":"<p>BAYAMON &#8211; Los alcaldes de\u00a0San Juan\u00a0y\u00a0Bayam\u00f3n, Miguel \u00a0Romero Lugo y Ram\u00f3n Luis Rivera Cruz firmaron el domingo un acuerdo colaborativo de seguridad que permitir\u00e1 el intercambio de tecnolog\u00eda, informaci\u00f3n y recursos especializados entre ambas ciudades para fortalecer la prevenci\u00f3n del crimen, apoyar investigaciones criminales, agilizar la respuesta a emergencias y reforzar la protecci\u00f3n de la [&hellip;]<\/p>","protected":false},"author":101,"featured_media":1005374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,3],"tags":[193,2585,135],"class_list":["post-1005373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-noticias","tag-bayamon","tag-miguel-romero-lugo","tag-san-juan"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1005373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1005373"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1005373\/revisions"}],"predecessor-version":[{"id":1005375,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1005373\/revisions\/1005375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1005374"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1005373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1005373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1005373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}