{"id":1004611,"date":"2026-06-03T07:52:26","date_gmt":"2026-06-03T11:52:26","guid":{"rendered":"https:\/\/noticel.com\/?p=1004611"},"modified":"2026-06-03T07:59:45","modified_gmt":"2026-06-03T11:59:45","slug":"acusan-a-enfermera-por-alterar-frascos-de-fentanilo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/20260603\/acusan-a-enfermera-por-alterar-frascos-de-fentanilo\/","title":{"rendered":"Acusan a enfermera por alterar frascos de fentanilo"},"content":{"rendered":"<p>El fiscal federal W. Stephen Muldrow inform\u00f3 que un gran jurado federal acus\u00f3 a Jackeline Correa V\u00e1zquez, de 45 a\u00f1os, por alterar frascos de fentanilo confiados para cuidado de pacientes.<\/p>\n\n\n\n<p>\u201cLa acusada traicion\u00f3 la confianza de los pacientes y de sus patronos al alterar medicamentos cr\u00edticos\u201d, dijo Muldrow en declaraciones escritas.<\/p>\n\n\n\n<p>Seg\u00fan documentos judiciales, Correa V\u00e1zquez ten\u00eda licencia de la Junta Examinadora de Enfermer\u00eda de Puerto Rico, adscrita al Departamento de Salud, como enfermera de pr\u00e1ctica avanzada con concentraci\u00f3n cl\u00ednica en anestesia.<\/p>\n\n\n\n<p>La acusaci\u00f3n sostiene que, desde una fecha no precisada, pero no m\u00e1s tarde del 28 de marzo de 2023, Correa V\u00e1zquez utiliz\u00f3 su empleo y posici\u00f3n de confianza en el campo m\u00e9dico para obtener ilegalmente frascos de citrato de fentanilo.<\/p>\n\n\n\n<p>Autoridades federales alegan que la enfermera remov\u00eda el fentanilo de los frascos y lo sustitu\u00eda por sustancias l\u00edquidas transparentes para ocultar el hurto.<\/p>\n\n\n\n<p>\u201cLos cargos de hoy reflejan la seriedad de estos delitos y deben dejar claro que la Fiscal\u00eda Federal, junto a nuestros socios de ley y orden, trabajar\u00e1 incansablemente para investigar y procesar a cualquier persona que ponga en riesgo la seguridad de pacientes que buscan tratamiento m\u00e9dico\u201d, sostuvo Muldrow.<\/p>\n\n\n\n<p>La acusaci\u00f3n federal incluye ocho cargos. Cuatro son por alteraci\u00f3n de productos de consumo, con una pena m\u00e1xima de 10 a\u00f1os de prisi\u00f3n por cada cargo.<\/p>\n\n\n\n<p>Otros cuatro cargos son por adquirir u obtener una sustancia controlada mediante representaci\u00f3n falsa, fraude, falsificaci\u00f3n, enga\u00f1o o subterfugio, con una pena m\u00e1xima de cuatro a\u00f1os de prisi\u00f3n por cada cargo.<\/p><div class=\"notic-content-middle\" id=\"notic-2030502617\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n\n\n\n<p>Michael Mayer, agente especial a cargo de la Administraci\u00f3n para el Control de Drogas en el Caribe, dijo que la pesquisa busca proteger pacientes y la integridad de sustancias controladas.<\/p>\n\n\n\n<p>\u201cEsta investigaci\u00f3n demuestra nuestro compromiso de proteger a los pacientes, salvaguardar la integridad de las sustancias controladas y responsabilizar a cualquiera que abuse de una posici\u00f3n de confianza para beneficio personal\u201d, expres\u00f3 Mayer.<\/p>\n\n\n\n<p>Juan Berr\u00edos, agente especial interino a cargo de la Oficina de Investigaciones Criminales de la Administraci\u00f3n federal de Alimentos y Medicamentos en Miami, sostuvo que alterar medicamentos pone en riesgo la salud de pacientes.<\/p>\n\n\n\n<p>\u201cLa Administraci\u00f3n federal de Alimentos y Medicamentos continuar\u00e1 responsabilizando a quienes comprometan la seguridad de nuestro sistema de salud\u201d, a\u00f1adi\u00f3 Berr\u00edos.<\/p>\n\n\n\n<p>Correa V\u00e1zquez ten\u00eda se\u00f1alada su comparecencia inicial el martes ante el magistrado federal H\u00e9ctor Ramos Vega, del Tribunal de Distrito de Estados Unidos para el Distrito de Puerto Rico.<\/p>\n\n\n\n<p>La Administraci\u00f3n para el Control de Drogas, la Polic\u00eda de Puerto Rico, la Oficina de Investigaciones Criminales de la Administraci\u00f3n federal de Alimentos y Medicamentos y el Departamento de Salud investigan el caso.<\/p>\n\n\n\n<p>Las fiscales federales auxiliares Myriam Fern\u00e1ndez Gonz\u00e1lez y Mar\u00eda Monta\u00f1ez Concepci\u00f3n tienen a cargo el procesamiento.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El fiscal federal W. Stephen Muldrow inform\u00f3 que un gran jurado federal acus\u00f3 a Jackeline Correa V\u00e1zquez, de 45 a\u00f1os, por alterar frascos de fentanilo confiados para cuidado de pacientes. \u201cLa acusada traicion\u00f3 la confianza de los pacientes y de sus patronos al alterar medicamentos cr\u00edticos\u201d, dijo Muldrow en declaraciones escritas. Seg\u00fan documentos judiciales, Correa [&hellip;]<\/p>","protected":false},"author":101,"featured_media":1004612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[3,13],"tags":[5563,5997,3154],"class_list":["post-1004611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-tribunales","tag-cargos-federales","tag-enfermera","tag-fentanilo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1004611"}],"version-history":[{"count":2,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004611\/revisions"}],"predecessor-version":[{"id":1004615,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004611\/revisions\/1004615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1004612"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1004611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1004611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1004611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}