{"id":1004225,"date":"2026-06-01T08:17:00","date_gmt":"2026-06-01T12:17:00","guid":{"rendered":"https:\/\/noticel.com\/?p=1004225"},"modified":"2026-06-01T08:31:32","modified_gmt":"2026-06-01T12:31:32","slug":"mujer-muere-en-accidente-en-toa-alta","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20260601\/mujer-muere-en-accidente-en-toa-alta\/","title":{"rendered":"Mujer muere en accidente en Toa Alta"},"content":{"rendered":"<p>Una motorista muri\u00f3 en un accidente de tr\u00e1nsito a eso de las 10:37 de la noche del domingo, en la carretera PR-828, avenida Los Palacios, frente a la urbanizaci\u00f3n Palacio del Monte, en Toa Alta.<\/p>\n\n\n\n<p>Seg\u00fan el reporte de la Polic\u00eda, una llamada recibida a trav\u00e9s del Sistema de Emergencias 9-1-1 alert\u00f3 a las autoridades sobre un accidente con una motora. Seg\u00fan informes, la motora fue impactada por otro veh\u00edculo que se dio a la fuga.<\/p><div class=\"notic-content-middle\" id=\"notic-4131587933\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n\n\n\n<p>Al llegar a la escena, los agentes encontraron a una mujer que no presentaba signos vitales, relacionada con el accidente. La mujer fue identificada como Harley Marrero Mel\u00e9ndez, de 42 a\u00f1os. Seg\u00fan la Polic\u00eda, la mujer muri\u00f3 decapitada.<\/p>\n\n\n\n<p>Agentes adscritos a la Divisi\u00f3n de Patrullas y Carreteras investigan.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una motorista muri\u00f3 en un accidente de tr\u00e1nsito a eso de las 10:37 de la noche del domingo, en la carretera PR-828, avenida Los Palacios, frente a la urbanizaci\u00f3n Palacio del Monte, en Toa Alta. Seg\u00fan el reporte de la Polic\u00eda, una llamada recibida a trav\u00e9s del Sistema de Emergencias 9-1-1 alert\u00f3 a las autoridades [&hellip;]<\/p>","protected":false},"author":101,"featured_media":1004226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[1241,786,143],"class_list":["post-1004225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas","tag-accidente-de-transito","tag-muerte","tag-toa-alta"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1004225"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004225\/revisions"}],"predecessor-version":[{"id":1004227,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004225\/revisions\/1004227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1004226"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1004225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1004225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1004225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}