{"id":1004133,"date":"2026-05-31T11:44:44","date_gmt":"2026-05-31T15:44:44","guid":{"rendered":""},"modified":"2026-05-31T11:50:40","modified_gmt":"2026-05-31T15:50:40","slug":"cangrejeros-caguas-y-vaqueros-suman-victorias-en-el-bsn","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20260531\/cangrejeros-caguas-y-vaqueros-suman-victorias-en-el-bsn\/","title":{"rendered":"Cangrejeros, Caguas y Vaqueros suman victorias en el BSN"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>Los Cangrejeros de Santurce, los Criollos de Caguas y los Vaqueros de Bayam\u00f3n terminaron con victorias el s\u00e1bado en el Baloncesto Superior Nacional.<\/p>\n\n\n\n<p>En el Coliseo Juan Aubin Cruz Abreu, los Vaqueros derrotaron 98-95 a los Osos de Manat\u00ed.<\/p>\n\n\n\n<p>Los Osos dominaron buena parte del encuentro e incluso entraron al \u00faltimo parcial con ventaja de 77-67 tras un dominante tercer periodo.<\/p>\n\n\n\n<p>Sin embargo, Bayam\u00f3n respondi\u00f3 en los minutos finales y complet\u00f3 la remontada para llevarse la victoria en la carretera.<\/p>\n\n\n\n<p>Jae Crowder lider\u00f3 a los Vaqueros con 25 puntos y 5 rebotes. Khary Maur\u00e1s a\u00f1adi\u00f3 20 puntos, Gary Browne aport\u00f3 18 puntos y 9 asistencias, mientras Jordan Cintr\u00f3n termin\u00f3 con 16 puntos y 8 rebotes.<\/p>\n\n\n\n<p>Por los Osos, Kristian Doolittle registr\u00f3 25 puntos y 14 rebotes. Jameer Nelson Jr. a\u00f1adi\u00f3 21 puntos, mientras Cheick Diallo debut\u00f3 con 13 puntos y 20 rebotes.<\/p>\n\n\n\n<p>De otra parte, en el Coliseo Arquelio Torres Ram\u00edrez, los Cangrejeros derrotaron 95-92 a los Atl\u00e9ticos de San Germ\u00e1n.<\/p>\n\n\n\n<p>San Germ\u00e1n domin\u00f3 el inicio del encuentro y lleg\u00f3 a tener ventaja de hasta 14 puntos en el primer parcial, impulsado por un r\u00e1pido comienzo ofensivo de Andr\u00e9 Curbelo.<\/p>\n\n\n\n<p>Sin embargo, los Cangrejeros reaccionaron antes del descanso y lograron empatar el marcador a 38 al concluir la primera mitad.<\/p>\n\n\n\n<p>Santurce tom\u00f3 control del partido en el tercer parcial, que gan\u00f3 27-19, para entrar al \u00faltimo periodo con ventaja de 65-57.<\/p><div class=\"notic-content-middle\" id=\"notic-328560862\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/01063812\/CST_Suma-Pasa-La-Llave_970x90-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n\n\n\n<p>El cierre estuvo lleno de drama. El encuentro cont\u00f3 con las expulsiones del dirigente Eddie Casiano y su asistente Manolo Cintr\u00f3n. Los Atl\u00e9ticos respondieron y redujeron una desventaja de 12 puntos hasta colocarse a solo un punto en los segundos finales, pero Santurce ejecut\u00f3 mejor desde la l\u00ednea de tiros libres para asegurar la victoria.<\/p>\n\n\n\n<p>Davon Jefferson lider\u00f3 a los Cangrejeros con 21 puntos y 15 rebotes. Walter Hodge a\u00f1adi\u00f3 18 puntos, Jordan Howard aport\u00f3 17 e Isaiah Pi\u00f1eiro termin\u00f3 con 11 puntos y 10 rebotes.<\/p>\n\n\n\n<p>Por los Atl\u00e9ticos, Andr\u00e9 Curbelo anot\u00f3 25 puntos. Nick Perkins registr\u00f3 20 puntos y 10 rebotes, mientras Montrezl Harrell aport\u00f3 19 puntos y 18 rebotes.<\/p>\n\n\n\n<p>Finalmente, en el Coliseo Roger Mendoza, los Criollos de Caguas derrotaron 99-83 a los Santeros de Aguada.<\/p>\n\n\n\n<p>Los Santeros arrancaron con fuerza y llegaron a tener ventaja de hasta 13 puntos durante el primer parcial. Aguada cerr\u00f3 los primeros diez minutos arriba 31-21 y se fue al descanso con ventaja de 45-39.<\/p>\n\n\n\n<p>Sin embargo, los Criollos reaccionaron despu\u00e9s del descanso. Caguas empat\u00f3 el marcador durante el tercer parcial y domin\u00f3 el periodo 32-21 para tomar ventaja de 71-66 entrando a los \u00faltimos diez minutos de juego.<\/p>\n\n\n\n<p>Los locales continuaron ampliando la diferencia en el cuarto parcial y llegaron a dominar por 14 puntos en la recta final para asegurar su cuarta victoria consecutiva en la Roger Mendoza.<\/p>\n\n\n\n<p>Moses Brown lider\u00f3 la ofensiva criolla con 25 puntos y 16 rebotes. Christian \u201cCuco\u201d L\u00f3pez a\u00f1adi\u00f3 22 puntos, incluyendo cinco triples, mientras Travis Trice aport\u00f3 14 puntos y 8 asistencias.<\/p>\n\n\n\n<p>Por los Santeros, Jacob Wiley termin\u00f3 con 19 puntos y 9 rebotes. Matthew Lee a\u00f1adi\u00f3 19 puntos y John Jenkins aport\u00f3 17.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los Cangrejeros de Santurce, los Criollos de Caguas y los Vaqueros de Bayam\u00f3n terminaron con victorias el s\u00e1bado en el Baloncesto Superior Nacional. En el Coliseo Juan Aubin Cruz Abreu, los Vaqueros derrotaron 98-95 a los Osos de Manat\u00ed. Los Osos dominaron buena parte del encuentro e incluso entraron al \u00faltimo parcial con ventaja de [&hellip;]<\/p>","protected":false},"author":100,"featured_media":1004134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[33,31],"tags":[],"class_list":["post-1004133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1004133"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004133\/revisions"}],"predecessor-version":[{"id":1004135,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1004133\/revisions\/1004135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1004134"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1004133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1004133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1004133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}