{"id":1003922,"date":"2026-05-30T11:43:00","date_gmt":"2026-05-30T15:43:00","guid":{"rendered":"https:\/\/noticel.com\/?p=1003922"},"modified":"2026-05-30T11:53:26","modified_gmt":"2026-05-30T15:53:26","slug":"puerto-rico-conocera-hoy-a-sus-nuevos-campeones-nacionales-de-tenis","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20260530\/puerto-rico-conocera-hoy-a-sus-nuevos-campeones-nacionales-de-tenis\/","title":{"rendered":"Puerto Rico conocer\u00e1 hoy a sus nuevos campeones nacionales de tenis"},"content":{"rendered":"<p>Tras una intensa semana de competencia que reuni\u00f3 a destacados tenistas de toda la Isla, hoy culmina El Nacional \u2013 Campeonato de Tenis de Puerto Rico, el principal torneo nacional organizado por la Asociaci\u00f3n de Tenis de Puerto Rico (PRTA) en las instalaciones del Torrimar Tennis Club.<\/p>\n\n\n\n<p>La jornada decisiva comenzar\u00e1 a las 10:00 de la ma\u00f1ana con la final femenina de sencillos entre la primera sembrada, Lauren Kettlewell, y Aurora Lugo, cuarta preclasificada del torneo.<\/p>\n\n\n\n<p>La final femenina marcar\u00e1 el regreso de Lauren Kettlewell al partido por el campeonato tras haber sido finalista en 2025. Esta vez buscar\u00e1 dar el paso final y quedarse con la corona nacional frente a Aurora Lugo, quien ha tenido una destacada actuaci\u00f3n durante toda la semana.<\/p>\n\n\n\n<p>Posteriormente se disputar\u00e1 una de las finales m\u00e1s esperadas del evento cuando el primer sembrado, Nicholas Snyder, enfrente al segundo sembrado y campe\u00f3n defensor, Luca Hotze Mart\u00ednez, quien intentar\u00e1 revalidar el t\u00edtulo conquistado el a\u00f1o pasado en la final masculina de sencillos.<\/p>\n\n\n\n<p>La acci\u00f3n continuar\u00e1 con la final femenina de dobles, donde las parejas de Dakota Fordham y Natalia Ponsa y Aurora Lugo y Siena Schintler buscar\u00e1n quedarse con la corona del torneo.<\/p>\n\n\n\n<p>El cierre del campeonato estar\u00e1 a cargo de la final masculina de dobles, con el duelo entre los primeros sembrados Nicholas Snyder y Luca Hotze Mart\u00ednez frente a Stephan Gonz\u00e1lez y Juan Marrero, segundos sembrados del evento.<\/p>\n\n\n\n<p>\u201cDurante toda la semana hemos visto un tenis de gran nivel y una extraordinaria muestra del talento que existe en Puerto Rico. El Nacional contin\u00faa siendo una plataforma fundamental para el desarrollo de nuestros jugadores y una celebraci\u00f3n de nuestra comunidad ten\u00edstica. Invitamos al p\u00fablico a acompa\u00f1arnos en esta jornada final y apoyar a nuestros atletas\u201d, expres\u00f3 Dr. William Micheo, presidente de la Asociaci\u00f3n de Tenis de Puerto Rico.<\/p><div class=\"notic-content-middle\" id=\"notic-222294950\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n\n\n\n<p>Las finales est\u00e1n abiertas al p\u00fablico y se espera la asistencia de familiares, entrenadores, aficionados y miembros de la comunidad deportiva para presenciar la coronaci\u00f3n de los campeones de la edici\u00f3n 2026 de El Nacional.<\/p>\n\n\n\n<p><strong>Programa de Finales \u2013 Hoy<\/strong><\/p>\n\n\n\n<p>10:00 a.m. \u2013 Final Femenina de Sencillos<br>Lauren Kettlewell (1) vs. Aurora Lugo (4)<\/p>\n\n\n\n<p>A continuaci\u00f3n \u2013 Final Masculina de Sencillos<br>Nicholas Snyder (1) vs. Luca Hotze (2)<\/p>\n\n\n\n<p>A continuaci\u00f3n \u2013 Final Femenina de Dobles<br>Dakota Fordham \/ Natalia Ponsa vs. Aurora Lugo \/ Siena Schintler (2)<\/p>\n\n\n\n<p>A continuaci\u00f3n \u2013 Final Masculina de Dobles<br>Nicholas Snyder \/ Luca Hotze (1) vs. Stephan Gonz\u00e1lez \/ Juan Marrero (2)<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30114701\/Lauren-Kettlewell-EL-NACIONAL-2026-05-29-at-18.52.16-2-1024x819.jpeg\" alt=\"\" class=\"wp-image-1003925\" srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30114701\/Lauren-Kettlewell-EL-NACIONAL-2026-05-29-at-18.52.16-2-1024x819.jpeg 1024w, https:\/\/cdn.noticel.com\/2026\/05\/30114701\/Lauren-Kettlewell-EL-NACIONAL-2026-05-29-at-18.52.16-2-300x240.jpeg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30114701\/Lauren-Kettlewell-EL-NACIONAL-2026-05-29-at-18.52.16-2-768x614.jpeg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30114701\/Lauren-Kettlewell-EL-NACIONAL-2026-05-29-at-18.52.16-2-1536x1229.jpeg 1536w, https:\/\/cdn.noticel.com\/2026\/05\/30114701\/Lauren-Kettlewell-EL-NACIONAL-2026-05-29-at-18.52.16-2-15x12.jpeg 15w, https:\/\/cdn.noticel.com\/2026\/05\/30114701\/Lauren-Kettlewell-EL-NACIONAL-2026-05-29-at-18.52.16-2.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Lauren Kettlewell. (Foto suministrada)<\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Tras una intensa semana de competencia que reuni\u00f3 a destacados tenistas de toda la Isla, hoy culmina El Nacional \u2013 Campeonato de Tenis de Puerto Rico, el principal torneo nacional organizado por la Asociaci\u00f3n de Tenis de Puerto Rico (PRTA) en las instalaciones del Torrimar Tennis Club. La jornada decisiva comenzar\u00e1 a las 10:00 de [&hellip;]<\/p>","protected":false},"author":100,"featured_media":1003924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31,37],"tags":[2499,5966,3743],"class_list":["post-1003922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-tenis","tag-campeonato-nacional","tag-el-nacional","tag-tenis-de-campo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1003922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=1003922"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1003922\/revisions"}],"predecessor-version":[{"id":1003926,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/1003922\/revisions\/1003926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/1003924"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=1003922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=1003922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=1003922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}